{"text_format":"1","workbook":"xlsx","n_sheets":14,"sheets":["Lookup","Lookup Alaska","TribePartI (2)","Instructions ","Profile","Form","PriorityListForm","TribePartI","Tribe Part II ","150 Per Cent","FPIG13","FPIG 125%","Sheet1","HIP Home "],"not_rendered":{"charts":0,"images":1,"macros":1,"external_links":7,"defined_names":85,"comments":2,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"Lookup","index":0,"n_rows":27,"n_cols":38,"rows_kept":27,"cut":false,"hidden":true,"merged":[[11,20,11,21],[17,13,17,14],[17,1,17,2],[17,4,17,5],[17,7,17,8],[17,10,17,11],[12,20,12,21],[13,20,13,21],[14,20,14,21],[15,20,15,21],[7,20,7,21],[8,20,8,21],[9,20,9,21],[10,20,10,21],[0,0,0,21],[3,20,3,21],[4,20,4,21],[5,20,5,21],[6,20,6,21],[1,0,1,21]]}
["FACTOR NO. 1 - HIP ELIGIBILITY/SELECTION CRITERIA @ 150%"]
["INCOME GUIDELINE POINT SCHEDULE FOR ALL STATES EXCEPT ALASKA"]
[null,null,25,null,null,20,null,null,15,null,null,10,null,null,5,null,null,0,null,null,"Ineligible",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Income","Family Size","Answer"]
[1,0,"TO",{"$f":"D17","v":3645},{"$f":"D4+1","v":3646},"TO",{"$f":"G17","v":7290},{"$f":"G4+1","v":7291},"TO",{"$f":"J17","v":10935},{"$f":"J4+1","v":10936},"TO",{"$f":"M17","v":14580},{"$f":"M4+1","v":14581},"TO",{"$f":"P17","v":18225},{"$f":"P4+1","v":18226},"TO",{"$f":"S17","v":21870},{"$f":"S4+1","v":21871},"& HIGHER",null,null,1,{"$f":"B4","v":0},{"$f":"E4","v":3646},{"$f":"H4","v":7291},{"$f":"K4","v":10936},{"$f":"N4","v":14581},{"$f":"Q4","v":18226},{"$f":"T4","v":21871},{"$f":"HLOOKUP($AJ5,Y4:AE5,2)","v":25},"hlookup if in this row"]
[2,0,"TO",{"$f":"(D4+D$16)","v":4930},4931,"TO",{"$f":"G4+G$16","v":9860},9861,"TO",{"$f":"J4+J$16","v":14790},14791,"TO",{"$f":"M4+M$16","v":19720},19721,"TO",{"$f":"P4+P$16","v":24650},24651,"TO",{"$f":"S4+S$16","v":29580},29581,"& HIGHER",null,1,null,25,20,15,10,5,0,"Not Eligible","Not Eligible",null,null,null,{"$f":"Form!G12","v":0},{"$f":"Form!E12","v":0},{"$f":"VLOOKUP(AK5,Income_2,9)","v":{"$error":"#N/A"}}]
[3,0,"TO",{"$f":"D5+D$16","v":6215},6216,"TO",12430,12431,"TO",18645,18646,"TO",24860,24861,"TO",31075,31076,"TO",37290,37291,"& HIGHER",null,null,2,{"$f":"B5","v":0},{"$f":"E5","v":4931},{"$f":"H5","v":9861},{"$f":"K5","v":14791},{"$f":"N5","v":19721},{"$f":"Q5","v":24651},{"$f":"T5","v":29581},{"$f":"HLOOKUP($AJ5,Y6:AE7,2)","v":25},"hlookup if in this row"]
[4,0,"TO",7500,7501,"TO",15000,15001,"TO",22500,22501,"TO",30000,30001,"TO",37500,37501,"TO",45000,45001,"& HIGHER",null,null,null,25,20,15,10,5,0,"Not Eligible"]
[5,0,"TO",8785,8786,"TO",17570,17571,"TO",26355,26356,"TO",35140,35141,"TO",43925,43926,"TO",52710,52711,"& HIGHER",null,null,3,{"$f":"B6","v":0},{"$f":"E6","v":6216},{"$f":"H6","v":12431},{"$f":"K6","v":18646},{"$f":"N6","v":24861},{"$f":"Q6","v":31076},{"$f":"T6","v":37291},{"$f":"HLOOKUP($AJ5,Y8:AE9,2)","v":25},"hlookup if in this row"]
[6,0,"TO",10070,10071,"TO",20140,20141,"TO",30210,30211,"TO",40280,40281,"TO",50350,50351,"TO",60420,60421,"& HIGHER",null,null,null,25,20,15,10,5,0,"Not Eligible"]
[7,0,"TO",11355,11356,"TO",22710,22711,"TO",34065,34066,"TO",45420,45421,"TO",56775,56776,"TO",68130,68131,"& HIGHER",null,null,4,{"$f":"B7","v":0},{"$f":"E7","v":7501},{"$f":"H7","v":15001},{"$f":"K7","v":22501},{"$f":"N7","v":30001},{"$f":"Q7","v":37501},{"$f":"T7","v":45001},{"$f":"HLOOKUP($AJ5,Y10:AE11,2)","v":25},"hlookup if in this row"]
[8,0,"TO",12640,12641,"TO",25280,25281,"TO",37920,37921,"TO",50560,50561,"TO",63200,63201,"TO",75840,75841,"& HIGHER",null,null,null,25,20,15,10,5,0,"Not Eligible"]
[9,0,"TO",13925,13926,"TO",27850,27851,"TO",41775,41776,"TO",55700,55701,"TO",69625,69626,"TO",83550,83551,"& HIGHER",null,null,5,{"$f":"B8","v":0},{"$f":"E8","v":8786},{"$f":"H8","v":17571},{"$f":"K8","v":26356},{"$f":"N8","v":35141},{"$f":"Q8","v":43926},{"$f":"T8","v":52711},{"$f":"HLOOKUP($AJ5,Y12:AE13,2)","v":25},"hlookup if in this row"]
[10,0,"TO",15210,15211,"TO",30420,30421,"TO",45630,45631,"TO",60840,60841,"TO",76050,76051,"TO",91260,91261,"& HIGHER",null,null,null,25,20,15,10,5,0,"Not Eligible"]
[11,0,"TO",16495,16496,"TO",32990,32991,"TO",49485,49486,"TO",65980,65981,"TO",82475,82476,"TO",98970,98971,"& HIGHER",null,null,6,{"$f":"B9","v":0},{"$f":"E9","v":10071},{"$f":"H9","v":20141},{"$f":"K9","v":30211},{"$f":"N9","v":40281},{"$f":"Q9","v":50351},{"$f":"T9","v":60421},{"$f":"HLOOKUP($AJ5,Y14:AE15,2)","v":25},"hlookup if in this row"]
[12,0,"TO",17780,17781,"TO",35560,35561,"TO",53340,53341,"TO",71120,71121,"TO",88900,88901,"TO",106680,106681,"& HIGHER",null,null,null,25,20,15,10,5,0,"Not Eligible"]
["EACH PERSON OVER 12 ADD",null,null,{"$f":"D18","v":1285},null,null,{"$f":"G18","v":2570},null,null,{"$f":"J18","v":3855},null,null,{"$f":"M18","v":5140},null,null,{"$f":"P18","v":6425},null,null,{"$f":"S18","v":7710},7711,"& HIGHER",null,null,7,{"$f":"B10","v":0},{"$f":"E10","v":11356},{"$f":"H10","v":22711},{"$f":"K10","v":34066},{"$f":"N10","v":45421},{"$f":"Q10","v":56776},{"$f":"T10","v":68131},{"$f":"HLOOKUP($AJ5,Y16:AE17,2)","v":25},"hlookup if in this row"]
[null,"@ 25% =",null,{"$f":"$M$17*0.25","v":3645},"@ 50% =",null,{"$f":"$M$17*0.5","v":7290},"@ 75% =",null,{"$f":"$M$17*0.75","v":10935},"@ 100% =",null,14580,"@ 125% =",null,{"$f":"$M$17*1.25","v":18225},"@150%","=",{"$f":"M17*1.5","v":21870},null,null,null,null,null,25,20,15,10,5,0,"Not Eligible"]
[null,"@ Add'l:",null,{"$f":"M18*0.25","v":1285},"@ Add'l:",null,{"$f":"M18*0.5","v":2570},"@ Add'l:",null,{"$f":"M18*0.75","v":3855},"@ Add'l:",null,5140,"@ Add'l:",null,{"$f":"M18*1.25","v":6425},null,null,{"$f":"M18*1.5","v":7710},null,null,null,null,8,{"$f":"-B11","v":0},{"$f":"E11","v":12641},{"$f":"H11","v":25281},{"$f":"K11","v":37921},{"$f":"N11","v":50561},{"$f":"Q11","v":63201},{"$f":"T11","v":75841},{"$f":"HLOOKUP($AJ5,Y18:AE19,2)","v":25},"hlookup if in this row"]
["FPIG =","Federal Poverty Income Guidelines (Health & Human Services Poverty Guidelines)",null,null,null,null,null,null,null,null,null,null,"PG =","Poverty Guidelines",null,null,null,null,null,null,null,null,null,null,25,20,15,10,5,0,"Not Eligible"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,9,{"$f":"B12","v":0},{"$f":"E12","v":13926},{"$f":"H12","v":27851},{"$f":"K12","v":41776},{"$f":"N12","v":55701},{"$f":"Q12","v":69626},{"$f":"T12","v":83551},{"$f":"HLOOKUP($AJ5,Y20:AE21,2)","v":25},"hlookup if in this row"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,25,20,15,10,5,0,"Not Eligible"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,10,{"$f":"B13","v":0},{"$f":"E13","v":15211},{"$f":"H13","v":30421},{"$f":"K13","v":45631},{"$f":"N13","v":60841},{"$f":"Q13","v":76051},{"$f":"T13","v":91261},{"$f":"HLOOKUP($AJ5,Y22:AE23,2)","v":25},"hlookup if in this row"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,25,20,15,10,5,0,"Not Eligible"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,11,{"$f":"B14","v":0},{"$f":"E14","v":16496},{"$f":"H14","v":32991},{"$f":"K14","v":49486},{"$f":"N14","v":65981},{"$f":"Q14","v":82476},{"$f":"T14","v":98971},{"$f":"HLOOKUP($AJ5,Y24:AE25,2)","v":25},"hlookup if in this row"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,25,20,15,10,5,0,"Not Eligible"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,12,{"$f":"B15","v":0},{"$f":"E15","v":17781},{"$f":"H15","v":35561},{"$f":"K15","v":53341},{"$f":"N15","v":71121},{"$f":"Q15","v":88901},{"$f":"T15","v":106681},{"$f":"HLOOKUP($AJ5,Y26:AE27,2)","v":25},"hlookup if in this row"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,25,20,15,10,5,0,"Not Eligible"]

{"sheet":"Lookup Alaska","index":1,"n_rows":27,"n_cols":38,"rows_kept":27,"cut":false,"hidden":true,"merged":[[14,20,14,21],[15,20,15,21],[17,1,17,2],[17,4,17,5],[17,7,17,8],[17,10,17,11],[17,13,17,14],[13,20,13,21],[0,0,0,21],[3,20,3,21],[4,20,4,21],[5,20,5,21],[6,20,6,21],[7,20,7,21],[1,0,1,21],[8,20,8,21],[9,20,9,21],[10,20,10,21],[11,20,11,21],[12,20,12,21]]}
["FACTOR NO. 1 - HIP ELIGIBILITY/SELECTION CRITERIA @ 150%"]
["INCOME GUIDELINE POINT SCHEDULE FOR ALASKA"]
[null,null,25,null,null,20,null,null,15,null,null,10,null,null,5,null,null,0,null,null,"Ineligible",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Income","Family Size","Answer"]
[1,0,"TO",{"$f":"D17","v":4552.5},{"$f":"D4+1","v":4553.5},"TO",{"$f":"G17","v":9105},{"$f":"G4+1","v":9106},"TO",{"$f":"J17","v":13657.5},{"$f":"J4+1","v":13658.5},"TO",{"$f":"M17","v":18210},{"$f":"M4+1","v":18211},"TO",{"$f":"P17","v":22762.5},{"$f":"P4+1","v":22763.5},"TO",{"$f":"S17","v":27315},{"$f":"S4+1","v":27316},"& HIGHER",null,null,1,{"$f":"B4","v":0},{"$f":"E4","v":4553.5},{"$f":"H4","v":9106},{"$f":"K4","v":13658.5},{"$f":"N4","v":18211},{"$f":"Q4","v":22763.5},{"$f":"T4","v":27316},{"$f":"HLOOKUP($AJ5,Y4:AE5,2)","v":25},"hlookup if in this row"]
[2,0,"TO",5387.5,5388.5,"TO",{"$f":"G4+G$16","v":12320},12321,"TO",{"$f":"J4+J$16","v":18480},18481,"TO",{"$f":"M4+M$16","v":24640},24641,"TO",{"$f":"P4+P$16","v":30800},30801,"TO",{"$f":"S4+S$16","v":36960},36961,"& HIGHER",null,1,null,25,20,15,10,5,0,"Not Eligible",null,null,null,null,{"$f":"Form!G12","v":0},{"$f":"Form!E12","v":0},{"$f":"VLOOKUP(AK5,Income_1,9)","v":{"$error":"#N/A"}}]
[3,0,"TO",6787.5,6788.5,"TO",15535,15536,"TO",23302.5,23303.5,"TO",31070,31071,"TO",38837.5,38838.5,"TO",46605,46606,"& HIGHER",null,null,2,{"$f":"B5","v":0},{"$f":"E5","v":5388.5},{"$f":"H5","v":12321},{"$f":"K5","v":18481},{"$f":"N5","v":24641},{"$f":"Q5","v":30801},{"$f":"T5","v":36961},{"$f":"HLOOKUP($AJ5,Y6:AE7,2)","v":25},"hlookup if in this row"]
[4,0,"TO",{"$f":"D6+D$16","v":8395},8396,"TO",18750,18751,"TO",28125,28126,"TO",37500,37501,"TO",46875,46876,"TO",56250,56251,"& HIGHER",null,null,null,25,20,15,10,5,0,"Not Eligible"]
[5,0,"TO",10002.5,10003.5,"TO",21965,21966,"TO",32947.5,32948.5,"TO",43930,43931,"TO",54912.5,54913.5,"TO",65895,65896,"& HIGHER",null,null,3,{"$f":"B6","v":0},{"$f":"E6","v":6788.5},{"$f":"H6","v":15536},{"$f":"K6","v":23303.5},{"$f":"N6","v":31071},{"$f":"Q6","v":38838.5},{"$f":"T6","v":46606},{"$f":"HLOOKUP($AJ5,Y8:AE9,2)","v":25},"hlookup if in this row"]
[6,0,"TO",11610,11611,"TO",25180,25181,"TO",37770,37771,"TO",50360,50361,"TO",62950,62951,"TO",75540,75541,"& HIGHER",null,null,null,25,20,15,10,5,0,"Not Eligible"]
[7,0,"TO",13217.5,13218.5,"TO",28395,28396,"TO",42592.5,42593.5,"TO",56790,56791,"TO",70987.5,70988.5,"TO",85185,85186,"& HIGHER",null,null,4,{"$f":"B7","v":0},{"$f":"E7","v":8396},{"$f":"H7","v":18751},{"$f":"K7","v":28126},{"$f":"N7","v":37501},{"$f":"Q7","v":46876},{"$f":"T7","v":56251},{"$f":"HLOOKUP($AJ5,Y10:AE11,2)","v":25},"hlookup if in this row"]
[8,0,"TO",14825,14826,"TO",31610,31611,"TO",47415,47416,"TO",63220,63221,"TO",79025,79026,"TO",94830,94831,"& HIGHER",null,null,null,25,20,15,10,5,0,"Not Eligible"]
[9,0,"TO",16432.5,16433.5,"TO",34825,34826,"TO",52237.5,52238.5,"TO",69650,69651,"TO",87062.5,87063.5,"TO",104475,104476,"& HIGHER",null,null,5,{"$f":"B8","v":0},{"$f":"E8","v":10003.5},{"$f":"H8","v":21966},{"$f":"K8","v":32948.5},{"$f":"N8","v":43931},{"$f":"Q8","v":54913.5},{"$f":"T8","v":65896},{"$f":"HLOOKUP($AJ5,Y12:AE13,2)","v":25},"hlookup if in this row"]
[10,0,"TO",18040,18041,"TO",38040,38041,"TO",57060,57061,"TO",76080,76081,"TO",95100,95101,"TO",114120,114121,"& HIGHER",null,null,null,25,20,15,10,5,0,"Not Eligible"]
[11,0,"TO",19647.5,19648.5,"TO",41255,41256,"TO",61882.5,61883.5,"TO",82510,82511,"TO",103137.5,103138.5,"TO",123765,123766,"& HIGHER",null,null,6,{"$f":"B9","v":0},{"$f":"E9","v":11611},{"$f":"H9","v":25181},{"$f":"K9","v":37771},{"$f":"N9","v":50361},{"$f":"Q9","v":62951},{"$f":"T9","v":75541},{"$f":"HLOOKUP($AJ5,Y14:AE15,2)","v":25},"hlookup if in this row"]
[12,0,"TO",21255,21256,"TO",44470,44471,"TO",66705,66706,"TO",88940,88941,"TO",111175,111176,"TO",133410,133411,"& HIGHER",null,null,null,25,20,15,10,5,0,"Not Eligible"]
["EACH PERSON OVER 12 ADD",null,null,{"$f":"D18","v":1607.5},null,null,{"$f":"G18","v":3215},null,null,{"$f":"J18","v":4822.5},null,null,{"$f":"M18","v":6430},null,null,{"$f":"P18","v":8037.5},null,null,{"$f":"S18","v":9645},9646,"& HIGHER",null,null,7,{"$f":"B10","v":0},{"$f":"E10","v":13218.5},{"$f":"H10","v":28396},{"$f":"K10","v":42593.5},{"$f":"N10","v":56791},{"$f":"Q10","v":70988.5},{"$f":"T10","v":85186},{"$f":"HLOOKUP($AJ5,Y16:AE17,2)","v":25},"hlookup if in this row"]
[null,"@ 25% =",null,{"$f":"$M$17*0.25","v":4552.5},"@ 50% =",null,{"$f":"$M$17*0.5","v":9105},"@ 75% =",null,{"$f":"$M$17*0.75","v":13657.5},"@ 100% =",null,18210,"@ 125% =",null,{"$f":"$M$17*1.25","v":22762.5},"@150%","=",{"$f":"M17*1.5","v":27315},null,null,null,null,null,25,20,15,10,5,0,"Not Eligible"]
[null,"@ Add'l:",null,{"$f":"M18*0.25","v":1607.5},"@ Add'l:",null,{"$f":"M18*0.5","v":3215},"@ Add'l:",null,{"$f":"M18*0.75","v":4822.5},"@ Add'l:",null,6430,"@ Add'l:",null,{"$f":"M18*1.25","v":8037.5},null,null,{"$f":"M18*1.5","v":9645},null,null,null,null,8,{"$f":"B11","v":0},{"$f":"E11","v":14826},{"$f":"H11","v":31611},{"$f":"K11","v":47416},{"$f":"N11","v":63221},{"$f":"Q11","v":79026},{"$f":"T11","v":94831},{"$f":"HLOOKUP($AJ5,Y18:AE19,2)","v":25},"hlookup if in this row"]
["FPIG =","Federal Poverty Income Guidelines (Health & Human Services Poverty Guidelines)",null,null,null,null,null,null,null,null,null,null,"PG =","Poverty Guidelines",null,null,null,null,null,null,null,null,null,null,25,20,15,10,5,0,"Not Eligible"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,9,{"$f":"B12","v":0},{"$f":"E12","v":16433.5},{"$f":"H12","v":34826},{"$f":"K12","v":52238.5},{"$f":"N12","v":69651},{"$f":"Q12","v":87063.5},{"$f":"T12","v":104476},{"$f":"HLOOKUP($AJ5,Y20:AE21,2)","v":25},"hlookup if in this row"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,25,20,15,10,5,0,"Not Eligible"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,10,{"$f":"B13","v":0},{"$f":"E13","v":18041},{"$f":"H13","v":38041},{"$f":"K13","v":57061},{"$f":"N13","v":76081},{"$f":"Q13","v":95101},{"$f":"T13","v":114121},{"$f":"HLOOKUP($AJ5,Y22:AE23,2)","v":25},"hlookup if in this row"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,25,20,15,10,5,0,"Not Eligible"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,11,{"$f":"B14","v":0},{"$f":"E14","v":19648.5},{"$f":"H14","v":41256},{"$f":"K14","v":61883.5},{"$f":"N14","v":82511},{"$f":"Q14","v":103138.5},{"$f":"T14","v":123766},{"$f":"HLOOKUP($AJ5,Y24:AE25,2)","v":25},"hlookup if in this row"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,25,20,15,10,5,0,"Not Eligible"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,12,{"$f":"B15","v":0},{"$f":"E15","v":21256},{"$f":"H15","v":44471},{"$f":"K15","v":66706},{"$f":"N15","v":88941},{"$f":"Q15","v":111176},{"$f":"T15","v":133411},{"$f":"HLOOKUP($AJ5,Y26:AE27,2)","v":25},"hlookup if in this row"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,25,20,15,10,5,0,"Not Eligible"]

{"sheet":"TribePartI (2)","index":2,"n_rows":2158,"n_cols":14,"rows_kept":2158,"cut":false,"hidden":true,"merged":[[6,12,8,12],[6,13,8,13],[5,1,5,10],[6,0,7,3],[6,4,8,4],[6,5,7,9],[6,10,8,10],[6,11,8,11],[3,1,3,3],[3,4,3,9],[3,11,3,13],[4,1,4,3],[4,4,4,9],[4,11,4,13],[0,0,0,10],[1,1,1,3],[1,4,1,9],[1,11,1,13],[2,1,2,3],[2,4,2,9],[2,11,2,13]]}
["                   PART I - TRIBAL WORK PLAN ",null,null,null,null,null,null,null,null,null,null,"Date:",null,{"$f":"IF(Profile!D17=0,\"\",Profile!D17)","v":""}]
[1,"Work Plan for Fiscal Year: ",null,null,{"$f":"IF(Profile!D9=0,\"\",Profile!D9)","v":2024},null,null,null,null,null,"Name:",{"$f":"IF(Profile!D10=0,\"\",Profile!D10)","v":""}]
[2,"Name of Tribe / Consortium:",null,null,{"$f":"IF(Profile!D6=0,\"\",Profile!D6)","v":"Quechen"},null,null,null,null,null,"Title:",{"$f":"IF(Profile!D11=0,\"\",Profile!D11)","v":""}]
[3,"Number of Eligible Applicants:",null,null,{"$f":"IF(M2052=0,\"\",M2052)","v":10},null,null,null,null,null,"Phone:",{"$f":"IF(Profile!D12=0,\"\",Profile!D12)","v":""}]
[4,"Number of Applications Received:",null,null,{"$f":"IF(B2052=0,\"\",B2052)","v":"Pretty Weasel"},null,null,null,null,null,"Fax:",{"$f":"IF(Profile!D13=0,\"\",Profile!D13)","v":""}]
[null,"See instructions for printing form            "]
["5. Name of Eligible Applicant              (ranked in order of need)",null,null,null,"6. Applicant's Servicing Tribe    ","7. Program Category            (Enter One As Applicable)",null,null,null,null,"8a. Estimated Start Date","8b. Estimated Project Costs                                         \n 25 CFR 256.17(b))**        ","Eligibility Status","8c. Priority Ranking Points                        (ranked in order from           highest to lowest)"]
[]
[null,"Last ","First","Suffix",null,"(A)","(B)","(C-1)","(C-2)","(D)"]
[1,"Charbonneau","Richard","J","Turtle Montain Band of Chippewa",null,null,null,"C-2",null,42186,120000,57,81]
[{"$f":"A10+1","v":2},"Grant","Francis","P","Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,54,70]
[{"$f":"A11+1","v":3},"Grandboise","Donald",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,50,60]
[4,"Janis","Leo",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,0]
[5,"Black Smith","Pete",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,0]
[6,"Brewer","Jennifer",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,2]
[7,"Grass","Kirsten",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,2]
[8,"Tobacco","Hattie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,3]
[9,"Fox","Holly",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,3]
[10,"Gegleman","Anita",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,3]
[11,"Crows Heart","Richard",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,3]
[12,"Morrison","Beverly",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,3]
[13,"McCoy","Hanni",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,4]
[14,"Felix-Wells","Corrine",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,5]
[15,"Black Hawk","Dinah",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,5]
[16,"Looks Twice","Georgine",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,6]
[17,"Walks Out","Darlene",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,7]
[18,"Brave Eagle","Theresa",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,8]
[19,"Murphy","Claire",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[20,"Trottier","Tresa",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[21,"James","Christina",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[22,"Decoteau","Tammy",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[23,"Desjarlais","Lisa","M","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[24,"Scott","Alice",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[25,"Payer","Vicky",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[26,"Nadeau","Felicia",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[27,"Bercier","Jerilyn",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[28,"Brien","Patricia",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[29,"Lavallie","Jamie",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[30,"Decoteau","Monica",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[31,"Handy","Debra",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[32,"Schroeder","Brooke",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[33,"Davis","Francine",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[34,"Azure","Holly",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[35,"Gourneau","Dianna",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[36,"Grant","Austin",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[37,"Fox","Marla",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[38,"Martin","Anita",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[39,"Hanson","Cherie",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[40,"Keplin","Mark","Jr","Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[41,"Gunville","Janelle",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[42,"Poitra","Kim",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[43,"Morin","Alisha",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[44,"Desjarlais","Ardis",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[45,"Peltier","Matthew",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[46,"Gourneau","Rodney",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[47,"Peltier","Roderick",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[48,"Lafountain","Shana",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[49,"Keplin","Terry",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[50,"Thomas","James",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[51,"Malaterre","Dianne",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[52,"Belgarde","Larry",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[53,"Johnson","Sarah",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[54,"Decoteau","Bryce",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[55,"Morin","Kristen",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[56,"Azure","Matthew",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[57,"Davis","Jamie",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[58,"Jeanotte","Faith",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[59,"Walter","Jetney",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[60,"Peltier","Harvey","Jr","Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[61,"Poitra","Sheila",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[62,"Munoz","Geraldine",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[63,"Owens","Misty",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[64,"Marcellais","Cameron",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[65,"Parisien","Nadine",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[66,"Lafountain","April",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[{"$f":"A75+1","v":67},"Houle","Stephanie",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[68,"Delorme","Darrell",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[69,"Lafromboise","Clifford","Jr","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[70,"Peltier","Rita",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[71,"Oslin","Cheryl",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[72,"Longie","Robert",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[73,"Wallette","Felix",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[74,"Gourneau","Antoine",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[75,"Morin","Roland",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[76,"Desjarlais","Lisa",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[77,"Hyde","Margaret",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[78,"Charette","Maryann",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[79,"Zaste","Shelly",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[80,"Allery","Dorine",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[81,"Frederick","David",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[82,"Larocque","Roxanne",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[83,"Jeanotte","Barbara",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[84,"Hawley","Rosa",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[85,"St. Claire","Nina",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[86,"Amyotte","Norbert",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[87,"Allery","Lou ann",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[88,"Akewanzie","Marvin",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[89,"Smith","Bonita",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[90,"Trottier","Antoinette",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[91,"Counts","Roger",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[92,"Crissler","Angela",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[93,"Morin","Paul ",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[94,"Houle","Barbara",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[95,"Bruce","Gene",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[96,"Wallette","Doris",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[97,"Delong","Frederick",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[98,"Houle","Wanda",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[99,"Larocque","Garry",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[100,"Decoteau","Roberta",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[101,"Lavallie","Peter",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[102,"Davis","Marla",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[103,"Lavallie","Cindy",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[104,"Larocque","Elaine",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[105,"Decoteau","Lisa","G","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[106,"Gourneau","Debra",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[107,"Higgins","Theresa",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[108,"Lenoir","Patty",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[109,"St. Claire","Winnona",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[110,"Lavallie","Louis",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[111,"Falcon","George","Sr","Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[112,"Chase","Todd",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[113,"Lafountain","Larry","J","Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[114,"Decoteau","Vernon",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[115,"Lunday","Brent",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[116,"Nadeau","Gale",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[117,"Houle","Donna",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[118,"Monette","Loretta",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[119,"Morin","Vicky",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[120,"Lavallie","Edward",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[121,"Greatwalker","Shelly",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[122,"Burschinger","James",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[123,"Maxon","Tracy",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[124,"Delorme","Chelsi",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[125,"Champagne","Sandra",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[126,"Decoteau","Jana",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[127,"Benson","Anita",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[128,"Counts","Carletta",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[129,"Davis","Uriah",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[130,"Morin","Rhonda",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[{"$f":"A139+1","v":131},"Keplin","April",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[132,"St. Claire","Shay",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[133,"Frederick","Hope",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[134,"Wallette","Samantha",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[135,"Lavallie","Linus",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[136,"Gourneau","Margo",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[137,"Poitra","Kyla",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[138,"Lavallie","Shelly",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[139,"Poitra","Brett",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[140,"Azure","Myron",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[141,"Decoteau","Brandy",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[142,"Baker","Larry","Jr","Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[143,"Azure","Jenita",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[144,"Vondal","Kevin",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[145,"Laverdure","Napoleon",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[146,"Blue","Yvonne",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[147,"Morin","Ramona",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[148,"Delonais","Jessica",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[149,"Gourneau","Terri",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[150,"Poitra","Melinda",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[151,"Lafountain","Leslie",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[152,"Parisien","Lorraine",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[153,"Reopolle","Farrah",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[154,"Delong","Art",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[155,"Keplin","Raylene",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[156,"Gunville","Jerry",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[157,"Chase","Marilyn",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[158,"Smith","John","J ","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[159,"Vivier","Randy",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[160,"Demery","Francis",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[161,"Lafountain","Jerilyn",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[162,"Bliss","Andrea",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[163,"Chavez","Toni",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[164,"Robertson","Dimothy",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[165,"Wessels","Wade",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[166,"Aiken","Arlene",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[167,"Azure","Cindy",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[168,"Champagne","Sandy",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[169,"Belgarde","Clarence",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[170,"Decoteau","Rhonda",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[171,"Tillich","Joni",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[172,"Houle","Ola",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[173,"Wilson","Lori",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[174,"Moors","Roxanne",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[175,"Brien","Gerald",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,10]
[176,"Hunt","Cindy",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,10]
[177,"Guerue","John",null,"Rosebud Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[178,"Lapointe","Chantelle",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[179,"Roubideax","Bernadette",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[180,"Yellow Bird","Laura",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[181,"Dixon","Maybelle",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[182,"Young","Elizabeth\"Betty\"",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[183,"Young","Loretta",null,"Rosebud Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[184,"Sedlmejer","Linda",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[185,"Allard","Shiela",null,"Rosebud Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[186,"Little Elk","Violet",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[187,"Jones","Calvin ","sr","Rosebud Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[188,"Kills In Water","Roberta",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[189,"Decory","Gordon",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[190,"Young","Lorraine",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[191,"Zimmernan","Betty",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[192,"Menard","Marc","sr","Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[193,"Vasquez","Rita ",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[194,"Leneaugh","George",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[{"$f":"A203+1","v":195},"HollowHornBear","Michelle",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[196,"Millard","Micheal",null,"Rosebud Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[197,"Bordeaux","Leroy",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[198,"Sazue","Brent",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[199,"Two Eagle","Calvin ","sr","Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[200,"Leroy","Caroline ",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[201,"Young","Timolin",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[202,"Jones","Noble",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[203,"Willcuts","Cecilia",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[204,"Douville","Lynda",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[205,"Good Shield","Faith",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[206,"Black Wolf","Carmen",null,"Rosebud Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[207,"Felix","Deanne",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[208,"Leader Charge","Victoria",null,"Rosebud Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[209,"McCloskey","Thetis",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[210,"Elk Looks Back","Backus",null,"Rosebud Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[211,"Spotted Tail","Charity",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[212,"Heck ","Rena",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[213,"BlackSpotted Horse","Nora",null,"Rosebud Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[214,"Wooden Knife","Ruth",null,"Rosebud Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[215,"WhiteThunder","Henrietta",null,"Rosebud Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[216,"Kitteaux","Emma",null,"Rosebud Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[217,"Spotted Elk","Andrette",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[218,"Knox","Everlyn",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[219,"Felicia","Vianna",null,"Crow Creek Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[220,"Taylor","Tamra",null,"Crow Creek Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[221,"Johnson","Janna",null,"Crow Creek Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[222,"Hanley ","Richard",null,"Standing Rock Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[223,"Yankton","Tiana",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[224,"Tirado","Hope",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[225,"Larrabee","Wayne",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[226,"Witt","Jaunita",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[227,"Hawk","Bradley",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[228,"Pourier","Kimberly",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[229,"Pourier","Curtis",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[230,"Garnier","Jacqueline",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[231,"Rabbit","Leanne",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[232,"Little Hawk","Cecil","Jr","Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[233,"Brewer","Anthony",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[234,"White Calf","Irvin",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[235,"Apple","Darrell",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[236,"Pacheco","Jody",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[237,"Sitting Bear","Naomi",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[238,"Fraser","Catlin",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[239,"Stone ","Roy",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[240,"Two Lance","Vincent",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[241,"Morrisette","Jennifer",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[242,"Red Owl","Helen",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[243,"Parmenter","Michelle",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[244,"Fights Over","Carolyn",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[245,"Winters-Schaffer","Lucine",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[246,"Brewer","Dayna",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[247,"Bettelyoun","Nathaniel",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[248,"Brown","Dora",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[249,"Big Crow","Susan",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[250,"Head","Byron",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[251,"Iron Horn","Lyle",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[252,"Little Killer","Sharon",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[253,"Provost","Kin",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[254,"Randall","Jacqueline ",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[255,"Red Owl","Richard",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[256,"Vocu","Marie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[257,"Whirlwind Horse","James",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[258,"Janis","Victor",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[{"$f":"A267+1","v":259},"Pourier","Duane",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[260,"Frogg","Charlotte",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[261,"Hard Heart","Alvin",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[262,"Helper","Brandon",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[263,"Helper","Geraldine",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[264,"Hernandez","Helen",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[265,"Hernandez","Robert",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[266,"Hernandez","Sonja",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[267,"High Bull","Collette",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[268,"High Bull","Maissa",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[269,"High Bull","Marvin",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[270,"Yellow Boy","Fredrick",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[271,"Palmier","Jamie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[272,"Runnels","Cheryce",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[273,"Sitting Holy","Tara",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[274,"Spotted Bear","Jennifer",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[275,"Yellow Shield","Dallas","Jr","Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[276,"Janis","Gerald",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[277,"Swallow","Carl",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[278,"Hawk","Lora",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[279,"Amiotte","Hanna",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[280,"Westover","Agnes",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[281,"Houle","Christopher",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,10]
[282,"White Singer","Alvin",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,10]
[283,"Franchuk","Charles",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,10]
[284,"Lockwood","Charlene",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,10]
[285,"Mancera","Kimberly",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,10]
[286,"Myrick","Jacob",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,10]
[287,"GoodIron","Nathan",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,10]
[288,"Boysen","Pansey",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[289,"Anderson","Russell",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[290,"Addison","Linda",null,"Cheyenne River Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[291,"Annis ","Carmen",null,"Cheyenne River Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[292,"Arpan","Albert",null,"Cheyenne River Sioux Tribe",null,"B",null,null,null,42186,35000,10]
[293,"Ashley","Michael",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[294,"Aungie","Marquis",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[295,"Avery","Lamar",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[296,"Bagola","Preston",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[297,"Bald Eagle","Leni",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[298,"Barragan","Madonna",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[299,"Bear Stops","Aleta",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[300,"Belt","Kendra",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[301,"Bird Necklace","Sondra",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[302,"Black Bird","Ansonia",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[303,"Blue Arm","Brionne",null,"Cheyenne River Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[304,"Blue Arm","Valance",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[305,"Blue Arm","Gordon",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[306,"Blue Coat","Phillip",null,"Cheyenne River Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[307,"Blue Coat","Carla",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[308,"Bowker","Dawncee",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[309,"Bowker","Renae",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[310,"Bowker","Robert",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[311,"Bowker","Holly",null,"Cheyenne River Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[312,"Bowker","Delise",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[313,"Bowker","Michael",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[314,"Brickbill","Michelle",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[315,"Brings Plenty","Joni",null,"Cheyenne River Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[316,"Brown","Sharina",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[317,"Brown Wolf","William",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[318,"Bruguier","Melody",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[319,"Bruguier","Rhonda",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[320,"Cass","Jordan",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[321,"Castro","Chalicia",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[322,"Castro","Pamela",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[{"$f":"A331+1","v":323},"Charger","Julian",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[324,"Charger","Ferrell",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[325,"Charger","Clarice",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[326,"Chasing Hawk","Tisi",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[327,"Chasing Hawk","Taryn",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[328,"Chasing Hawk","Lynn",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[329,"Chasing Hawk","Allen",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[330,"Chasing Hawk","Ann",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[331,"Cisneros","Everardo",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[332,"Clausen","Troy",null,"Cheyenne River Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[333,"Claymore","Grady",null,"Cheyenne River Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[334,"Clown","Carlin",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[335,"Clown","Nolan",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[336,"Clown","Desiree",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[337,"Clown","Ricardo",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[338,"Clown","Raymond",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[339,"Clown","Bradley",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[340,"Collins","Wicahpi",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[341,"Collins","Delicia",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[342,"Colombe","Delphine",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[343,"Condon","Jae",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[344,"Condon","Kate",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[345,"Cook","William",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[346,"Cota Araujo","Rae Jean",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[347,"Counting","Kenneth",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[348,"Cudmore","Glen",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[349,"Curley","Jerry",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[350,"Cutt","Carmen",null,"Cheyenne River Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[351,"Defender","Earl",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[352,"Demery","Frenchy",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[353,"Dennis","Mary",null,"Cheyenne River Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[354,"Dennis","Rochelle",null,"Cheyenne River Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[355,"Different Horse","Emery",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[356,"Dog Eagle","Samantha",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[357,"Ducheneaux","Faye",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[358,"Ducheneaux","Nicole",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[359,"Ducheneaux","Theresa",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[360,"Dupris","Sharon",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[361,"Dupris","Yvonne",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[362,"Dupris","Angela",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[363,"Dupris","Jaymee",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[364,"Dupris","Julian",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[365,"Eagle Bear","Gwendolyn",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[366,"Eagle Chasing","Alvina",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[367,"Eagle Chasing","Cherronna",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[368,"Eagle Chasing","Treena",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[369,"Eagleman","June",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[370,"Elk Eagle ","Benjamin",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[371,"Eagle Chasing","LaVina",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[372,"Evans","Alexia",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[373,"Fiafoa","Alma",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[374,"Fire Cloud","Ida",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[375,"Francois","Delia",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[376,"Frazier","Natasha",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[377,"Frazier","Beyan",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[378,"Frazier","Kate",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[379,"Galaviz","Elena",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[380,"Garreau","Allen",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[381,"Garreau","Justin",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[382,"Gilbert","Eva",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[383,"Greaves","Amanda",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[384,"Guerrero","Irene",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[385,"Hale","Cleo",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[386,"Hale","Herbert",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[{"$f":"A395+1","v":387},"Hansen","Walter",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[388,"Haskell","David",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[389,"Hayes","Sharon",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[390,"Hearon","Sherlyn",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[391,"High Bear","Flora",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[392,"High Bear","Twyla",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[393,"High Bear","Cami",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[394,"High Bear","Jolene",null,"Cheyenne River Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[395,"High Bear","Andrew",null,"Cheyenne River Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[396,"High Elk","Angela",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[397,"High Elk","Arlee",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[398,"Hill","Lyn'Dee",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[399,"Hill","Jenny",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[400,"Hollow Horn","Maura",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[401,"Hollow Horn","Veldon",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[402,"Hollow Horn","Zigmund",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[403,"Holloway","Charles",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[404,"Howard","Linda",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[405,"In The Woods","Larry",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[406,"In The Woods","Burton",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[407,"In The Woods","Barbara",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[408,"Traversie","Ina",null,"Cheyenne River Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[409,"Iron Hawk","Germaine",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[410,"Iron Lightning","Marlarae",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[411,"Iron Wing","Roxanne",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[412,"Iron Wing","Gilford",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[413,"Jefferies","Wade",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[414,"Kavanaugh","Rain'e",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[415,"Keller","Delaine",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[416,"Knight","Heather",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[417,"Lafferty","Joseph",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[418,"LaPlante","Douglas",null,"Cheyenne River Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[419,"Lara","Lucy",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[420,"Fast Horse","Richard",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[421,"Laundreau","David",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[422,"Lawerence","Bryce",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[423,"LeBeau","Amber",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[424,"LeBeau","Antone",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[425,"LeBeau","Justin",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[426,"LeClaire","William",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[427,"LeCompte","D'lani",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[428,"Lee","Lola",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[429,"Lee","Joette",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[430,"Little Shield","June",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[431,"Little Shield","Nathan",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[432,"Little Sky","Chaska",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[433,"Little Star","Cassandra",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[434,"Little Star","Odessa",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[435,"Lone Eagle ","Zouie",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[436,"Lone Eagle ","Violet",null,"Cheyenne River Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[437,"Lone Eagle ","Francis",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[438,"Long Chase","Ramona",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[439,"Looking Horse","Beatrice",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[440,"Looking Horse","Ivan",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[441,"Lucero","Roberta",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[442,"Mann","Janie",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[443,"Marrowbone","David",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[444,"Marshall","Charlie",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[445,"Marti","Viodelca",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[446,"McLane","Romona",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[447,"Means","Charmayne",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[448,"Means","Jeremy",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[449,"Mestes","Orville",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[450,"Mesteth ","Larry",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[{"$f":"A459+1","v":451},"Miner","Charity",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[452,"Mitchell","Charity",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[453,"Mitchell","Merrill",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[454,"Molash","Jennifer",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[455,"Moran","Marissa",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[456,"Moran","JoBeth",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[457,"Moran","James",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[458,"Moran","John",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[459,"Moran","Kristina",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[460,"Morrison","Alyce",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[461,"Morrison","Orlando",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[462,"Mound","Arlene",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[463,"Nichols","July",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[464,"Night","Markus",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[465,"Oakie","Bernadine",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[466,"Oakie","Ila",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[467,"Oakie","Ricco",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[468,"Oliver","Dalton",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[469,"One Feather ","Lucy",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[470,"Peterson","Cal",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[471,"Phillips","Terry",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[472,"Phillips","Wendy",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[473,"Pretty Boy","Robert",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[474,"Pretty Weasel","Priscella",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[475,"Plainbull","Shannon",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,11]
[476,"Gooden","Shelly",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,11]
[477,"Demery","Justine",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,11]
[478,"Belgarde","Sarah",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,11]
[479,"Moors","Jenny",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,11]
[480,"Falcon","Ericka",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,11]
[481,"Morin","Billi Jo",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,11]
[482,"Lilley","Brian",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,11]
[483,"Jerome","Carla",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,11]
[484,"Dauphinas","Tara",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,11]
[485,"Poitra","Crystal",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,11]
[486,"Larocque","Curtis",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,11]
[487,"Picotte","Flora",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,11]
[488,"Marcellais","Marlin",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,11]
[489,"Davis","Amber",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,11]
[490,"Barron","Kelly",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,11]
[491,"Parisien","Morgan",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,11]
[492,"Azure","Ernest",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,11]
[493,"Delong","Carol",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,11]
[494,"Larocque","Darlene",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,11]
[495,"Allery","Ina",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,11]
[496,"Belgarde","Dennis",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,11]
[497,"Peltier","Darice",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,11]
[498,"Provancial","Quinn",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,11]
[499,"Sitting Bear","Sharisse",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,11]
[500,"Neiss","Laura",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,11]
[501,"MannyWounds","Marie",null,"Standing Rock Sioux Tribe",null,"B",null,null,null,42186,35000,11]
[502,"Kindle","Timothy",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,11]
[503,"Red Owl","Jennifer",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,11]
[504,"Kills Small","Brandon",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,11]
[505,"Short Bull","Jessica",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,11]
[506,"Broken Nose","Francis",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,11]
[507,"Patton","Dorothy",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,11]
[508,"Zephier","Ezra",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,11]
[509,"White Hawk","Tonya",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,11]
[510,"Black Tail Deer","Frances",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,11]
[511,"Furr","Lisa",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,11]
[512,"Beston","Jennifer",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,11]
[513,"Schultz","Lisa",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,11]
[514,"Hoover","Dinah",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,12]
[{"$f":"A523+1","v":515},"McCloud","Christa",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,12]
[516,"Peltier","Tanya","L","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,12]
[517,"Poitra","Caroline","A","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,12]
[518,"Azure","Donna","R","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,12]
[519,"Gourneau","Susan",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,12]
[520,"Desjarlais","Kristen",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,12]
[521,"Crissler","Sherry",null,"Turtle Montain Band of Chippewa",null,null,null,"C-2",null,42186,120000,12]
[522,"Lavallie","Jesse",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,12]
[523,"Vote","Raelynn",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,12]
[524,"Henry","Sloan",null,"Turtle Montain Band of Chippewa",null,null,null,"C-2",null,42186,120000,12]
[525,"Bercier","Kayla",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,12]
[526,"Champagne","Christy",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,12]
[527,"Belgarde","Gerald",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,12]
[528,"Larocque","Elaine",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,12]
[529,"Houle","Harvey",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,12]
[530,"Lenoir","Janet",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,12]
[531,"Lavallie","Peter",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,12]
[532,"Aiken","Yvonne",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,12]
[533,"Martell","Melody",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,12]
[534,"Cree","David",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,12]
[535,"Counts","Justine",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,12]
[536,"Amyotte","Ronald",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,12]
[537,"Henry","Brian",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,12]
[538,"Patnaude","John",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,12]
[539,"Bruce","Ruby",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,12]
[540,"Peltier","Rose",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,12]
[541,"Brien","Regina",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,12]
[542,"Short","Eugene",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,12]
[543,"Nadeau","Verna",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,12]
[544,"Houle","Waylon",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,12]
[545,"Azure","Kylee","M","Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,12]
[546,"Hunter","Rachel",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,12]
[547,"Richard","Joseph","Jr","Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,12]
[548,"Short Bull","Thearl",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,12]
[549,"Condon","Naomi",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,12]
[550,"Mesteth","Jill",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,12]
[551,"Roubideaux","Wyleen",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,12]
[552,"Rowland","Benton",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,12]
[553,"Waters","Rulon",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,12]
[554,"Knight","Charlene",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,12]
[555,"Longie","Kavannah",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,13]
[556,"Davis","Kylee",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,13]
[557,"Morin","Gena",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,13]
[558,"Laducer","Terry",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,13]
[559,"Lattergrass","Robert","Jr","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,13]
[560,"Walter","Dayla",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,13]
[561,"Malaterre","Doreen",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,13]
[562,"Nadeau","Roberta",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,13]
[563,"Baker","Connie",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,13]
[564,"Vivier","Bryan ",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,13]
[565,"St. Claire","Vernon",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,13]
[566,"Allery","Lonnie",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,13]
[567,"Murphy","Brenda",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,13]
[568,"Beston","Elizabeth",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,13]
[569,"Azure","Frank",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,13]
[570,"Bercier","John",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,13]
[571,"Peltier","Phyllis",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,13]
[572,"Demontigny","Ferdinand",null,"Turtle Montain Band of Chippewa",null,null,null,"C-2",null,42186,120000,13]
[573,"Prouty","Mary Ann",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,13]
[574,"Wilkie","Clarence",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,13]
[575,"Longie","Preston",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,13]
[576,"Azure","Carlyle",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,13]
[577,"Malaterre","Rodney",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,13]
[578,"Poitra","Donald",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,13]
[{"$f":"A587+1","v":579},"Boyer","Darrell",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,13]
[580,"Martin","Leona ",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,13]
[581,"Poitra","Lonnie",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,13]
[582,"St. Claire","Betty",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,13]
[583,"Demery","Jerry",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,13]
[584,"Houle","Valerie",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,13]
[585,"Martell","Shirley",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,13]
[586,"Eagle Bear","Seth",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,13]
[587,"Dupris","Ophelia",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,13]
[588,"Azure","Peter",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,14]
[589,"Decoteau","Vanessa",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,14]
[590,"Belgarde","Kindra",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,14]
[591,"Delorme","Kathleen",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,14]
[592,"Decoteau","Mary",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,14]
[593,"Vondal","Mary",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,14]
[594,"Trottier","Pauline",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,14]
[595,"Poitra","Brenda",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,14]
[596,"Lavallie","Bryant",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,14]
[597,"Wilkie","Gail",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,14]
[598,"Bruce","Caroline",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,14]
[599,"Peltier","Mary","J ","Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,14]
[600,"Greenwood","Michael",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,14]
[601,"Azure","Edward",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,14]
[602,"Falcon","Valerie",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,14]
[603,"Demery","Francine",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,14]
[604,"Hoeger","Kenny",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,14]
[605,"Counts","Harold",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,14]
[606,"Belgarde","Lyle",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,14]
[607,"Fleetwood","Sharvelle",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,14]
[608,"Morin","Michelle",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,14]
[609,"Gunville","John",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,14]
[610,"Azure","Frederick",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,14]
[611,"Crissler","Leo",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,14]
[612,"Enno","Wyman",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,14]
[613,"Peltier","Francis",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,14]
[614,"Apple ","Melanie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,14]
[615,"Vondal","Richard",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,15]
[616,"Hanson","Morgan",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,15]
[617,"Azure","Kandace",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,15]
[618,"Lavallie","Ronald","Jr","Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,15]
[619,"Crissler","Maryann",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,15]
[620,"Grant","Geraldine",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,15]
[621,"Poitra","Melinda",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,15]
[622,"Gourneau","Terri",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,15]
[623,"Poitra","Damon",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,15]
[624,"Parisien","Lorraine",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,15]
[625,"Enno","Leah",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,15]
[626,"Decoteau","Dennis",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,15]
[627,"Falcon","Sandra",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,15]
[628,"Morin","Ramona",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,15]
[629,"Longie","Anna",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,15]
[630,"Laducer","Leslie",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,15]
[631,"Baker","Pamela",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,15]
[632,"Falcon","Trina",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,15]
[633,"Beston","Sherry",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,15]
[634,"Seydel","Evangeline",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,15]
[635,"Red Elk","Ruth",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,15]
[636,"Black Smith","Norma",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,15]
[637,"Herman","Rhonda",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,15]
[638,"Randall-Ghost","Gloria",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,15]
[639,"Ruff","Corrine",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,15]
[640,"Pourier","Desiree",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,15]
[641,"Jealous Of Him","Rodney",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,15]
[642,"Broken Nose","Harriet",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,15]
[{"$f":"A651+1","v":643},"Bettelyoun","Shira",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,15]
[644,"Big Crow","Cecelia",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,15]
[645,"Big Crow","Coy",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,15]
[646,"Stover","Jennifer",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,15]
[647,"Twiss","Lindsey",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,15]
[648,"Smith","Eric","Jr","Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,15]
[649,"Young Bird","Dwight",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,15]
[650,"White Body","Ellen",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,15]
[651,"Decoteau","Robin",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,16]
[652,"Decoteau","Walter",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,16]
[653,"Short","Michael",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,16]
[654,"Decoteau","Isabel",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,16]
[655,"Thompson","Christine",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,16]
[656,"Davis","Gregory",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,16]
[657,"Larocque","Gail ",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,16]
[658,"Myers","Lawrence",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,16]
[659,"Davis","William",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,16]
[660,"Decoteau","Tina",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,16]
[661,"Allard","Frances",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,16]
[662,"Vivier","Marlin",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,16]
[663,"Kirkwood","Carol",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,16]
[664,"Lafountain","Theresa",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,16]
[665,"Bercier","Victoria",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,16]
[666,"Decoteau","Michael",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,17]
[667,"Decoteau","Rhonda",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,17]
[668,"Wilkie","Vince ",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,17]
[669,"Baker","Donna",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,17]
[670,"Franz","Hazel",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,17]
[671,"Belgarde","Norman",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,17]
[672,"Spaeth","Rose",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,17]
[673,"Lafountain","Donna",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,17]
[674,"Poitra","Eugene","M","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,17]
[675,"Morin","Sylvia",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,17]
[676,"Laverdure","Linda",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,17]
[677,"Lindgren","Yvonne",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,17]
[678,"Desjarlais","Dorothy",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,17]
[679,"Henry","Phyllis",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,17]
[680,"St. Claire","Mary",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,17]
[681,"Azure","George",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,17]
[682,"Lafountain","Lavern",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,17]
[683,"Wetherington","Lucinda",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,17]
[684,"Laducer","Linus","R","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,18]
[685,"Beston","Sheila",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,18]
[686,"Baker","Jason",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,18]
[687,"Belgarde","Lester",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,18]
[688,"Blue","Ruth",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,18]
[689,"Desjarlais","Carol",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,18]
[690,"Houle","Tina",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,18]
[691,"Lafromboise","Leann",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,18]
[692,"Peltier","Sherry",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,18]
[693,"Burcham","Dawna",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,18]
[694,"Peltier","Debra",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,18]
[695,"Steele","Glinda",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,18]
[696,"Azure","Donna",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,18]
[697,"Belgarde","Misty",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,18]
[698,"Farr","Betty",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,18]
[699,"Shots","Valerie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,18]
[700,"Cuny","Austin",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,18]
[701,"Lobzun","Faith",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,18]
[702,"Duchaine","Betty",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,19]
[703,"Charette","Wanda",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,19]
[704,"Davis","Leona ",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,19]
[705,"Wallette","Wanda",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,19]
[706,"Decoteau","Leah",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,19]
[{"$f":"A715+1","v":707},"Allery","Cheryl",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,19]
[708,"Belgarde","Gaileen",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,19]
[709,"Allery","Dallas",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,19]
[710,"Nadeau","Veronica",null,"Rosebud Sioux Tribe",null,null,"C-1",null,null,42186,120000,19]
[711,"Janis","Karlene",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,19]
[712,"Locke","Lenore",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,19]
[713,"Clifford","William",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,19]
[714,"Dodge","Brian",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,19]
[715,"Dubois","Jeremy",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,20]
[716,"Belgarde","Jennifer",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,20]
[717,"Charbonneau","Jeff",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,20]
[718,"Davis","Ramona",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,20]
[719,"Demery","Justine",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,20]
[720,"Mattson","Andrea",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,20]
[721,"Poitra","Joelle",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,20]
[722,"Belgarde","Lenore",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,20]
[723,"Poitra","Crystal",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,20]
[724,"Azure","Rosemary",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,20]
[725,"Morin","Linda",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,20]
[726,"Keplin","Rhonda",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,20]
[727,"Grant","Desire",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,20]
[728,"Charbonneau","Jessica",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,20]
[729,"Greatwalker","Laura",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,20]
[730,"Peltier","Tanya",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,20]
[731,"Peltier","Carmen",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,20]
[732,"Malaterre","Jesse",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,20]
[733,"Keplin","Julie",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,20]
[734,"Morin","Loretta",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,20]
[735,"Poitra","Arlind","Jr","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,20]
[736,"Houle","Anna",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,20]
[737,"Belgarde","Amanda",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,20]
[738,"Morin","Shirley",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,20]
[739,"Vivier","Lucille",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,20]
[740,"Allery","Dallas",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,20]
[741,"St. Pierre","Walter","Jr","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,20]
[742,"Peltier","Louise","H","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,20]
[743,"Delorme","Cecelia",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,20]
[744,"Carrington","Ben",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,20]
[745,"Norman","Betty",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,20]
[746,"Belgarde","Raymond",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,20]
[747,"Lavallie","Tanya",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,20]
[748,"Prouty","Alfred",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,20]
[749,"Rodland","Elaine",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,20]
[750,"Thomas","Shirley",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,20]
[751,"Schindler","Fred","Sr","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,20]
[752,"Peach","Georgia",null,"Turtle Montain Band of Chippewa",null,null,null,"C-2",null,42186,120000,20]
[753,"Larocque","Delray",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,20]
[754,"Caster","Roger",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,20]
[755,"Wright","Isabelle",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,20]
[756,"St. John","Eunice",null,"Crow Creek Sioux Tribe",null,"B",null,null,null,42186,35000,20]
[757,"Grass rope","Merlin",null,"Crow Creek Sioux Tribe",null,"B",null,null,null,42186,35000,20]
[758,"Thompson","Sandra",null,"Crow Creek Sioux Tribe",null,"B",null,null,null,42186,35000,20]
[759,"Silk","Emery",null,"Standing Rock Sioux Tribe",null,"B",null,null,null,42186,35000,20]
[760,"Tobacco","Gina",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[761,"Gotheridge","sammi",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,20]
[762,"Janis","Annie",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,20]
[763,"Moves Camp","Bernadette",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,20]
[764,"Brown","Fred","Sr","Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,20]
[765,"Ferguson","Jeffery","Sr","Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[766,"Tobacco","Phyllis",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,20]
[767,"Lays Bad","Gary",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,20]
[768,"Kills Straight","Birgil",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,20]
[769,"Christensen","Michael",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[770,"Janis","Mabel",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,20]
[{"$f":"A779+1","v":771},"Lone Hill","Theresa",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,20]
[772,"Garnier","William",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,20]
[773,"Two Bulls","Rachel",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[774,"Williams","Wanda",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,20]
[775,"Garcia","Mary",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[776,"Fisherman","Joseph",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[777,"Black Crow","Eugene",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,20]
[778,"Janis","Renee",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,20]
[779,"Bettelyoun","Kashmir",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,20]
[780,"Arapahoe","David",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[781,"Helper","Helen",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[782,"Gallego","John",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[783,"Steele","Tlana",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[784,"Brown Bear","Tera",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[785,"Bettelyoun","Eugenia",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,20]
[786,"Little Killer","Corrine",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[787,"Red Elk","Lydia",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,20]
[788,"Fallis","Bobbie",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,20]
[789,"Shot With Arrow","Bernard",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[790,"Kills Small","Krista",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[791,"Rogers","David",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[792,"Spotted Thunder","Tiana",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,20]
[793,"Weasel Bear","Arlette",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[794,"Dubray","Charmaine",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[795,"Flying Hawk","Stanley",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[796,"Brave Heart","Kerry",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,20]
[797,"Brewer","Lisa D.",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[798,"Bissonette","Gabrielle",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[799,"Black Elk","Jeanette",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,20]
[800,"Little Bull","Holly",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[801,"Little Sky","Faith",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[802,"Morrison","Robert",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[803,"Patton","Alisha",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[804,"Returns","Clarence",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[805,"Roan Eagle","Susan",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,20]
[806,"Steele","Sherry",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[807,"Hunts Horse","David",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,20]
[808,"Mesteth","Madeline",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,20]
[809,"Lockwood","Clayton",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,20]
[810,"Yellow Bird","Dennis",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,20]
[811,"White Tail","Nelson",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,20]
[812,"Ruiz","Amber",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,20]
[813,"Fox","Chad",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,20]
[814,"Wilkie","Rocky",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,20]
[815,"Newman","Allen",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,20]
[816,"Painte","Donald","Sr","Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,20]
[817,"Clown","Rolynn",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,20]
[818,"Blue","Lindsay",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,21]
[819,"Martell","Pamela",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,21]
[820,"Labato","Lisa",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,21]
[821,"Malaterre","Walter",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,21]
[822,"Zaste","Stephanie",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,21]
[823,"Morin","Raelynn",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,21]
[824,"Patnaude","Wilma",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,21]
[825,"Thomas","Linda",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,21]
[826,"Krom","Debra",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,21]
[827,"Bercier","Judy",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,21]
[828,"Bogardis","Grace",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,21]
[829,"Demery","Claudia",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,21]
[830,"Poitra","Bernice",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,21]
[831,"Slater","Kayla",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,21]
[832,"Martin","Nicholas",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,21]
[833,"Walter","Frank",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,21]
[834,"Waln","Courtney",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,21]
[{"$f":"A843+1","v":835},"Refel","Joey",null,"Rosebud Sioux Tribe",null,null,"C-1",null,null,42186,120000,21]
[836,"Eisenbraun","Tessa",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,21]
[837,"Brewer","Duane","Jr","Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,21]
[838,"Her Many Horses","Elena",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,21]
[839,"Spotted Elk","Myrtle",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,21]
[840,"Briggs","Ira",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,21]
[841,"Jordan","Edward",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,21]
[842,"Pourier","Candace",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,21]
[843,"Brown","Candace",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,21]
[844,"Trejo","Melda",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,21]
[845,"Afraid Of Bear","Charity",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,21]
[846,"Beane","Elizabeth",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,21]
[847,"Bear Shield","Jerry",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,21]
[848,"Janis","Tammy",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,21]
[849,"Long","Ramona",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,21]
[850,"Long","Xavier",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,21]
[851,"Lovejoy","Delores",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,21]
[852,"Two Bulls","Dawn",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,21]
[853,"Martin-Waters","Dana",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,21]
[854,"Bianas ","Catherine",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,21]
[855,"Bear","Gayla",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,21]
[856,"Hall","Rhonda",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,21]
[857,"Dye","Marilyn",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,21]
[858,"Defender","Michael",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,22]
[859,"Morin","Shawn",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,22]
[860,"Short","John",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,22]
[861,"Azure","Vita",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,22]
[862,"Peltier","Louis ",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,22]
[863,"Christopherson","Alice",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,22]
[864,"Lafromboise","Louis",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,22]
[865,"No Moccasin","Doreen",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,22]
[866,"Friday","Marsha",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,22]
[867,"Thunder Hawk","Susan",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,22]
[868,"Lebeau","Marlin",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,22]
[869,"Clifford","Edith",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,22]
[870,"Bissonette","Gabrielle 'Lisa'",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,22]
[871,"Red Cloud","Geraldine",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,22]
[872,"Red Wing","James",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,22]
[873,"Mousseau","Laura",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,22]
[874,"Palmier","Ervene",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,22]
[875,"Weston","Verne","Sr","Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,22]
[876,"Clifford","Jo-El",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,22]
[877,"Crow ","Jessica",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,22]
[878,"Tallman","Harvey",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,22]
[879,"Arapahoe","Emery",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,22]
[880,"Benson","Kelly",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,22]
[881,"Pourier","Lorna",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,22]
[882,"Red Wing","James",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,22]
[883,"Cottier","Gerald",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,22]
[884,"Henry","Glendon",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,22]
[885,"Driver","Paulette",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,22]
[886,"Young Bear","Joan",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,22]
[887,"Old Horn","Merledean",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,22]
[888,"Larocque","Floyd",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,23]
[889,"Poitra","Jennifer",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,23]
[890,"Herrera","Wanda",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,23]
[891,"Poitra","Theresa",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,23]
[892,"Lee","Gladys",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,23]
[893,"Janis ","Lorraine",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,23]
[894,"Maruffo","Stacey",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,23]
[895,"Tyon-Jacobs","Mary",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,23]
[896,"Mousseaux","Lynn",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,23]
[897,"Rodriguez","Renee",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,23]
[898,"Tobacco","Abraham",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,23]
[{"$f":"A907+1","v":899},"Smith","Merle",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,23]
[900,"White Singer","Natalie",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,23]
[901,"Dupris","Bernadine",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,23]
[902,"Bercier","Kimberly",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,24]
[903,"Delorme","Vincent",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,24]
[904,"Thiefoe","Phyllis",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,24]
[905,"Baker","Donna","M","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,24]
[906,"Belgarde","Leslie","C","Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,24]
[907,"Weber","Clara Flood",null,"Rosebud Sioux Tribe",null,null,"C-1",null,null,42186,120000,24]
[908,"Montileaux","Dawn",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,24]
[909,"Lamont","Tracy",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,24]
[910,"White Whirlwind","Lois",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,24]
[911,"Poor Thunder","Mona",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,24]
[912,"Shangreaux","Baptist",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,24]
[913,"Black Hawk","Alberta",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,24]
[914,"Kills Warrior","Katherine",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,24]
[915,"Mills ","Renee",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,24]
[916,"Red Owl ","Michelle",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,24]
[917,"Andrews","Bonita",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,24]
[918,"Bissonette","John",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,24]
[919,"Reyes","Lucille",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,24]
[920,"Felix","Hazel",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,24]
[921,"Smith","Dwight",null,"Turtle Montain Band of Chippewa",null,null,null,"C-2",null,42186,120000,25]
[922,"Desjarlais","Willard",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,25]
[923,"Bercier","Thomas",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,25]
[924,"Brown","Ed",null,"Standing Rock Sioux Tribe",null,null,null,"C-2",null,42186,120000,25]
[925,"Stretches","Jonathan",null,"Standing Rock Sioux Tribe",null,null,"C-1",null,null,42186,120000,25]
[926,"Clifford","LaWanda",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,25]
[927,"Roubideaux","Norma",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,25]
[928,"Twiss","Cheryl",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,25]
[929,"Two Bulls","Renaldo",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,25]
[930,"Wounded Arrow","Horace",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,25]
[931,"Young ","Tonya",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,25]
[932,"Ashmore","Ramona",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,25]
[933,"Iron Crow","Lynette",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,25]
[934,"Good Plume","Garvard",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,25]
[935,"Clifford","Laura",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,25]
[936,"Irving","Fawn",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,25]
[937,"Johnson","Selma",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,25]
[938,"Tail","Anthony",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,25]
[939,"Fox","Elizabeth",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,25]
[940,"Belgarde","Gerald","A","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,26]
[941,"Black Elk","Virginia",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,26]
[942,"Salcedo","Lynette",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,26]
[943,"Decory","Betty",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,26]
[944,"Waters","Phillip",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,26]
[945,"Two Two","Jeanene",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,26]
[946,"Laducer","Florence",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,26]
[947,"Belgarde","Carol",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,27]
[948,"Delorme","Phillip",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,27]
[949,"Jetty","Mary",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,27]
[950,"Standing Soldier","Earl",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,27]
[951,"Cottier","Ashley",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,27]
[952,"Poitra","Marcelline",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,28]
[953,"Lafromboise","Larry",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,28]
[954,"Shots","Valerie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,28]
[955,"Long","Beverly",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,28]
[956,"Red Kettle","Mabel",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,28]
[957,"Bull Bear","Jodi",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,28]
[958,"Frank","Sawee",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,28]
[959,"Goings","Marvin",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,28]
[960,"Zah","Candace",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,28]
[961,"Janis ","Michael",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,28]
[962,"Little Finger","Stevie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,28]
[{"$f":"A971+1","v":963},"Rogers","Delvin",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,28]
[964,"Fragoza","Hope",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,28]
[965,"Little Sky","Mary",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,28]
[966,"Davis","Linus","A","Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,29]
[967,"Young","Shiela",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,29]
[968,"Chasing Hawk","Aaron",null,"Standing Rock Sioux Tribe",null,null,"C-1",null,null,42186,120000,29]
[969,"Peil","Lorraine",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,29]
[970,"Backward","Ethel",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,29]
[971,"Westover","Gaylyn",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,29]
[972,"Zaste","Tyler",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,30]
[973,"Larocque","April",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,30]
[974,"Decoteau","Barry",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,30]
[975,"St. Pierre","Marina",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,30]
[976,"Gourneau","Gerald",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,30]
[977,"Belgarde","Duane",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,30]
[978,"Laverdure","Linda",null,"Turtle Montain Band of Chippewa",null,null,null,"C-2",null,42186,120000,30]
[979,"Allard","Arlene",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,30]
[980,"Azure","Lambert",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,30]
[981,"Gourneau","Eugene","E","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,30]
[982,"Hall","Corey","J ","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,30]
[983,"Handeland","Kim",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,30]
[984,"Peltier","Phyllis",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,30]
[985,"St. Pierre","Kevin",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,30]
[986,"Walter","Glendale",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,30]
[987,"Swain ","Dawn",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,30]
[988,"Peltier","Melvin",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,30]
[989,"Cromwell","Raeann",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,30]
[990,"Decoteau","Lucinda",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,30]
[991,"Laducer","Leslie",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,30]
[992,"Gourneau","Mike",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,30]
[993,"Bruquier","Sonia",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,30]
[994,"Davis","Sophia",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,30]
[995,"Smith","Devin",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,30]
[996,"Morin","Vicky",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,30]
[997,"Thomas","Rebecca",null,"Turtle Montain Band of Chippewa",null,null,null,"C-2",null,42186,120000,30]
[998,"Amyotte","Lawrence",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,30]
[999,"Peltier","Faye",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,30]
[1000,"Trottier","Shane",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,30]
[1001,"Belgarde","Melinda",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,30]
[1002,"Eagle Bear","Jerome",null,"Rosebud Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1003,"Crystal","McCloskey",null,"Rosebud Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1004,"Farmer","Doris",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,30]
[1005,"ShotWithTwoArrows","Melvin ","Jr","Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,30]
[1006,"Becker","Nakia",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,30]
[1007,"Red Bird","Howard",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,30]
[1008,"Estes","Todd",null,"Rosebud Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1009,"White Bird","Sheldon",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,30]
[1010,"Thin Elk","Clarissa",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,30]
[1011,"Two Charger","M.Francis Picket",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,30]
[1012,"Lapointe","Warren H",null,"Rosebud Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1013,"Young","Caroline ",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,30]
[1014,"Yougman","Daniel",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,30]
[1015,"Larvie","Harvie","Jr","Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,30]
[1016,"Smashed Ice","Sarah",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,30]
[1017,"Red Bird","Patrick T",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,30]
[1018,"His Law","Robert","Jr","Crow Creek Sioux Tribe",null,null,null,"C-2",null,42186,120000,30]
[1019,"Antelope","Valerie",null,"Standing Rock Sioux Tribe",null,null,null,"C-2",null,42186,120000,30]
[1020,"St. John","Christine",null,"Standing Rock Sioux Tribe",null,null,null,"C-2",null,42186,120000,30]
[1021,"Yellow Earrings","Ivan",null,"Standing Rock Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1022,"Little Warrior","Lori",null,"Standing Rock Sioux Tribe",null,null,null,"C-2",null,42186,120000,30]
[1023,"Cheauma","Lawrence","Jr","Standing Rock Sioux Tribe",null,null,null,"C-2",null,42186,120000,30]
[1024,"Coomes","Delvin",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1025,"New-Bad Bear","Natalie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1026,"Grass","Aldo",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,30]
[{"$f":"A1035+1","v":1027},"Black Horse","Sidney",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1028,"Bad Bear","Edsel",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1029,"Charging Crow","Everette",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1030,"White Dress","Richard",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1031,"White Face","Greeley",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1032,"Sharp","Marla",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1033,"Yellow Cloud","Todd",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,30]
[1034,"Janis","Olive",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1035,"Brown Eyes","Erroll",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,30]
[1036,"Running Hawk","Harold",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,30]
[1037,"Pumpkin Seed","Darlene",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,30]
[1038,"Richard","Denise",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,30]
[1039,"Claymore","Theresa",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,30]
[1040,"Anduja","Eric",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,30]
[1041,"Hand","Elton",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1042,"Good Voice Elk","Billy",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1043,"Tobacco","Wayland",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1044,"Hunts Horse","Jeremy",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1045,"White Eagle","Ernest",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1046,"Spotted Elk","Wayne",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1047,"Fineran","Tamera",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1048,"Conquering Bear","Orianna",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1049,"White Bull","David",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1050,"Clements","Ruby",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1051,"Bull Bear","Leona",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1052,"Iron Crow","Garfield",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1053,"Martinez","Antoinette",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1054,"Coleman","Maurice",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1055,"Brave ","Albert","Jr","Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1056,"Guthmiller","Richard",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1057,"Little Spotted Horse","Roberta",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1058,"Pipe On Head","Ben",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1059,"Saucedo","Angelina",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1060,"Star Comes Out","Juanita",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,30]
[1061,"Cottier","Alyssa",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1062,"Gutierrez-Burns","Theresa",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1063,"Black Elk","Nathaniel",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1064,"Goings","Monte",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1065,"Hand","Elton",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,30]
[1066,"American Horse","Burton",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1067,"Araphaoe","David",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1068,"Pulliam","Patricia",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1069,"Swallow","Nicole",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1070,"Tail","Frank",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,30]
[1071,"Waters","Cass",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1072,"Waters","Cleveland",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1073,"Wilson","Annette",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1074,"Wilson","Jace",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1075,"Yellow Hair","Elliott",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1076,"Kaline","Meghan",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,30]
[1077,"Tall ","Hermis",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,30]
[1078,"Shawnta","Everett",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,30]
[1079,"Fox","Danette",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,30]
[1080,"Lone Fight","Cheryl",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,30]
[1081,"Young Bear","Franklin",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,30]
[1082,"Wilson","Danielle",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,30]
[1083,"White Bear","Paul","Sr","Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,30]
[1084,"Thompson","Esther",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,30]
[1085,"Morin","Caitlin",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,31]
[1086,"Azure","Letina",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,31]
[1087,"Falcon","George","Jr","Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,31]
[1088,"Morin","Miranda",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,31]
[1089,"Houle","Latera",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,31]
[1090,"Poitra","Bobbi Jo",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,31]
[{"$f":"A1099+1","v":1091},"Blue","Sharon",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,31]
[1092,"Aiken","Constance",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,31]
[1093,"Morin","Sandra","M","Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,31]
[1094,"Black Lance","Gwendolyn",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,31]
[1095,"Waln","Candace",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,31]
[1096,"Neck","Valencia",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,31]
[1097,"Black Calf","Michelle",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,31]
[1098,"Edwards","Dorothy ",null,"Rosebud Sioux Tribe",null,null,"C-1",null,null,42186,120000,31]
[1099,"Stead","Melinda",null,"Rosebud Sioux Tribe",null,null,"C-1",null,null,42186,120000,31]
[1100,"Black Lance","Debbie",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,31]
[1101,"Dillon","Doug","sr","Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,31]
[1102,"New ","Danielle",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,31]
[1103,"Bull Bear","Maureen",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,31]
[1104,"Brewer","Lola",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,31]
[1105,"White Calf","Royce",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,31]
[1106,"Thunder Hawk","Conrad",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,31]
[1107,"Buckman","Rita",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,31]
[1108,"Henry","Ken",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,31]
[1109,"Kills Small","Lois",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,31]
[1110,"Young Bull Bear","Kelly",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,31]
[1111,"Koenen","Lew",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,31]
[1112,"Brought Plenty","Arlette",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,31]
[1113,"Fast Horse","Moses",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,31]
[1114,"Pipe On Head","Brenda",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,31]
[1115,"Two Bulls","Pauline",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,31]
[1116,"Iron Cloud","Melissa",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,31]
[1117,"Belt","Waylon",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,31]
[1118,"Steele","Deidra",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,31]
[1119,"Steele","Gary",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,31]
[1120,"One Horn","Marana",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,31]
[1121,"Incognito","Elaine",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,31]
[1122,"Gillette","Stephanie",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,31]
[1123,"Azure","Clifford","A","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,32]
[1124,"Allery","Leonard",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,32]
[1125,"Gladue","Ashley",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,32]
[1126,"Vondal","Tracey",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,32]
[1127,"Azure","Gabrielle",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,32]
[1128,"Longie","Clayton",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,32]
[1129,"Parisien","Kaylee",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,32]
[1130,"Gunville","Bobby","J","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,32]
[1131,"Enno","Jeanelle",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,32]
[1132,"Fluery","Lani",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,32]
[1133,"Malaterre","Debbie",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,32]
[1134,"Charette","Christy",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,32]
[1135,"Lenoir","Jessica",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,32]
[1136,"Falcon","Derek",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,32]
[1137,"Decoteau","James","H","Turtle Montain Band of Chippewa",null,null,null,"C-2",null,42186,120000,32]
[1138,"Steele","Dorothy",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,32]
[1139,"Vann","Irene",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,32]
[1140,"Wilkie","Jenny",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,32]
[1141,"Keplin","Clemence",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,32]
[1142,"Morin","Archie",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,32]
[1143,"Morin","Penny",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,32]
[1144,"Neilsen","Louise",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,32]
[1145,"Swallow-Arcoren","Debra",null,"Rosebud Sioux Tribe",null,null,"C-1",null,null,42186,120000,32]
[1146,"Larrabee","Jess",null,"Standing Rock Sioux Tribe",null,null,null,"C-2",null,42186,120000,32]
[1147,"One Feather","Delmar",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,32]
[1148,"Little Thunder","Blaine",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,32]
[1149,"Yellow Horse","Leonard",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,32]
[1150,"Mesteth","Francis",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,32]
[1151,"Blue Bird","Catherine",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,32]
[1152,"Fast Horse","Talbert",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,32]
[1153,"Lay","Carol",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,32]
[1154,"Rowland","Ashley",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,32]
[{"$f":"A1163+1","v":1155},"Ferguson","Antoinette",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,32]
[1156,"Gay ","Iris",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,32]
[1157,"Buckman","Ursula",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,32]
[1158,"Fast Horse","Dana",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,32]
[1159,"Buckman","Erica",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,32]
[1160,"Goings","Frank",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,32]
[1161,"Twiss","Gertrude",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,32]
[1162,"Bad Wound","Martin",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,32]
[1163,"Means","John",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,32]
[1164,"Merrival","Yvonne",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,32]
[1165,"Poor Bear","PteskaHinapaWi",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,32]
[1166,"Rowlnad","Phoebe",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,32]
[1167,"Waters","Brett",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,32]
[1168,"Winters","Esther",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,32]
[1169,"Yellow Bull","Jennifer",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,32]
[1170,"Marrow Bone","Yvette",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,32]
[1171,"Sleeping Bear","Carla",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,32]
[1172,"West","Jay",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,32]
[1173,"Martinelli","Michaela",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,32]
[1174,"Bailey","Alona",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,32]
[1175,"Morsette","Chad","Sr","Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,32]
[1176,"Swift Eagle","Jolene",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,32]
[1177,"Delilah","Charger",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,32]
[1178,"Charbonneau","Jessica",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,33]
[1179,"Gourneau","Inez",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,33]
[1180,"Champagne","Willard",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,33]
[1181,"Martin","Yvonne",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,33]
[1182,"Keplin","Larry",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,33]
[1183,"Black Spotted Horse","Ethel",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,33]
[1184,"Franzen","Vernell",null,"Standing Rock Sioux Tribe",null,null,null,"C-2",null,42186,120000,33]
[1185,"Gary","Debra",null,"Standing Rock Sioux Tribe",null,"B",null,null,null,42186,35000,33]
[1186,"Black Feather","Glenda",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,33]
[1187,"Merrival","Leonard",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,33]
[1188,"Yellow Shield","Erna",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,33]
[1189,"Red Cloud","Vanessa",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,33]
[1190,"Two Eagle","Jolynn",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,33]
[1191,"Wilson","Kayla",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,33]
[1192,"Bettelyoun","Colleen",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,33]
[1193,"Marshall","Kimberly",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,33]
[1194,"Marshall","Nora",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,33]
[1195,"Martinez","Ellen",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,33]
[1196,"Nelson","J.R.",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,33]
[1197,"White","Krista",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,33]
[1198,"Marshall","Lisa",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,33]
[1199,"Her Many Horses","Robin",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,33]
[1200,"Eagle","Alberta",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,33]
[1201,"Esparza","Lolita",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,33]
[1202,"Good Crow","Delores",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,33]
[1203,"Bagola","Collette",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,33]
[1204,"Long ","Genevieve",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,33]
[1205,"White Bull","Lisa",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,33]
[1206,"Gibbons","Glen",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,33]
[1207,"Goings","Marvin",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,33]
[1208,"Grinnell","Charles",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,33]
[1209,"Holy Bear","Anthony",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,33]
[1210,"Blacksmith","Cheryl",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,34]
[1211,"Thiefoe","Nicole",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,34]
[1212,"Trottier","Alfred",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,34]
[1213,"Qugley","Patricia",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,34]
[1214,"Red Feather","Helen",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,34]
[1215,"Good Voice Flute","Merrill",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,34]
[1216,"Kills In Water","Valorie",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,34]
[1217,"Brewer","Lenora",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,34]
[1218,"Shangreaux","Baptist",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,34]
[{"$f":"A1227+1","v":1219},"Watkins","Lisa",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,34]
[1220,"Chief","Waverly",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,34]
[1221,"Pourier","Derek",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1222,"Pourier","Michelle",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,32]
[1223,"Chief Eagle","Margaret",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,34]
[1224,"Slow Bear","Alvin",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,34]
[1225,"Clifford","Anne",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,34]
[1226,"American","Carmen",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,34]
[1227,"Morrison","Noella",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,34]
[1228,"Shaving","Gerald",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,34]
[1229,"Peltier","Wendy",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,35]
[1230,"Swain ","Loretta",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,35]
[1231,"Champagne","Gloria",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,35]
[1232,"Morin","Mary","C","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,35]
[1233,"Jaste","Karen",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,35]
[1234,"Defender","Delores",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,35]
[1235,"Jeanotte","Verna",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,35]
[1236,"Johnson","Edward","Sr","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,35]
[1237,"Shields","Cheryl",null,"Crow Creek Sioux Tribe",null,"B",null,null,null,42186,35000,35]
[1238,"Olsen","Hazel",null,"Crow Creek Sioux Tribe",null,"B",null,null,null,42186,35000,35]
[1239,"Long Crow ","Chauncey",null,"Crow Creek Sioux Tribe",null,"B",null,null,null,42186,35000,35]
[1240,"Condon","Deirdre",null,"Standing Rock Sioux Tribe",null,"B",null,null,null,42186,35000,35]
[1241,"Lodge","Henry",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,35]
[1242,"Locke","Marlene",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,35]
[1243,"Richard","Joseph",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,35]
[1244,"Mora","Rhea",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,35]
[1245,"Good Plume","Garvard",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,35]
[1246,"Pourier","Alonna",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,35]
[1247,"Standing Soldier","Victor",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,35]
[1248,"Briseno","Brandon",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,35]
[1249,"Red Cloud","Guy",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,35]
[1250,"Red Cloud","Linda",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,35]
[1251,"Red Cloud","Marty",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,35]
[1252,"Goings","Yvonne",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,35]
[1253,"Wilkie","Jennifer",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,35]
[1254,"Dunn","Germaine",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,35]
[1255,"Keplin","Rose","M","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,36]
[1256,"Cree","Jesse",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,36]
[1257,"Belgarde","Steven",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,36]
[1258,"Allery","Carol",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,36]
[1259,"Delorme","Darlene",null,"Turtle Montain Band of Chippewa",null,null,null,"C-2",null,42186,120000,36]
[1260,"Brien","Rita",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,36]
[1261,"Vivier","Cora",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,36]
[1262,"Touch","Clara",null,"Standing Rock Sioux Tribe",null,null,"C-1",null,null,42186,120000,36]
[1263,"Standing Elk","Joseph",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,36]
[1264,"Sharpfish","Donald",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,36]
[1265,"Goodman","Leola",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,36]
[1266,"Big Crow","Walter",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,36]
[1267,"Janis","Cora",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,36]
[1268,"Horse","Alberta",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,36]
[1269,"Garnier","Dirk",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,36]
[1270,"Trevino","Shannon",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,36]
[1271,"Kills Warrior","Geraldine",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,36]
[1272,"Brown Eyes","Pete",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,36]
[1273,"Rabbithead","Kenneth",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,36]
[1274,"Laducer","Debra",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,37]
[1275,"Sherman","Clarrisa",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,37]
[1276,"Lavallie","Lawrence",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,37]
[1277,"Lafountain","Benedict",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,37]
[1278,"Menard","Janice",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,37]
[1279,"Blue Thunder","Lawrence",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,37]
[1280,"Brown Wolf","Julia",null,"Crow Creek Sioux Tribe",null,"B",null,null,null,42186,35000,37]
[1281,"Pourier","Dale",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,37]
[1282,"Alkire","Mildred",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,37]
[{"$f":"A1291+1","v":1283},"Garnier","Oliver",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,37]
[1284,"Kills In Water","Wilma",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,37]
[1285,"Fire Thhunder","Lillian",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,37]
[1286,"Rosalas","Mabel",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,37]
[1287,"Lone Fight","Donald",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,37]
[1288,"Boyer","Leonard",null,"Turtle Montain Band of Chippewa",null,null,null,"C-2",null,42186,120000,38]
[1289,"Slater","Delane",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,38]
[1290,"Hunt","Ruth",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,38]
[1291,"Falcon","Linda",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,38]
[1292,"Night Shield","Francine",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,38]
[1293,"Wilson","Jewell",null,"Crow Creek Sioux Tribe",null,null,null,"C-2",null,42186,120000,38]
[1294,"Titus","Emma",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,38]
[1295,"Red Paint","Yolanda",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,38]
[1296,"Bordeaux","Chrystal",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,38]
[1297,"Yellow Wolf","Joseph",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,38]
[1298,"Protector","Dawson",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,38]
[1299,"Nadeau","Mildred",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,39]
[1300,"Nadeau","Gerald","L","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,39]
[1301,"Azure","James","M","Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,39]
[1302,"Jumping Eagle","Juanita",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,39]
[1303,"Thunder Hawk","Bernadette",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,39]
[1304,"Janis","Richard",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,39]
[1305,"Little Hawk","Julia",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,39]
[1306,"White Hawk","Matyna",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,39]
[1307,"Chase","James","Jr","Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,40]
[1308,"Larocque","Cody",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,40]
[1309,"Decoteau","Lisa","K","Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,40]
[1310,"Belgarde","Duane","L","Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,40]
[1311,"Morin","Blake","Jr","Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,40]
[1312,"Blue","Patrick",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,40]
[1313,"Vivier","Velma",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,40]
[1314,"Jollie","Edward",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,40]
[1315,"Lavallie","George",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,40]
[1316,"Morin","Ronald","Jr","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,40]
[1317,"Faine","Jenny",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,40]
[1318,"Swain ","Francis",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,40]
[1319,"Eagle Bear","Patrick ",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1320,"Burning Breast","Kathy",null,"Rosebud Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1321,"Yellow Robe","Joseph",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1322,"Shaw","Darlene",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1323,"Witt","Paula",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1324,"Eagleman","Nellie",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1325,"Ree","Myra",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1326,"Wright","Stephanie",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1327,"Peneaux","Tylene",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1328,"Spotted tail","Darwin",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1329,"Burning Breast","Jeanette",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1330,"Marshall","Loretta",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1331,"Kills Plenty","George",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1332,"First In Trouble","Theodore",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1333,"Covey","Janet",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1334,"Guerue","Andrea",null,"Rosebud Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1335,"Stands By Ear","John",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1336,"Farmer","Dessirea",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1337,"Chasing Horse","Franklin V",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1338,"Guerue","Burton",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1339,"Mirreau","Justin",null,"Crow Creek Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1340,"Howe","Gina",null,"Crow Creek Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1341,"Harrison","Brian",null,"Crow Creek Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1342,"Brown Bull","Peter",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1343,"Cross Dog","Ronald",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1344,"Dismounts Thrice","Charlotte",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1345,"Good Voice Elk","Roseann",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1346,"Weston","Jamie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[{"$f":"A1355+1","v":1347},"Puckett","Flora",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1348,"Merrival","Barton",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1349,"Two Lance","Marissa",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1350,"Lamont","Jaun",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1351,"Alvarado","Julian",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1352,"Two Bulls","Catherine",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1353,"Brave Heart","Sylvester",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1354,"Mercado","Rebecca",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1355,"Pedregon","Ella Sioux",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1356,"Makes Good","Antoine",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1357,"Watkins","Austin",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1358,"Janis","Dean",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1359,"Tobacco","Chelsea",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1360,"Black Bull","Michelle",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1361,"DeSersa","Kandee",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1362,"Watters","Kelly",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1363,"Jealous Of Him","Waylon",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1364,"Long Jaw","Cheyenne",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1365,"White Plume","Unpowin",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1366,"Steele","Andrew",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1367,"Wounded Arrow","Purvis",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1368,"Ten Fingers","Theodore",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1369,"Brave","Ohitika",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1370,"Means","Francis",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1371,"Poor Thunder-Clifford","Melonie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1372,"Martinez","Annabelle",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1373,"White Calf`","Ansel",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1374,"Champagne","Maurice",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1375,"Red Cloud","Bernard","III","Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1376,"Brown","Stanley",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1377,"Spotted Elk","Cordelia",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1378,"Bird Necklace","Dawn",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1379,"Bad Yellow Hair","Marlena",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1380,"White Butterfly","Ronald",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1381,"Two Bulls","Melissa",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1382,"Shott ",null,null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1383,"Steele","Darwin",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1384,"White Face","Monique",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1385,"Janis ","Thomas",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1386,"Merrival","Yvonne",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1387,"Leftwich","Roman",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1388,"American Horse","Joel",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1389,"Bad Bear","Denissha",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1390,"Backward","Archie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1391,"Siers","Anna",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1392,"Janis","Sydney",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1393,"Black Bear","Jacqueline",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1394,"Arapahoe","Candace",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1395,"Janis","Jay",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1396,"Plenty Wolf","Latonna",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1397,"Red Boy","Jaunita",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1398,"Marshall","Abe",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1399,"Stands ","Cynthia",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1400,"Holy Eagle","Clem",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1401,"Little Killer","Leon",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1402,"Lakota","Gloria",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1403,"Montelongo","Talena",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1404,"Red Blanket","Rick",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1405,"Standing Soldier","Quentin",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1406,"White Bull","Darrell",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1407,"Yellow Elk","Henry",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1408,"Brown Bull","Verdell",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1409,"Clifford","Edward",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1410,"Dillon","Verna",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[{"$f":"A1419+1","v":1411},"Dubray","Melanie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1412,"Eagle Elk","Christopher",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1413,"Elk","Nathalie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1414,"Good Voice Elk","Woniya",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1415,"Hunter","Paulette",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1416,"Makes Good","Stevie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1417,"Makes Good ","Vinnie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1418,"One Horn","Crystal",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1419,"Spencer","Jennifer",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1420,"Talks","Lonnie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1421,"Bush","Jason",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1422,"Catches","Desiree",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1423,"Cottier","Jeremy",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1424,"Hernandez","Julian",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1425,"Horse","Ambrose",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1426,"Horse","Malcolm",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1427,"Horse","Thurman",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1428,"Little ","Garrell",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1429,"Lone Elk","Brian",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1430,"Oldsen","Tadrey",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1431,"Wounded Head","Anthony",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1432,"Apple ","Frank","Jr","Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1433,"New-Bad Bear","Elizabeth",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1434,"Bagola","Candida",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1435,"Belt","Merton",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1436,"Black Smith","Jackie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1437,"Black Smith","Vonna",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1438,"Corbine","Eric",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1439,"Cuny","Wade",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1440,"Eagle Hawk","Jennifer",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1441,"Janis","Joelle",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1442,"LaDeaux","Colton",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1443,"Long Visitor","Jennifer",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1444,"Long Visitor","Leah",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1445,"Little Spotted Horse","Norton",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1446,"Means","Henry",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1447,"Plenty Arrows","Carley",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1448,"Saucedo","Stephanie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1449,"Starr","Roberta",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1450,"Two Eagles","Ona",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1451,"Warrior","Lavelle",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1452,"Clifford","Eli",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1453,"Clifford","Toree",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1454,"Cortier","Harley",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1455,"Dowty","Dawn",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1456,"Garnier","Yolanda",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1457,"Buckman","Waverly",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1458,"Black Elk","Tabitha",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1459,"Bordeaux","Kenneth",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1460,"Brewer","Lisa M.",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1461,"Brown","Cody",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1462,"Haas","Gilminita",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1463,"Hawk Wing","Elijah",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1464,"Hawk Wing","George",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1465,"Hollow Horn","Albert",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1466,"Janis","Charles",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1467,"Bissonette","Calvin",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1468,"DuBray","Ruth",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1469,"Garner","Lorette",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1470,"Mousseaux","Eddy",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1471,"Waters","Raymond",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1472,"Bagola","Lisa",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1473,"Bettelyoun","Eric",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1474,"Bissonette","Pedro",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[{"$f":"A1483+1","v":1475},"Bissonette","Wendy",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1476,"Janis","Gary Dawn",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1477,"Kills Enemy At Night","Dale",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1478,"Lafferty","Uriah",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1479,"Little Moon","Missy",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1480,"Long","Mitchell",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1481,"Mousseaux","Dustin",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1482,"Mousseaux","Ronald",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1483,"Oldson","Macy",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1484,"Patton","Michelle",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1485,"Richards","Filmore",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1486,"Shangreaux","Kelly",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1487,"Standing Soldier","Leah",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1488,"Stoldt","Ray",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1489,"Swick","Emmanuel",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1490,"Swift Bird","Peter",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1491,"Tobacco","Curtis",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1492,"Ten Fingers","Freida",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1493,"Thunder Bull","Earl",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1494,"Two Bulls ","Marissa",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1495,"Two Bulls ","T'Lana",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1496,"Two Eagle","Jolynn",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1497,"Waters","Cole",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1498,"Day Boy-Waters","Marla",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1499,"Waters","Kelly",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1500,"White","Cassandra",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1501,"Whiting","Christopher",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1502,"White Eyes","Melanie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1503,"White Magpie","Latisha",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1504,"White Rabbit","Cheryl",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1505,"Wolfe","Tara",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1506,"Yellow Bird-Steele","Michelle",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1507,"Yellow Boy","Christopher",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1508,"Clifford","Carmena",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1509,"Hawk Wing","Virgil",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1510,"Kelly ","Heather",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1511,"One Horn","Darrell",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1512,"Pino","Rainbow",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1513,"Pettigrew","Susan",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1514,"Respects Nothing","Doris",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1515,"Touche","Samantha",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1516,"Coomes","Theodore",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1517,"Goings","Monte",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1518,"Grass","Kristen",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1519,"Haas","Gilmanita",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[1520,"Garnier","Stephanie",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,40]
[1521,"Baker","Talana",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,40]
[1522,"Bateman","Jeffrey",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,40]
[1523,"White Singer","Alvin",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,40]
[1524,"Old Rock","Francis","Jr","Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,40]
[1525,"Dye","Grayson",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,40]
[1526,"Fox","Tana",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,40]
[1527,"Newman","Herald",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,40]
[1528,"Smith","Davina",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,40]
[1529,"Whitman","Heather",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,40]
[1530,"Halvorson","Arden",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,40]
[1531,"Irwin","Aaron",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,40]
[1532,"Sheppo","Henry",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,40]
[1533,"Smith","Ryan",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,40]
[1534,"Lovelette","Scot",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1535,"Garreau","Melvin",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1536,"Brown","Benjamin",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1537,"Fielder","William",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1538,"Little Moon","Wallace",null,"Cheyenne River Sioux Tribe",null,null,"C-1",null,null,42186,120000,40]
[{"$f":"A1547+1","v":1539},"Chasing Hawk","Tisevera",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1540,"High Hawk","Floyd",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1541,"Bowker","Marlene",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1542,"Long","Nial",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1543,"White Magpie","Marta",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1544,"Brings Horse","James",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1545,"Thunder Hawk","Madonna",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1546,"Traversie","Ty",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1547,"High Elk","Clara",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1548,"LaClaire","Charlene",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1549,"Buck Elk Thunder","Ethlene",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,40]
[1550,"Bruce","Marlene",null,"Turtle Montain Band of Chippewa",null,null,null,"C-2",null,42186,120000,41]
[1551,"Nadeau","Linda","M","Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,41]
[1552,"Hall","Charlene",null,"Turtle Montain Band of Chippewa",null,null,null,"C-2",null,42186,120000,41]
[1553,"Lenoir","William",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,41]
[1554,"Longie","Stella",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,41]
[1555,"Grandboise","Judith",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,41]
[1556,"Ludwig","Christine",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,41]
[1557,"Romero","T-Sheena",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,41]
[1558,"Smith","Chelsea",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,41]
[1559,"Plumman","Katelyn",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,41]
[1560,"Swift","Diana",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,41]
[1561,"Colhoff","Desiree",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,41]
[1562,"Eagle Bull","Paul",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,41]
[1563,"Martinez","Roberta",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,41]
[1564,"Afraid Of Bear","Jeremy",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,41]
[1565,"Kills Enemy","Gerard",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1566,"Garbaldi","Ana",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1567,"DeSersa","Sherman",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1568,"Vonasch","Katela",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1569,"Dodge","Brian",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,41]
[1570,"Cheyenne","Mabel",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1571,"Saucedo","Angelina",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1572,"Evans ","Jennifer",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1573,"Little Boy","Maria",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1574,"Rhambrose","Carmen",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1575,"Bettelyoun","Darin",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1576,"Two Two","Ashley",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,41]
[1577,"Sierra","Heather",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,41]
[1578,"Apple ","Mary ",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1579,"Black Elk-Homer","Rayette",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1580,"Clifford","Christina",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,41]
[1581,"Morrisette","Amanda",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1582,"Bad Wound","Katheena",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1583,"Jack","Alice",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1584,"Watson","Pamlyn",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1585,"Curry ","Albert",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1586,"Catches","Martin",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1587,"Jones","Lorrie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1588,"Fast Wolf","Antoinette",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,41]
[1589,"Randall","Rodney",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1590,"Coleman","Tricia",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1591,"High Hawk","Charles",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1592,"Lone Hill","Malcolm",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1593,"Mesteth","Travis",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1594,"Peneaux","Karen",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1595,"Quick Bear","Jennifer",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1596,"Shot","He-Ska-Win",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1597,"Thunder Hawk",null,null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1598,"Thunder Hawk","Suzette",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1599,"Belt ","Novelyn",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1600,"Brave","Georgianna",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,41]
[1601,"Chief Eagle","Lucille",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1602,"Corbine","Jack",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[{"$f":"A1611+1","v":1603},"Rouillard","Samuel",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1604,"Sits Poor","Franklin",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1605,"Tobacco","Eldon",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1606,"Two Bulls","Samantha",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1607,"Yellow Hair","Elmer",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1608,"Coomes","Nikki",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,41]
[1609,"Cuny","Raeann",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,41]
[1610,"Day Boy","Miranda",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1611,"Fast Horse","Jason",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,41]
[1612,"Fast Horse","Nichole",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1613,"Brewer","Lenora",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1614,"Brings Him Back","Ellis",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,41]
[1615,"Brings Plenty","Darrell",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1616,"Ghost Bear","Jeri",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,41]
[1617,"Horse","Maryann",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1618,"Janis","Rodney",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1619,"Trejo","Reann",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1620,"Little Hawk","Kelmarie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1621,"Little Hawk","Marvin",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1622,"Long Soldier","Joylinn",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1623,"Mesteth","Rachel",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,41]
[1624,"Merrival","Michael",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1625,"Merrival","Thomas",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1626,"Nelson","Dallas",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1627,"Nelson","Sam",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1628,"Oldson","Echo",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1629,"Red Cloud","John",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,41]
[1630,"Richards","Ariel",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1631,"Stewart","Carley",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1632,"Two Bulls","Harold",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1633,"Two Two","Mary Jo",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1634,"Weston","Mark",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1635,"Wounded Arrow","Brenda",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1636,"Youngman","Gavin",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1637,"Black Elk","Ryan",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1638,"Chase Alone","Reggie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1639,"Chief Eagle","Erica",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,41]
[1640,"Duchaine","Roddora",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,41]
[1641,"Good Bear","Cheryle",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,41]
[1642,"Morsette","Dawn",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,41]
[1643,"Lockwood","Heather",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,41]
[1644,"Black Hawk","Helen",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,41]
[1645,"Conklin","Alyssa",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,41]
[1646,"Morsette","Dawn",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,41]
[1647,"Shakespear","Brenda",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,41]
[1648,"Goetz","Carrie",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,41]
[1649,"Boyer","Allen",null,"Turtle Montain Band of Chippewa",null,null,null,"C-2",null,42186,120000,42]
[1650,"Delorme","Joanne",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,42]
[1651,"Swain ","Frank","Sr","Turtle Montain Band of Chippewa",null,null,null,"C-2",null,42186,120000,42]
[1652,"Allery","David",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,42]
[1653,"Laducer","Alfred","J","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,42]
[1654,"Jeanotte","Angel",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,42]
[1655,"Larvie","Candace",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,42]
[1656,"White Bull","Ferris",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1657,"Chavez","Myron","Jr","Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1658,"Waters","Chifon",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1659,"Weston","Carol",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,42]
[1660,"Weston","Kimberly",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1661,"Vocu","Michelle",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1662,"Little","Sioux Dawn",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1663,"Kills In Water","Gwen",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1664,"Lodge","Michael",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,42]
[1665,"Little Bear","Garrett",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1666,"Iron Crow","Rochelle",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,42]
[{"$f":"A1675+1","v":1667},"Hernandez","Julian",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1668,"Little Boy","Geraldine",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1669,"Standing Soldier","Kimberly",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1670,"True Blood","Imogene",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1671,"Martinez","Jessica",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1672,"Belt","Merton",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1673,"Martinez","Christina",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1674,"Black Crow","Jaydee",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1675,"Belt","Amy",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1676,"Ghost","Shilo",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1677,"Standing Soldier","Kenneth",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1678,"Janis","Shalene",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1679,"Smoke","Benjamin",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1680,"Ramos","Katrina",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1681,"Lone Elk","Daniel",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1682,"Leftwich","April",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1683,"Returns","Clarence","Sr","Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1684,"Warrior","Felicia",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,42]
[1685,"Mesteth","Jennifer",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1686,"Janis ","Belva",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1687,"Boyd","Tana",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1688,"Goings ","Luhanna",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1689,"Martinez","Antoine",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1690,"Rooks","JoAnn",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,42]
[1691,"Rosalas","April",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,42]
[1692,"Tobacco","Belva",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,42]
[1693,"Hernandez","Ben",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1694,"Lone Elk","Lucille",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1695,"Means","Gabrielle",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,42]
[1696,"Ponca","Janelle",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1697,"Swallow","David",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1698,"Two Eagle","Edward",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1699,"Young Bear","Cameron",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,42]
[1700,"Big Crow","Stacy",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,42]
[1701,"Dreaming Bear","Angel",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1702,"Fast Horse","Calendra",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1703,"Garnier","Germaine",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,42]
[1704,"High Hawk ","Natasha",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1705,"Long ","Jennifer",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1706,"Tobacco","Bobbi Jo",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1707,"Two Eagles","Eleanor",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,42]
[1708,"Weasel Bear","Ashley",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1709,"Clifford","Edith",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1710,"Little-Davis","Misty",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,42]
[1711,"Eagle Bull","Autumn",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1712,"Fox Belly","Summer",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1713,"Brown","Leann",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1714,"Goings ","Yvonne",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1715,"Iron Horse","Jeremy",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1716,"Iron Horse","Jeremy",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1717,"Conroy","Opal",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1718,"Bissonette","Tracy",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1719,"Little","Kandis",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1720,"Little","Raine",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,42]
[1721,"Little Bear","Ramona",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1722,"Little Bear","Richard",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1723,"Little Hawk","Rosalie",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,42]
[1724,"McGaa","Dawn",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,42]
[1725,"McLaughlin","Carla",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,42]
[1726,"Martinez","Annabelle",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1727,"Peters","Kelly",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1728,"Poor Bear","Irene",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1729,"Red Cloud","Betty",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,42]
[1730,"Red Feather","Martin",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[{"$f":"A1739+1","v":1731},"Red Hawk","Mary",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1732,"Red Hawk","Mollie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1733,"Salway","Vanessa",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1734,"Shangreaux","James",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1735,"Swift Bird","Faron",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1736,"Tobacco","Harold",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1737,"Three Fingers","Anastasia",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1738,"Twiss","Justine",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1739,"Walking","Tracy",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1740,"Waters","Alan",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1741,"Weston","Antonio",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1742,"Whalen","Quentin",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,42]
[1743,"Wilson","Kayla",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1744,"Kootswatewa","Erika",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1745,"LaDeaux","Megan",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1746,"Martinez","King",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1747,"Romero","Leslie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1748,"Water","Charles",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1749,"Yellow Hawk","Tessie",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,42]
[1750,"Yellow Shield","Sheryl",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1751,"Bolman","Joni",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,42]
[1752,"Moniz","Melanie",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,42]
[1753,"White Bear","Beverly",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,42]
[1754,"Lone Eagle ","Al",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,42]
[1755,"High Pine","Delores",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,42]
[1756,"Miner","William",null,"Cheyenne River Sioux Tribe",null,null,"C-1",null,null,42186,120000,42]
[1757,"Moran","Roderick",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,42]
[1758,"Hileman","Virginia",null,"Turtle Montain Band of Chippewa",null,null,null,"C-2",null,42186,120000,43]
[1759,"Esmie","Vanessa",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,43]
[1760,"Davis","Alfred",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,43]
[1761,"Jordan","Rose",null,"Standing Rock Sioux Tribe",null,null,null,"C-2",null,42186,120000,43]
[1762,"Wilson","Norman","Sr","Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,43]
[1763,"Amercan Horse","Romona",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,43]
[1764,"Wilson-Brave","Alicia",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1765,"Martinez","Molbay",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1766,"Mesteth","Mary",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1767,"Short Bull","Marcia",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,43]
[1768,"Red Cloud","Marty","Jr","Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,43]
[1769,"One Horn","Savanna",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1770,"Sitting Holy","Sondra",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1771,"Pourier","Jessica",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1772,"Lone Hill","Monica",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1773,"Tail","Holly",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,43]
[1774,"Camp","Rayette",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,43]
[1775,"Romero","Charlotte",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,43]
[1776,"Jones ","Lorrie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1777,"Palmier","Sheri",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1778,"Marshall","Summer",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1779,"Thin Elk","Babette",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,43]
[1780,"Clements","Ruby",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1781,"Three Fingers","Anastasia",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1782,"Hernandez","Faye",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,43]
[1783,"Twiss","Justine",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,43]
[1784,"Richards-Fisherman","Floreda",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1785,"Simental","Pedro",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1786,"Brewer","Lisa M.",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1787,"Jumping Eagle","Mandi",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1788,"Lopez","Casey",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1789,"Coleman","Jesse",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,43]
[1790,"Imitates Dog","Celeste",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1791,"Pourier","Douglas",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1792,"Sitting Bear","Romaine",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1793,"Shangreaux","Clarissa",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1794,"Yellow Wolf","Crystal",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[{"$f":"A1803+1","v":1795},"Sevilla","Betty",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1796,"Schweigman","Donna",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1797,"Short Bull","Jewel",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1798,"Weasel Bear","Francy",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1799,"Humming Bird","Evonne",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1800,"Witt","Santee",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1801,"Basurto","Cassandra",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1802,"Krueger","Yolanda",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1803,"Pulliam","Patricia",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,43]
[1804,"Red Cloud","Tiffany",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1805,"Red Shirt","Matilda",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1806,"Weston","Verne","Jr","Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1807,"White Calf","Beverly",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1808,"White Dress","Alvin",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1809,"Clifford","Jo-El",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1810,"Clifford","Toree",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1811,"Clifford","William",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1812,"Condon","Naomi",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,43]
[1813,"Giago","Richard",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1814,"Goings","Doris",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,43]
[1815,"Goings","Frank",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,43]
[1816,"Ramirez","Manuel",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,43]
[1817,"Blue Arm","Teresita",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,43]
[1818,"Decoteau","Patrick","J","Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,44]
[1819,"Chase","Leroy",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,44]
[1820,"Sea Walker","Gertrude",null,"Standing Rock Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1821,"Quick Bear","Urva",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1822,"Last Horse","Joyce",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,44]
[1823,"White Dress","Cyrinthia",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1824,"Bissonette","Roger",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1825,"Brown","Doreen",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1826,"Jumping Eagle","Edward","Sr","Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1827,"Mercado","Sophia",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1828,"Thunder Bull","Kimberly",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,44]
[1829,"High Hawk","Sheri",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,44]
[1830,"Kocer","Lavon",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,44]
[1831,"Pourier","Denise",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,44]
[1832,"Brave Heart","He Tehila",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1833,"Price","Janelle",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1834,"Giago","Richard",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1835,"Bark","Ryan",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1836,"Red Feather","Kathy",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1837,"Respects Nothing","Anna",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1838,"White Face","David",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1839,"Tail","Mary",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1840,"Bettelyoun","George",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,44]
[1841,"Morgan","Sophie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1842,"Black Elk","Tabitha",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1843,"Brown","Lindsey",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,44]
[1844,"Buckman","Clifford",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1845,"Buckman","Misty",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1846,"Gutierrez-Burns","Theresa",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1847,"Caldwell","Brandon",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1848,"Carlow","Michelle",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1849,"Catches","Arvella",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1850,"Catches","Dale",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1851,"Catches","Johnathan",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1852,"Champagne","James",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1853,"Chief Eagle","Rachel",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1854,"Clifford","Anne",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1855,"Clifford","Edith",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,44]
[1856,"Kazena","Charlotte",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,44]
[1857,"Quick Bear","Kelli",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,44]
[1858,"Good Left","Myrtle",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,44]
[{"$f":"A1867+1","v":1859},"Houston","Marvin",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,44]
[1860,"Horn","Aaron",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,44]
[1861,"Low Dog","Nora",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,44]
[1862,"Peltier","Sylvester",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,45]
[1863,"Malaterre","Thomas",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,45]
[1864,"Morin","Lawrence",null,"Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,45]
[1865,"Sitting Crow","Victor",null,"Crow Creek Sioux Tribe",null,"B",null,null,null,42186,35000,45]
[1866,"Brings Plenty","Delano",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,45]
[1867,"Lamont","Shaler",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,45]
[1868,"Marshall","Albert","Sr","Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,45]
[1869,"Bad Milk","Ione",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,45]
[1870,"Chief Eagle","Lucille",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,45]
[1871,"Janis","Tiffany",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,45]
[1872,"Belt","Sara",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,45]
[1873,"Milk","Orville",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,45]
[1874,"Pierce","Richard",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,45]
[1875,"Marshall ","William",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,45]
[1876,"Standing Soldier","Mary",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,45]
[1877,"White Face","Manuel",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,45]
[1878,"Returns","Bonnie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,45]
[1879,"Ten Fingers","Evelyn",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,45]
[1880,"Red Elk","Ernest",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,45]
[1881,"Good Crow","Delores",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,45]
[1882,"Good Plume","Garvard",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,45]
[1883,"Oakie","Romanus",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,45]
[1884,"Howard","Amelia",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,45]
[1885,"Thomas","Bernard",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,46]
[1886,"Fast Wolf","Varden",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,46]
[1887,"Jacobs","Wesley",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,46]
[1888,"Apple","Fern",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,46]
[1889,"Pumpkin Seed","Colleen",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,46]
[1890,"Bettelyoun","George",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,46]
[1891,"Locke","Darrell",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,46]
[1892,"Red Ear Horse","Karen",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,46]
[1893,"Black Feather","Lucille",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,46]
[1894,"Reddy","Timothy",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,46]
[1895,"Red Hawk","Melvin",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,46]
[1896,"Romero","Eloise",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,46]
[1897,"Tyon","Floyd","Sr","Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,46]
[1898,"Brown","Judith",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,46]
[1899,"Belgarde","Carol","J","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,47]
[1900,"Thomas","Rebecca","M","Turtle Montain Band of Chippewa",null,null,null,"C-2",null,42186,120000,47]
[1901,"McCloskey","Lenora",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,120000,47]
[1902,"Frazer","Francis",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,47]
[1903,"White Face","Ellen",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,47]
[1904,"Hunter","Caroline",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,47]
[1905,"Bordeaux","Lee",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,47]
[1906,"Sitting Eagle","James",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,47]
[1907,"Poitra","Lionel",null,"Turtle Montain Band of Chippewa",null,null,"C-1",null,null,42186,120000,48]
[1908,"Kills In Water","Theresa",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,48]
[1909,"Richards","Douglas",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,48]
[1910,"Brave Heart","Lyle",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,48]
[1911,"Old Horse","Faron",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,48]
[1912,"Fisherman","Ronald",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,48]
[1913,"Brewer","Mona",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,48]
[1914,"Goings","Doris",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,48]
[1915,"Little Dog","Joseph",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,48]
[1916,"Swan","Valerie",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,48]
[1917,"West","Nancy",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,48]
[1918,"Decoteau","Irene","M","Turtle Montain Band of Chippewa",null,"B",null,null,null,42186,35000,49]
[1919,"Brewer","Alden",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,49]
[1920,"Grooms","William",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,49]
[1921,"Garnier","Wanda",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,49]
[1922,"Grooms","William",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,49]
[{"$f":"A1931+1","v":1923},"Whalen","Jeffrey",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,49]
[1924,"Spotted Bear","Hobart",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,49]
[1925,"High Elk","Salina",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,49]
[1926,"Mesteth","Larry",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,49]
[1927,"Iron Hawk","Inez",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,49]
[1928,"Smith","Kayo F.",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,50]
[1929,"Howe","John",null,"Crow Creek Sioux Tribe",null,"B",null,null,null,42186,35000,50]
[1930,"Big Road","Frieda",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,50]
[1931,"Cortier","Adrian",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,50]
[1932,"Red Hawk","Melvin",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,50]
[1933,"Garner","Louis",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,50]
[1934,"Big Road","Freida",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,50]
[1935,"Mousseaux","Fred",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,50]
[1936,"Spotted Eagle","Bernice",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,50]
[1937,"Wilkinson","Gordon",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,50]
[1938,"Lovelette","Wayne",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,50]
[1939,"Hill","Joyce",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,50]
[1940,"Darlene","Bowker",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,50]
[1941,"Hollow Horn","Linda",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,51]
[1942,"Steele","Chester",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,51]
[1943,"Goings","Rochelle",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,51]
[1944,"Rooks","Grace",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,51]
[1945,"Red Cloud","Verdell",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,51]
[1946,"Ribsman","Sheldon",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,51]
[1947,"Sitting Bear","Verna",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,51]
[1948,"Wells","Billie",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,51]
[1949,"Red Horse","Hermus",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,51]
[1950,"Black Lance","Marie",null,"Rosebud Sioux Tribe",null,null,null,"C-2",null,42186,120000,52]
[1951,"Fleury","Velma",null,"Crow Creek Sioux Tribe",null,"B",null,null,null,42186,35000,52]
[1952,"Red Elk","Vern",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,52]
[1953,"Little Brave","Christina",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,52]
[1954,"Quiver","Louis",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,52]
[1955,"Lamere","Roger",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,52]
[1956,"Bull Bear","Meltino",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,52]
[1957,"Gay ","Nancy",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,52]
[1958,"Janis ","Norma",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,52]
[1959,"One Horn ","Tylene",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,52]
[1960,"Perea","Julia",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,52]
[1961,"Dreaming Bear","Delmar",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,52]
[1962,"Morgan","Sophie",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,52]
[1963,"Stands","Richard",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,52]
[1964,"White Magpie","Victoria",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,52]
[1965,"Little Wounded","Patricia",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,52]
[1966,"High Hawk","Natasha",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,53]
[1967,"Vitalis","Darrell",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,53]
[1968,"Wilson","Edna",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,53]
[1969,"Two Bulls","Ron",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,53]
[1970,"Dull Knife","Guy","Sr","Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,53]
[1971,"Black Feather","Glenda",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,53]
[1972,"Chaddelsone-Little","Janice",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,53]
[1973,"Red Cloud","Theresa",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,53]
[1974,"Standing Soldier","Donald",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,53]
[1975,"Owl King","Elizabeth",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,53]
[1976,"Noble","Joy",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,54]
[1977,"Feather Earring","Luwanda",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,54]
[1978,"Martin","Antoine",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,54]
[1979,"Janis ","Filbert",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,54]
[1980,"Martin","Lema",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,54]
[1981,"DeSersa","Clifton",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,54]
[1982,"Little Bear","Roselyn",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,54]
[1983,"Phillips","Beatrice",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,54]
[1984,"Catches","Veda",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,54]
[1985,"Hill","Ford",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,54]
[1986,"Collins","Phyllis",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,54]
[{"$f":"A1995+1","v":1987},"Huber","Elsie",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,55]
[1988,"Janis","Tiffany",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,55]
[1989,"Hollow Horn","Joyce",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,55]
[1990,"Warrior","Sylvia",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,55]
[1991,"Janis","Donna",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,55]
[1992,"Garfield","John",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,55]
[1993,"Red Paint","Matthew",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,55]
[1994,"Little White Man","Louis",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,56]
[1995,"Lone Hill","Mildred",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,56]
[1996,"Coleman","Ella",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,56]
[1997,"Catches","Cynthia",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,56]
[1998,"In The Woods","Loveleah",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,56]
[1999,"Locke","Mary",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,57]
[2000,"Long ","Bart",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,57]
[2001,"Rodriquez","Marilyn",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,57]
[2002,"Kills Plenty","Marie",null,"Rosebud Sioux Tribe",null,"B",null,null,null,42186,35000,58]
[2003,"Tobacco","Orlando",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,58]
[2004,"Garnette","Aqualynne",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,58]
[2005,"One Feather","Phyllis",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,58]
[2006,"Cottier","Leo",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,58]
[2007,"Mousseaux","Oletha",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,58]
[2008,"Walker","Quanah",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,58]
[2009,"Danley","Elberta",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,58]
[2010,"Iron Wing","Barbara",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,58]
[2011,"Herman","Patrick ","Sr","Rosebud Sioux Tribe",null,null,"C-1",null,null,42186,120000,59]
[2012,"Whirlwind Horse","William",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,59]
[2013,"Brave Eagle","Ruby",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,59]
[2014,"Martin-Vegas","Carmel",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,59]
[2015,"White Bull","Dawn",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,60]
[2016,"Elk","Anthony",null,"Three Affiliated Tribes",null,null,"C-1",null,null,42186,120000,60]
[2017,"Good Shield","Mary",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,60]
[2018,"LaPlante","Lanny",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,60]
[2019,"Watkins","Lisa",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,61]
[2020,"Montreal","Magdeline",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,61]
[2021,"Montreal","Magdeline",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,61]
[2022,"Starr","Edward",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,62]
[2023,"Lefthand","Richard",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,62]
[2024,"Yellow Wolf","Eunice",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,62]
[2025,"Dixon","Althea",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,62]
[2026,"Black Bear","Millie",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,62]
[2027,"Little Bear","Roselyn",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,63]
[2028,"Red Cloud","Sylvia",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,63]
[2029,"Garnette","Anthony",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,64]
[2030,"Standing Soldier","Vern",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,65]
[2031,"Swan","Barbara",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,66]
[2032,"Twin","Irvene",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,66]
[2033,"Eagle Hawk","Christopher",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,66]
[2034,"Brings Him Back","Olive",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,67]
[2035,"Grass","Duffy",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,68]
[2036,"Broken Nose","Tex",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,69]
[2037,"Around Him-Fineran","Anne",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,71]
[2038,"Cortier","Lila",null,"Oglala Sioux Tribe",null,null,null,"C-2",null,42186,120000,79]
[2039,"Brown Thunder","Joe",null,"Oglala Sioux Tribe",null,null,"C-1",null,null,42186,120000,83]
[2040,"Garnette","Theodore",null,"Oglala Sioux Tribe",null,"B",null,null,null,42186,35000,93]
[2041]
[null,"Pretty Weasel","Kristen",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Pretty Weasel","Madrick",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10,{"$f":"COUNT(N10:N2050)","v":3}]
[null,"Quilt","Charlene",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Red Bear","Pierce",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Red Bear","Arvin",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Red Bear","Gina",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Red Bear","Sheldon",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Red Bird","Cheryl",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Red Bird","Rochelle",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Red Bull ","Elizabeth",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Red Fox","Sandra",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Red Fox","Patricia",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Red Horse","Devina",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Red Horse","Iris",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Reindle","Maris",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Richards","Jacey",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Rivers","Patrick",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Rivers","William",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Roach","Cameo",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Roberts","Melissa",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Romero","Mabel",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Rosas","Dion",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Runs After","Marilyn",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Sand","Frankie",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Sand","Caroline",null,"Cheyenne River Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[null,"Sherman","Marita",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Shooter","Jacob",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Spotted Bear","Robert",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Spotted Horse","Kim",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Stadel","Jordan",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Strong Heart","Sylvia",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Sunkaska","David",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Swimmer","Tim",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Takes The Knife","Jorden",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Takes The Knife","Marty",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Talks","Sandra",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Taylor","Paula",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Taylor","Charles",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Thompson","Alex",null,"Cheyenne River Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[null,"Thompson","Kenton",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Thompson","Marty",null,"Cheyenne River Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[null,"Traversie","Misti",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Two Hearts","Karen",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Uses Many","Jared",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Veo","Jeff",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Veo","Bill",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Viet","Joni",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Walking Crane","Arnold",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Waloke","April",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Waloke","Sylvester",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"War Cloud","Artis",null,"Cheyenne River Sioux Tribe",null,null,"C-1",null,null,42186,120000,10]
[null,"White Dog","David",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"White Eagle","Leonard",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"White Eyes","Lonny",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"White Feather","Virginia",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"White Feather","Evan",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"White Magpie","Wendell",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Whiteman","Oscar",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Widow","Narcelle",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Widow","Ed",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Widow","Norris",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Wolfe","Orlando",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Yellow Hawk","Kathy",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Young","Angela",null,"Cheyenne River Sioux Tribe",null,null,null,"C-2",null,42186,120000,10]
[null,"Belgarde","Imogene",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,20]
[null,"Greyhorn","Vincent","Sr","Spirit Lake Tribe",null,"B",null,null,null,42186,35000,20]
[null,"LaRoque","Trudy",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,20]
[null,"Ross","Claudette",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,25]
[null,"Cavanaugh","Daniel",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,10]
[null,"Lohnes","David","Sr","Spirit Lake Tribe",null,"B",null,null,null,42186,35000,10]
[null,"Thomas","Wanda",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,10]
[null,"Myrick","Pauline",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,10]
[null,"Demarce","Andrew",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,75]
[null,"Georgeson","Sharon",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,61]
[null,"Culbertson","Pierre",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,53]
[null,"Thomas","Richard",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,53]
[null,"Abraham","Glenn",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,46]
[null,"Bendickson","Deborah",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,44]
[null,"Littleghost","Elizabeth",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,42]
[null,"Jackson","Barbara",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,40]
[null,"Chaske","Corrine",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,38]
[null,"Cloud","Aloysius",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,38]
[null,"Touche","Omar",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,37]
[null,"Green","Inez",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,37]
[null,"Herman","Terrance",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,37]
[null,"Denne","Randy",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,35]
[null,"Cavanaugh","Peggy",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,34]
[null,"Woods ","Anna",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,31]
[null,"Chaske","Winfield",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,29]
[null,"Young","Wesley",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,28]
[null,"Morin","Andrew",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,27]
[null,"Redroad","Francis",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,27]
[null,"Whiteman","Cora",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,25]
[null,"Alfeldt","Joyce",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,25]
[null,"Sherman","Joseph",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,24]
[null,"Lawrence","Jeanette",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,23]
[null,"Lohnes","Steve",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,22]
[null,"Greywater","Delemma",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,21]
[null,"Ironheart","Silas","Jr","Spirit Lake Tribe",null,"B",null,null,null,42186,35000,19]
[null,"Stensland","Loretta",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,18]
[null,"Demarce","Timothy",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,18]
[null,"Wadsworth","Darlene",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,17]
[null,"Robinson","Elaine",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,2]
[null,"Thomas","Adrian",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,10]
[null,"Feather","Virgil",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,10]
[null,"Belgarde","Cheryl",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,10]
[null,"Davidson","Eunice",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,10]
[null,"Jetty","Charlene",null,"Spirit Lake Tribe",null,"B",null,null,null,42186,35000,10]

{"sheet":"Instructions ","index":3,"n_rows":131,"n_cols":2,"rows_kept":131,"cut":false,"hidden":false,"merged":[[115,1,115,6],[116,1,116,6],[117,1,117,6],[118,1,118,6],[119,1,119,6],[60,1,60,6],[61,1,61,6],[111,1,111,6],[112,1,112,6],[113,1,113,6],[104,1,104,6],[85,1,85,6],[96,1,96,6],[99,1,99,6],[86,1,86,6],[84,1,84,6],[77,1,77,6],[78,1,78,6],[79,1,79,6],[81,1,81,6],[75,1,75,6],[32,1,32,6],[33,1,33,6],[38,1,38,6],[41,1,41,6],[34,1,34,6],[36,1,36,6],[68,1,68,6],[63,1,63,6],[66,1,66,6],[48,1,48,6],[52,1,52,6],[55,1,55,6],[35,1,35,6],[46,1,46,6],[62,1,62,6],[47,1,47,6],[49,1,49,6],[53,1,53,5],[54,1,54,6],[67,1,67,6],[58,1,58,6],[59,1,59,6],[14,1,14,6],[9,1,9,5],[7,1,7,6],[42,1,42,6],[45,1,45,6],[15,1,15,6],[39,1,39,2],[40,1,40,2],[37,1,37,6],[30,1,30,6],[31,1,31,6],[26,1,26,6],[25,1,25,5],[27,1,27,6],[18,1,18,6],[19,1,19,6],[20,1,20,6],[21,1,21,6],[22,1,22,6],[16,1,16,6],[17,1,17,6],[23,1,23,6],[29,1,29,6],[28,1,28,6],[1,1,1,6],[10,1,10,5],[12,1,12,6],[13,1,13,6],[5,1,5,6],[11,1,11,6],[8,0,8,6],[6,1,6,6],[2,1,2,6],[3,1,3,6],[4,1,4,6],[129,1,129,6],[109,1,109,6],[106,1,106,6],[83,1,83,5],[91,1,91,6],[87,1,87,6],[108,1,108,5],[93,1,93,6],[94,1,94,6],[95,1,95,6],[110,1,110,6],[101,1,101,6],[97,1,97,6],[100,1,100,6],[89,1,89,6],[105,1,105,6],[128,1,128,6],[120,1,120,6],[121,1,121,6],[122,1,122,6],[123,1,123,6],[125,1,125,6],[124,1,124,6],[114,1,114,6],[126,1,126,6],[127,1,127,6],[102,1,102,6],[103,1,103,6],[98,1,98,6],[88,1,88,6],[90,1,90,6],[92,1,92,6],[43,1,43,6],[44,1,44,6],[56,1,56,6],[57,1,57,6],[50,1,50,6],[82,1,82,5],[72,1,72,6],[64,1,64,6],[65,1,65,6],[80,1,80,6],[73,1,73,6],[69,1,69,6],[70,1,70,6],[71,1,71,6],[74,1,74,6],[76,1,76,6]]}
[]
[null,"This workbook was created using Windows 10, Office Suite Excel 10. There may be some compatibility issues when trying to use this workbook with an earlier version of Excel. It may not work with Microsoft Excel 7 Workbook version. "]
[null,"You are using the Electronic VBA Version of the 2024 HIP Tribal Annual Performance Report. This version shall only be used for FY 2024."]
[null,"This workbook contains macros and formulas, to properly use this Excel Workbook, you must save as enabled Workbook or enable the security macros."]
[null,"To save for use with an older version of Excel,choose Office,then Save As and select one of these options from the Save As Type dropdown list:1)Excel 10 Workbook;2)Save as type:Excel Enabled Workbook;3)Save by adding your tribe name to file;(e.g. 2024 HIP Tribal Annual Performance Report - Your Tribe name)"]
[null,"The 2024 HIP Tribal Annual Performance Report is due to your respective region by COB December 31, 2023."]
[null,"Before submitting this workbook to your respective Regional Office,                                     please save as type: Excel Workbook."]
[null,"Operating Systems: Windows 10 "]
[]
[null,"Profile"]
[null,"Item Number Instructions"]
[null,"To properly populate the combo box, please make selection in the regions   dropdown box twice."]
[1,"Select Region from Dropdown box, twice."]
[{"$f":"A13+1","v":2},"Select Tribe/Consortium from Dropdown box."]
[{"$f":"A14+1","v":3},"Press the continue button."]
[{"$f":"A15+1","v":4},"Select member Tribe of Consortia from Dropdown Box"]
[{"$f":"A16+1","v":5},"Provide four digit fiscal year (FY) that identifies fiscal year in which work plan will be implemented. (Fiscal year beginning in October 1, of the current calendar year)."]
[6,"Provide name of preparer in the event we may need to contact you."]
[7,"Select position that you are currently holding from Dropdown Box."]
[8,"Provide phone number."]
[9,"Provide fax number."]
[10,"Provide email address."]
[11,"Digital signature, will Autofill when cell \"D10\" is filled. (Cell is protected)"]
[12,"Will Autofill when cell \"D9\" is filled. (Cell is protected)"]
[]
[null,"Form"]
[null,"Portions of this worksheet are protected and have formulas."]
[1,"Provide District or Member Tribe of consortia, if applicable."]
[{"$f":"A28+1","v":2},"Provide the Date when the applicant signed the application."]
[{"$f":"A29+1","v":3},"Provide Last Name of Applicant."]
[{"$f":"A30+1","v":4},"Provide First Name of Applicant."]
[{"$f":"A31+1","v":5},"Select Suffix Name from Dropdown Box ( i.e. Sr. Jr. III. IV) "]
[6,"Provide Tribal Enrollment number of applicant."]
[7,"Select Category of service, applicant is requesting from Dropdown Box. (i.e. A, B, C-1, C-2, D) "]
[8,"Provide total number of occupants in the household."]
[9,"Provide total amount of income for all family members."]
[10,"Provide birthdate of  1st aged person. (i.e. 06/13/1950)"]
[11,"Select \"Yes\" if claiming disability, \"No\" if no disability."]
[12,"Provide number of dependents."]
[13,"Select \"Yes\" if house is in  dilapidated condition              Select, \"No\" if house in in repairable condition."]
[14,"Select \"Yes\" if applicant is a Native Veteran"]
[15,"Provide date when applicant signed application."]
[16,"Select \"Yes\" if applicant received a letter of denial of service and is waiting list from Tribal Housing Authority.        Select \"Pending\" if applicant will get a letter from Housing Authority at a later time.                                                                      Select \"No\" if  applicant has not obtained a denial letter and is not on the Tribal Housing Authority waiting list. "]
[17,"Select \"Yes\" if applicant has received HIP assistance. Select \"No\" if applicant has \"Not\" received HIP assistance in their lifetime.  "]
[18,"Select \"Yes\" if applicant has received housing assistance from the Native American Self Determination Housing Act (NAHASDA) of 1997. Select \"No\" if applicant has \"Not\" received housing assistance from NAHASDA.  "]
[19,"Provide an Estimated Start Date. (i.e. 07/16/2013)"]
[20,"Provide an Estimated cost for project. (i.e. 130,000)"]
[21,"Click the \"Transfer\" button to print Priority Calculation sheet and transfer data to worksheets \"Priority Calculation\" and \"Tribe Part I\". Place printed calculation sheet in Applicant case file."]
[22,"For extra sheets, Click the \"Print\" button to print the Calculation sheet ."]
[23]
[24]
[]
[null,"*Program Category:  (A)  Interim Improvements; (B) Renovations; (C-1) Replacement Housing (replacement of existing, substandard dwelling); (C-2) Replacement Housing (housing provided, no existing dwelling) "]
[null,"Priority List Form"]
[null,"Portions of this worksheet are protected and have formulas."]
[null,"Row \"2\", Cell \"C2\" will auto fill from information entered in worksheet \"Form\". (Cell is protected)"]
[1,"Row \"2\", Cell \"M2\" will auto fill from information entered in worksheet \"Form\". (Cell is protected)"]
[{"$f":"A57+1","v":2},"Row \"3\", Cell \"M3\" will auto fill from information entered in worksheet \"Form\". (Cell is protected)"]
[{"$f":"A58+1","v":3},"Row \"4\",Cell \"M4\" will auto fill from information entered in worksheet \"Form\". (Cell is protected)"]
[4,"Column B will auto fill from information entered in worksheet \"Form\". "]
[5,"Column C will auto fill from information entered in worksheet \"Form\"."]
[6,"Column D will auto fill from information entered in worksheet \"Form\"."]
[7,"Column E will auto fill from information entered in worksheet \"Form\". "]
[8,"Column F will auto fill from information entered in worksheet \"Form\". "]
[9,"Column G will auto fill from information entered in worksheet \"Form\". "]
[10,"Column H will auto fill from information entered in worksheet \"Form\". "]
[11,"Column I will auto fill from information entered in worksheet \"Form\". "]
[12,"Column J will auto fill from information entered in worksheet \"Form\". "]
[13,"Column K will auto fill from information entered in worksheet \"Form\". "]
[14,"Column L will auto fill from information entered in worksheet \"Form\". "]
[15,"Column M will auto fill from information entered in worksheet \"Form\". "]
[16,"Column N will auto fill from information entered in worksheet \"Form\". "]
[17,"Column O will auto fill from information entered in worksheet \"Form\". "]
[18,"Column P will auto fill from information entered in worksheet \"Form\". "]
[19,"Column Q will auto fill from information entered in worksheet \"Form\". "]
[20,"Column R will auto fill from information entered in worksheet \"Form\". "]
[21,"Column S will auto fill from information entered in worksheet \"Form\". "]
[22,"Column T will auto fill from information entered in worksheet \"Form\". "]
[23,"Column U will auto fill from information entered in worksheet \"Form\". "]
[24,"Column V will auto fill from information entered in worksheet \"Form\". "]
[25,"When printing Priority Calculation sheet, to prevent printing extra sheets, select file, select print, select active sheets and select the number of sheets you want to print."]
[]
[null,"Tribe Part I"]
[null,"Item Number Instructions"]
[]
[null,"Row \"2\", Cell \"E2\" will auto fill from information entered in worksheet \"Form\". (Cell is protected)"]
[1,"Row \"2\", Cell \"K2\" will auto fill from information entered in worksheet \"Form\". (Cell is protected)"]
[null,"Row \"3\", Cell \"E3\" will auto fill from information entered in worksheet \"Form\". (Cell is protected)"]
[{"$f":"A87+1","v":2},"Row \"3\", Cell \"K3\" will auto fill from information entered in worksheet \"Form\". (Cell is protected)"]
[null,"Row \"4\",Cell \"E4\" will auto fill from information entered in worksheet \"Form\". (Cell is protected)"]
[{"$f":"A89+1","v":3},"Row \"4\", Cell \"K4\" will auto fill from information entered in worksheet \"Form\". (Cell is protected)"]
[null,"Row \"5\", Cell \"E5\" will auto fill from information entered in worksheet \"Form\". (Cell is protected)"]
[{"$f":"A91+1","v":4},"Row \"5\", Cell \"K5\" will auto fill from information entered in worksheet \"Form\". (Cell is protected)"]
[null,"Column B will auto fill from information entered in worksheet \"Form\". "]
[{"$f":"A93+1","v":5},"Column C will auto fill from information entered in worksheet \"Form\"."]
[null,"Column D will auto fill from information entered in worksheet \"Form\"."]
[null,"Column E will auto fill from information entered in worksheet \"Form\". "]
[{"$f":"A95+1","v":6},"Column F will auto fill from information entered in worksheet \"Form\". "]
[{"$f":"A98+1","v":7},"Column G will auto fill from information entered in worksheet \"Form\". "]
[null,"Column H will auto fill from information entered in worksheet \"Form\". "]
[null,"Column I will auto fill from information entered in worksheet \"Form\". "]
[null,"Column J will auto fill from information entered in worksheet \"Form\". "]
["8a","Column K will auto fill from information entered in worksheet \"Form\". "]
["8b","Column L will auto fill from information entered in worksheet \"Form\". "]
["9a","Column M will auto fill from information entered in worksheet \"Form\". "]
[null,"Column N will auto fill from information entered in worksheet \"Form\". "]
["9b","When printing Tribe Part I, to prevent printing extra sheets, select file, select print,select print active sheets and select the number of sheets you want to print."]
[]
[null,"Tribe Part II"]
[null,"Item Number Instructions"]
[null,"Portions of this worksheet are protected and have formulas; it contains no macros."]
[]
[null,"Will autofill (Cells are protected)"]
["1a","Will autofill (Cells are protected)"]
["1b","Will autofill (Cells are protected)"]
["2a","Will autofill (Cells are protected)"]
["2b","Will autofill (Cells are protected)"]
["2c","For each recipient provided program service, within accomplishing reporting FY, enter last and first name of recipient."]
[3,"Provide Name of the Tribe/Consortium for which information is being reported."]
[4,"For each recipient listed in Item Number 3,enter the type of program assistance provided, by entering a digit (1) in the applicable Program Category column(s):"]
[5,"     (A)   Interim Improvements (Repairs)"]
[null,"     (B)   Renovations"]
[null,"     (C-1) Replacement Housing (replacement of existing substandard housing)."]
[null,"     (C-2) New Housing (provision of housing for families without a home)."]
[null,"     (D) Down Payment Assistance (provision of housing in providing a grant for down payment)."]
[null,"For each recipient listed in Item 6a, enter the Actual Start Date (MM/YY) of the construction project."]
["6a","For each recipient listed in Item 6, enter Actual Completion Date of the project."]
["6b","For each recipient listed in Item Number 7a, enter Actual Administrative Cost of the project."]
["7a","For each recipient listed in Item Number 7b, enter Actual Project Cost."]
["7b","Will autofill. (Cell is Protected)"]
["7c"]

{"sheet":"Profile","index":4,"n_rows":589,"n_cols":20,"rows_kept":589,"cut":false,"hidden":false,"merged":[[0,1,0,4],[19,1,21,4],[2,1,2,4],[6,1,6,4],[14,2,14,4],[36,1,36,4],[28,1,28,4],[29,1,35,4],[37,1,42,4],[1,1,1,4]]}
[null,"Housing Improvement Program",null,null,null,null,null,"ALASKA","EASTERN OKLAHOMA","EASTERN ","GREAT PLAINS","MIDWEST","NAVAJO","NORTHWEST","PACIFIC","ROCKY MOUNTAIN","SOUTHERN PLAINS","SOUTHWEST","WESTERN"]
[null,"Tribal Annual Performance Report",null,null,null,null,"ALASKA","Arctic Slope Native Association","Chickasaw","Aroostook Band of Micmacs ","Crow Creek","Bay Mills","Navajo Nation","Chehalis","Agua Caliente","Blackfeet","Alabama-Coushatta","Cochiti","Ak-Chin Community","Housing Officer"]
[null,"Profile",null,null,null,null,"EASTERN ","Association of Village Council Presidents","Choctaw","Catawba Indian Tribe        ","Flandreau","Bois Forte",null,"Coeur D'alene","Alturas","Crow","Apache Of Oklahoma","Isleta","Battle Mountain","Housing Executive Director"]
[null,null,null,null,null,null,"EASTERNOKLAHOMA","Bristol Bay Native Association","Creek","Cayuga Nation         ","Fort Berthold","Fon Du Lac",null,"Colville","Auburn","Fort Belknap","Caddo","Jemez","Cocopah","Housing Director"]
[null,1,"Region","WESTERN",null,null,"GREATPLAINS","Central Council Tlingit and Haida","Eastern Shawnee","Chickahominy Indian Tribe   ","Fort Totten","Forest County",null,"Coos Bay","Augustine","Fort Peck","Cheyenne & Arapaho","Jicarilla","Colorado River","Housing Coordinator"]
[null,2,"Tribe / Consortia","Quechen",null,null,"MIDWEST","Cook Inlet Tribal Council","Miami","Chickahominy Indians - Eastern Division                        ","Lower Brule","Grand Portage",null,"Coquille","Barona","Little Shell","Citizen Potawatomi","Laguna","Duck Valley","Other"]
[null,null,null,null,null,null,"NAVAJO","Council Of Athabascan Tribal Governments","Modoc","Chitimacha Tribe of Louisiana ","Oglala Sioux Pine Ridge","Grand Traverse",null,"Cow Creek","Benton","Northern Cheyenne","Comanche Nation","Mescalero","Duckwater"]
[null,3,"Agency",null,null,null,"NORTHWEST","Fairbanks Native Association","Osage","Coushatta Indian Tribe of Louisiana                           ","Omaha","Hannahville",null,"Cowlitz","Berry Creek","Chippewa Cree ","Delaware","Nambe","Elko"]
[null,4,"Fiscal Year",2024,null,null,"PACIFIC","Inupiat Community of the Arctic Slope","Ottawa","Eastern Band of Cherokee Indians ","Ponca","Ho-Chunk (Wis. Potawatomi)",null,"Grand Ronde","Big Lagoon","Northern Arapaho","Fort Sill Apache","Picuris","Ely"]
[null,5,"Name",null,null,null,"ROCKYMOUNTAIN","Kawerak Inc","Peoria","Houlton Band of Maliseet Indians                                   ","Rosebud Sioux","Huron Band of Potawatomi",null,"Hoh","Big Pine","Shoshone","Iowa Of Kansas","Pojoaque","Fallon"]
[null,6,"Title",null,null,null,"SOUTHERNPLAINS","Kuskokwim Native Association","Quapaw","Jena Band of Choctaw Indians ","Santee Sioux","Keweenaw Bay",null,"Sb-Jamestown S'kallum","Big Sandy",null,"Iowa Of Oklahoma","Ramah","Fort McDermitt"]
[null,7,"Phone #",null,null,null,"SOUTHWEST","Maniilaq Association","Seminole","Mashantucket Pequot Tribe  ","Sisseton-Wahpeton","Lac Courte Oreilles",null,"Kalispel","Big Valley",null,"Kaw Of Oklahoma","San Felipe","Fort McDowell"]
[null,8,"Fax #",null,null,null,"WESTERN","Tanana Chiefs Conference","Seneca-Cayuga","Mashpee Wampanoag Tribe   ","Standing Rock","Lac Du Flambeau",null,"Klamath","Bishop",null,"Kickapoo Tribe Of Kansas","San Ildfonso","Gila River"]
[null,9,"Email",null,null,null,null,"Native Village Of Akhiok","Thlopthlocco","Miccosukee Tribe           ","Trenton","Lac Vieux Desert",null,"Kootenai","Blue Lake",null,"Kickapoo Tribe Of Oklahoma","San Juan","Goshute Business Council"]
[null,null,"I certify that the information given is true, complete and correct to                                                                                                                    the best of my knowledge, belief, and they are made in good faith.",null,null,null,null,"Akiachak Native Community","Wyandotte","Mississippi Band of Choctaw Indians","Turtle Mountain","Leech Lake",null,"Lower Elwha","Bridgeport",null,"Kickapoo Tribe Of Texas","Sandia","Havasupai"]
[null,10,"Signature",{"$f":"IF(D10=\"\",\"\",D10)","v":""},null,null,null,"Akiak Native Community",null,"Mohegan Indian Tribe    ","Winnebago","Little River Ottawa",null,"Sb-Lummi","Buena Vista",null,"Kiowa Of Oklahoma","Santa Ana","Hopi Tribe"]
[null,11,"Date",{"$f":"IF(D16=\"\",\"\",NOW())","v":""},null,null,null,"Native Village Of Akutan",null,"Monacan Indian Nation ","Yankton","Minominee",null,"Makah","Cabazon",null,"Otoe-Missouria","Santa Clara","Hopi Tribe (Hpl)"]
[null,null,null,null,null,null,null,"Village Of Alakanuk",null,"Nansemond Indian Tribe ",null,"Mille Lacs Ojibwe",null,"Metlakatla","Cahuilla",null,"Pawnee","Santa Domingo","Hualapai"]
[null,null,null,null,null,null,null,"Alatna Village",null,"Narragansett Indian Tribe  ",null,"Minnesota Chippewa Tribe",null,"Muckleshoot","Campo",null,"Ponca","Southern Ute","Kabaib Paiute"]
[null,null,null,null,null,null,null,"Native Village Of Aleknagik",null,"Oneida Indian Nation    ",null,"Oneida Tribe ",null,"Nez Perce","Cedarville",null,"Prairie Potawatomi","Taos","Lovelock"]
[null,null,null,null,null,null,null,"Allakaket Village",null,"Onondaga Indian Nation ",null,"Odawa, Little Traverse",null,"Nisqually","Chicken Ranch",null,"Sac & Fox - Missouri","Tesuque","Moapa"]
[null,null,null,null,null,null,null,"Native Village Of Ambler",null,"Pamunkey Tribe of Virginia ",null,"Pokagon Band Potawatomi",null,"Nooksack","Chico",null,"Sac & Fox Nation - Oklahoma","Ute Mountain","Pascua Yaqui"]
[null,null,null,null,null,null,null,"Village Of Anaktuvuk Pass",null,"Passamaquoddy Tribe – Indian Township             ",null,"Prairie Island",null,"Nw Band Shoshoni","Cloverdale",null,"Tonkawa Tribe of Oklahoma","Ysleta Del Sur","Pyramid Lake"]
[null,null,null,null,null,null,null,"Yupiit Of Andreafski",null,"Passamaquoddy Tribe – Pleasant Point                               ",null,"Red Cliff",null,"Port Gamble","Cold Springs",null,"Wichita","Zia","Quechen"]
[null,null,null,null,null,null,null,"Angoon Community Association",null,"Penobscot Nation              ",null,"Red Lake Chippewa",null,"Puyallup","Colusa",null,null,"Zuni","Reno-Sparks"]
[null,null,null,null,null,null,null,"Village Of Aniak",null,"Poarch Band of Creek Indians ",null,"Saginaw Chippewa",null,"Quileute","Cortina",null,null,null,"Salt River"]
[null,null,null,null,null,null,null,"Anvik Village",null,"Rappahannock Tribe, Inc.    ",null,"Sault Ste. Marie",null,"Sb-Quinault","Coyote Valley",null,null,null,"San Carlos Apache"]
[null,null,null,null,null,null,null,"Arctic Village",null,"Saint Regis Mohawk Tribe ",null,"Shakopee",null,"Salish & Kootenai","Cuyapaipe",null,null,null,"San Juan Paiute"]
[null,"PRIVACY ACT STATEMENT",null,null,null,null,null,"Native Village Of Atka",null,"Seminole Tribe of Florida ",null,"Sokaogon",null,"Samish","Dry Creek",null,null,null,"Skull Valley"]
[null,"25 CFR 265 and 25 U.S.C. 13 authorize the collection of this information.  This information is covered by the system of record notice “Indian Housing Improvement Program, Interior, BIA-10.”  The primary use of this information is to determine eligibility for assistance under the Housing Improvement Program.  The records contained therein may only be disclosed in accordance with the routine uses and may not otherwise be disclosed by any means of communication to any person, or to another agency, except pursuant to a written request by, or with prior written consent of the individual to whom the record pertains.  If the BIA uses the information furnished on this form for purposes other than those indicated above, it may provide you with an additional statement reflecting those purposes.  Executive Order 9397 authorizes the collection of your Social Security number.  Furnishing the information is voluntary but failure to do so may result in disapproval of your application.  ",null,null,null,null,null,"Village Of Atmautluak",null,"Seneca Nation of Indians ",null,null,null,null,null,null,null,null,"South Fork"]
[null,null,null,null,null,null,null,"Beaver Village",null,"Shinnecock Indian Nation ",null,"St Croix",null,"Sauk-Suiattle","Elem (Sulphur Bank)",null,null,null,"Summitt Lake"]
[null,null,null,null,null,null,null,"Native Village Of Belkofski",null,"Tonawanda Band of Seneca Indians                        ",null,"Stockbridge Munsee",null,"Shoalwater Bay","Elk Valley",null,null,null,"Tohono O'odham"]
[null,null,null,null,null,null,null,"Orutsararmuit Native Village",null,"Tunica/Biloxi Indians of Louisiana                     ",null,"Upper Sioux",null,"Shoshone-Bannock","Enterprise",null,null,null,"Tonto Apache"]
[null,null,null,null,null,null,null,"Village Of Bill Moore's Slough",null,"Tuscarora Nation    ",null,"White Earth",null,"Siletz","Fort Bidwell",null,null,null,"Uintah & Ouray"]
[null,null,null,null,null,null,null,"Birch Creek Tribe",null,"Upper Mattaponi Tribe ",null,null,null,"Skokomish","Fort Independence",null,null,null,"Walker River Paiute"]
[null,null,null,null,null,null,null,"Native Village Of Brevig Mission",null,"Wampanoag Tribe of Gay Head (Aquinnah)",null,null,null,"Snoqualmie","Greenville",null,null,null,"Washoe"]
[null,"PAPERWORK REDUCTION ACT STATEMENT",null,null,null,null,null,"Native Village Of Buckland",null,null,null,null,null,"Spokane","Grindstone",null,null,null,"Wells"]
[null,"This information is being collected to select eligible families or individuals to participate in the Housing Improvement Program.  Response to this request is required to obtain a benefit in accordance with 25 CFR 256.  You are not required to respond to this collection of information unless it displays a currently valid OMB control number.  This information will be used to determine the eligibility and the ranking of the applicant.  Public reporting burden for this form is estimated to average 1 hour per response, including the time for reviewing instructions, gathering and maintaining data, and completing and reviewing the form.  Direct comments regarding the burden estimate or any other aspect of this form to Information Collection Clearance Officer – Indian Affairs, 1849 C Street, NW, MS-4141, Washington, DC 20240.",null,null,null,null,null,"Native Village Of Cantwell",null,null,null,null,null,"Squaxin Island","Guidiville",null,null,null,"White Mountain Apache"]
[null,null,null,null,null,null,null,"Chalkyitsik Village",null,null,null,null,null,"Stillaguamish","Sb-Hoopa",null,null,null,"Yavapai-Apache"]
[null,null,null,null,null,null,null,"Village Of Chefornak",null,null,null,null,null,"Suquamish","Hopland",null,null,null,"Yavapai-Prescott"]
[null,null,null,null,null,null,null,"Chevak Native Village",null,null,null,null,null,"Swinomish","Inaja-Cosmit",null,null,null,"Yerington Paiute"]
[null,null,null,null,null,null,null,"Chickaloon Native Village",null,null,null,null,null,"Tulalip","Ione",null,null,null,"Yomba"]
[null,null,null,null,null,null,null,"Native Village Of Chignik",null,null,null,null,null,"Umatilla","Jackson"]
[null,null,null,null,null,null,null,"Native Village Of Chignik Lagoon",null,null,null,null,null,"Upper Skagit","Jamul"]
[null,null,null,null,null,null,null,"Chignik Lake Village",null,null,null,null,null,"Warm Springs","Karuk"]
[null,null,null,null,null,null,null,"Village Of Crooked Creek",null,null,null,null,null,"Yakama","La Jolla"]
[null,null,null,null,null,null,null,"Native Village Of Deering",null,null,null,null,null,null,"Mooretown"]
[null,null,null,null,null,null,null,"Curyung Tribal Council",null,null,null,null,null,null,"Morongo"]
[null,null,null,null,null,null,null,"Village Of Dot Lake",null,null,null,null,null,null,"North Fork"]
[null,null,null,null,null,null,null,"Douglas Indian Association",null,null,null,null,null,null,"Pala"]
[null,null,null,null,null,null,null,"Native Village Of Eagle",null,null,null,null,null,null,"Paskenta"]
[null,null,null,null,null,null,null,"Native Village Of Eek",null,null,null,null,null,null,"Pauma"]
[null,null,null,null,null,null,null,"Egegik Village",null,null,null,null,null,null,"Pechanga"]
[null,null,null,null,null,null,null,"Eklutna Native Village",null,null,null,null,null,null,"Picayune"]
[null,null,null,null,null,null,null,"Native Village Of Ekuk",null,null,null,null,null,null,"Pinoleville"]
[null,null,null,null,null,null,null,"Ekwok Village",null,null,null,null,null,null,"Pit River"]
[null,null,null,null,null,null,null,"Native Village Of Elim",null,null,null,null,null,null,"Potter Valley"]
[null,null,null,null,null,null,null,"Emmonak Village",null,null,null,null,null,null,"Quartz Valley"]
[null,null,null,null,null,null,null,"Native Village Of Nanwalek",null,null,null,null,null,null,"Ramona"]
[null,null,null,null,null,null,null,"Evansville Village",null,null,null,null,null,null,"Redding"]
[null,null,null,null,null,null,null,"Native Village Of Eyak",null,null,null,null,null,null,"Redwood Valley"]
[null,null,null,null,null,null,null,"Native Village Of False Pass",null,null,null,null,null,null,"Resighini"]
[null,null,null,null,null,null,null,"Native Village Of Fort Yukon",null,null,null,null,null,null,"Rincon"]
[null,null,null,null,null,null,null,"Native Village Of Gakona",null,null,null,null,null,null,"Robinson"]
[null,null,null,null,null,null,null,"Native Village Of Gambell",null,null,null,null,null,null,"Rohnerville"]
[null,null,null,null,null,null,null,"Native Village Of Georgetown",null,null,null,null,null,null,"Round Valley"]
[null,null,null,null,null,null,null,"Chinik Eskimo Community",null,null,null,null,null,null,"Rumsey"]
[null,null,null,null,null,null,null,"Organized Village Of Grayling",null,null,null,null,null,null,"San Manuel"]
[null,null,null,null,null,null,null,"Gulkana Village",null,null,null,null,null,null,"San Pasqual"]
[null,null,null,null,null,null,null,"Chilkoot Indian Association",null,null,null,null,null,null,"Santa Rosa"]
[null,null,null,null,null,null,null,"Native Village Of Hamilton",null,null,null,null,null,null,"Santa Rosa Rancheria"]
[null,null,null,null,null,null,null,"Holy Cross Village",null,null,null,null,null,null,"Santa Ynez"]
[null,null,null,null,null,null,null,"Hoonah Indian Association",null,null,null,null,null,null,"Santa Ysabel"]
[null,null,null,null,null,null,null,"Native Village Of Hooper Bay",null,null,null,null,null,null,"Scotts Valley"]
[null,null,null,null,null,null,null,"Hughes Village",null,null,null,null,null,null,"Sheep Ranch"]
[null,null,null,null,null,null,null,"Huslia Village",null,null,null,null,null,null,"Sherwood"]
[null,null,null,null,null,null,null,"Hydaburg Cooperative Association",null,null,null,null,null,null,"Shingle Springs"]
[null,null,null,null,null,null,null,"Igiugig Village",null,null,null,null,null,null,"Smith River"]
[null,null,null,null,null,null,null,"Village Of Iliamna",null,null,null,null,null,null,"Soboba"]
[null,null,null,null,null,null,null,"Native Village Of Diomede",null,null,null,null,null,null,"Stewarts Points"]
[null,null,null,null,null,null,null,"Ivanoff Bay Village",null,null,null,null,null,null,"Susanville"]
[null,null,null,null,null,null,null,"Organized Village Of Kake",null,null,null,null,null,null,"Sycuan"]
[null,null,null,null,null,null,null,"Kaktovik Village",null,null,null,null,null,null,"Table Bluff"]
[null,null,null,null,null,null,null,"Village Of Kalskag",null,null,null,null,null,null,"Table Mountain"]
[null,null,null,null,null,null,null,"Village Of Kaltag",null,null,null,null,null,null,"Tejon Tribe"]
[null,null,null,null,null,null,null,"Native Village Of Karluk",null,null,null,null,null,null,"Timbi-Sha"]
[null,null,null,null,null,null,null,"Organized Village Of Kasaan",null,null,null,null,null,null,"Torres-Martin"]
[null,null,null,null,null,null,null,"Native Village Of Kasigluk",null,null,null,null,null,null,"Trinidad"]
[null,null,null,null,null,null,null,"Kenaitze Indian Tribe",null,null,null,null,null,null,"Tule River"]
[null,null,null,null,null,null,null,"Ketchikan Indian Corporation",null,null,null,null,null,null,"Tuolumne"]
[null,null,null,null,null,null,null,"Native Village Of Kiana",null,null,null,null,null,null,"Upper Lake"]
[null,null,null,null,null,null,null,"Agdaagux Tribe Of King Cove",null,null,null,null,null,null,"Viejas"]
[null,null,null,null,null,null,null,"King Island Native Community",null,null,null,null,null,null,"Wilton Tribe"]
[null,null,null,null,null,null,null,"Native Village Of Kipnuk",null,null,null,null,null,null,"Yurok"]
[null,null,null,null,null,null,null,"Native Village Of Kivalina"]
[null,null,null,null,null,null,null,"Klawock Cooperative Association"]
[null,null,null,null,null,null,null,"Chilkat Indian Village"]
[null,null,null,null,null,null,null,"Knik Village"]
[null,null,null,null,null,null,null,"Native Village Of Kobuk"]
[null,null,null,null,null,null,null,"Kokhanok Village"]
[null,null,null,null,null,null,null,"New Koliganek Village Council"]
[null,null,null,null,null,null,null,"Native Village Of Kongiganak"]
[null,null,null,null,null,null,null,"Village Of Kotlik"]
[null,null,null,null,null,null,null,"Native Village Of Kotzebue"]
[null,null,null,null,null,null,null,"Native Village Of Koyuk"]
[null,null,null,null,null,null,null,"Koyukuk Native Village"]
[null,null,null,null,null,null,null,"Organized Village Of Kwethluk"]
[null,null,null,null,null,null,null,"Native Village Of Kwigillingok"]
[null,null,null,null,null,null,null,"Native Village Of Larsen Bay"]
[null,null,null,null,null,null,null,"Levelock Village"]
[null,null,null,null,null,null,null,"Lime Village"]
[null,null,null,null,null,null,null,"Galena Village"]
[null,null,null,null,null,null,null,"Village Of Lower Kalskag"]
[null,null,null,null,null,null,null,"Manley Hot Springs Village"]
[null,null,null,null,null,null,null,"Manokotak Village"]
[null,null,null,null,null,null,null,"Native Village Of Marshall"]
[null,null,null,null,null,null,null,"Native Village Of Mary's Igloo"]
[null,null,null,null,null,null,null,"Mcgrath Native Village"]
[null,null,null,null,null,null,null,"Native Village Of Mekoryuk"]
[null,null,null,null,null,null,null,"Mentasta Traditional Council"]
[null,null,null,null,null,null,null,"Native Village Of Minto"]
[null,null,null,null,null,null,null,"Asa'carsarmiut Tribe"]
[null,null,null,null,null,null,null,"Pauloff Harbor Village"]
[null,null,null,null,null,null,null,"Native Village Of Goodnews Bay"]
[null,null,null,null,null,null,null,"Native Village Of Naknek"]
[null,null,null,null,null,null,null,"Native Village Of Napamite"]
[null,null,null,null,null,null,null,"Native Village Of Napakiak"]
[null,null,null,null,null,null,null,"Native Village Of Napaskiak"]
[null,null,null,null,null,null,null,"Native Village Of Nelson Lagoon"]
[null,null,null,null,null,null,null,"Nenana Native Association"]
[null,null,null,null,null,null,null,"New Stuyahok Village"]
[null,null,null,null,null,null,null,"Newhalen Village"]
[null,null,null,null,null,null,null,"Newtok Village"]
[null,null,null,null,null,null,null,"Native Village Of Nightmute"]
[null,null,null,null,null,null,null,"Nikolai Village"]
[null,null,null,null,null,null,null,"Native Village Of Nikolski"]
[null,null,null,null,null,null,null,"Ninilchik Village"]
[null,null,null,null,null,null,null,"Native Village Of Noatak"]
[null,null,null,null,null,null,null,"Nome Eskimo Community"]
[null,null,null,null,null,null,null,"Nondalton Village"]
[null,null,null,null,null,null,null,"Native Village Of Nuiqsut"]
[null,null,null,null,null,null,null,"Noorvik Native Community"]
[null,null,null,null,null,null,null,"Northway Village"]
[null,null,null,null,null,null,null,"Nulato Village"]
[null,null,null,null,null,null,null,"Native Village Of Nunaptichuk"]
[null,null,null,null,null,null,null,"Village Of Ohogamiut"]
[null,null,null,null,null,null,null,"Village Of Old Harbor"]
[null,null,null,null,null,null,null,"Oscarville Traditional Village"]
[null,null,null,null,null,null,null,"Native Village Of Ouzinkie"]
[null,null,null,null,null,null,null,"Native Village Of Paimut"]
[null,null,null,null,null,null,null,"Pedro Bay Village"]
[null,null,null,null,null,null,null,"Native Village Of Perryville"]
[null,null,null,null,null,null,null,"Petersburg Indian Association"]
[null,null,null,null,null,null,null,"Native Village Of Pilot Point"]
[null,null,null,null,null,null,null,"Pilot Station Traditional Village"]
[null,null,null,null,null,null,null,"Native Village Of Pitka's Point"]
[null,null,null,null,null,null,null,"Platinum Traditional Village"]
[null,null,null,null,null,null,null,"Native Village Of Point Hope"]
[null,null,null,null,null,null,null,"Native Village Of Point Lay"]
[null,null,null,null,null,null,null,"Native Village Of Port Graham"]
[null,null,null,null,null,null,null,"Native Village Of Port Heiden"]
[null,null,null,null,null,null,null,"Native Village Of Port Lions"]
[null,null,null,null,null,null,null,"Portage Creek Village"]
[null,null,null,null,null,null,null,"Native Village Of Kwinhagak"]
[null,null,null,null,null,null,null,"Rampart Village"]
[null,null,null,null,null,null,null,"Village Of Red Devil"]
[null,null,null,null,null,null,null,"Native Village Of Ruby"]
[null,null,null,null,null,null,null,"Iqurmuit Traditional Council"]
[null,null,null,null,null,null,null,"Village Of Salamatoff"]
[null,null,null,null,null,null,null,"Qagan Tayagungin Tribe Of Sand Point"]
[null,null,null,null,null,null,null,"Native Village Of Savoonga"]
[null,null,null,null,null,null,null,"Village Of Saxman"]
[null,null,null,null,null,null,null,"Native Village Of Scammon Bay"]
[null,null,null,null,null,null,null,"Native Village Of Selawik"]
[null,null,null,null,null,null,null,"Seldovia Village Tribe"]
[null,null,null,null,null,null,null,"Shageluk Native Village"]
[null,null,null,null,null,null,null,"Native Village Of Shaktoolik"]
[null,null,null,null,null,null,null,"Native Village Of Sheldon's Point"]
[null,null,null,null,null,null,null,"Native Village Of Shismaref"]
[null,null,null,null,null,null,null,"Native Village Of Shungnak"]
[null,null,null,null,null,null,null,"Sitka Tribe Of Alaska"]
[null,null,null,null,null,null,null,"Skagway Village"]
[null,null,null,null,null,null,null,"Village Of Sleetmute"]
[null,null,null,null,null,null,null,"Village Of Solomon"]
[null,null,null,null,null,null,null,"South Naknek Village"]
[null,null,null,null,null,null,null,"Pribilof Island Aleut Community Of Saint George"]
[null,null,null,null,null,null,null,"Algaaciq Native Village"]
[null,null,null,null,null,null,null,"Native Village Of Saint Michael"]
[null,null,null,null,null,null,null,"Pribilof Island Aleut Community Of Saint Paul"]
[null,null,null,null,null,null,null,"Stebbins Community Association"]
[null,null,null,null,null,null,null,"Native Village Of Stevens"]
[null,null,null,null,null,null,null,"Village Of Stony River"]
[null,null,null,null,null,null,null,"Takotna Village"]
[null,null,null,null,null,null,null,"Native Village Of Tanacross"]
[null,null,null,null,null,null,null,"Native Village Of Tanana"]
[null,null,null,null,null,null,null,"Native Village Of Tatilek"]
[null,null,null,null,null,null,null,"Native Village Of Tazlina"]
[null,null,null,null,null,null,null,"Telida Village"]
[null,null,null,null,null,null,null,"Native Village Of Teller"]
[null,null,null,null,null,null,null,"Native Village Of Tetlin"]
[null,null,null,null,null,null,null,"Traditional Village Of Togiak"]
[null,null,null,null,null,null,null,"Nunakauyarmiut Tribe"]
[null,null,null,null,null,null,null,"Tuluksak Native Community"]
[null,null,null,null,null,null,null,"Native Village Of Tuntutuliak"]
[null,null,null,null,null,null,null,"Native Village Of Tununak"]
[null,null,null,null,null,null,null,"Twin Hills Village"]
[null,null,null,null,null,null,null,"Native Village Of Tyonek"]
[null,null,null,null,null,null,null,"Ugashik Village Village"]
[null,null,null,null,null,null,null,"Umkumiute Native Village"]
[null,null,null,null,null,null,null,"Native Village Of Unalakleet"]
[null,null,null,null,null,null,null,"Qawalangin Tribe Of Unalaska"]
[null,null,null,null,null,null,null,"Native Village Of Unga"]
[null,null,null,null,null,null,null,"Arctic Village"]
[null,null,null,null,null,null,null,"Village Of Wainwright"]
[null,null,null,null,null,null,null,"Native Village Of Wales"]
[null,null,null,null,null,null,null,"Native Village Of White Mountain"]
[null,null,null,null,null,null,null,"Lesnoi Village"]
[null,null,null,null,null,null,null,"Wrangell Cooperative Association"]
[null,null,null,null,null,null,null,"Yakutat Tlingit Tribe"]
[null,null,null,null,null,null,null,"King Salmon Tribe"]
[null,null,null,null,null,null,null,"Shoonaq Tribe Of Kodiak"]
[null,null,null,null,null,null,null,"Native Village Of Chanega"]
[null,null,null,null,null,null,null,"Kaguyak Village"]
[null,null,null,null,null,null,null,"Native Village Of Kanatak",null,null,null,null,null,{"$f":"COUNTIF(N1:N223,\"*\")","v":45}]
[null,null,null,null,null,null,null,"Healy Lake Village",null,null,null,null,null,null,{"$f":"COUNTIF(O1:O224,\"*\")","v":93}]
[null,null,null,null,null,null,null,"Native Village Of Chuathbaluk"]
[null,null,null,null,null,null,null,"Village Of Venetie"]
[null,null,null,null,null,null,null,{"$f":"COUNTIF(H2:H227,\"*\")","v":226}]
[null,null,null,null,null,null,null,"EASTERN OKLAHOMA"]
[null,null,null,null,null,null,null,"Chickasaw"]
[null,null,null,null,null,null,null,"Choctaw",null,null,{"$f":"COUNTIF(K1:K230,\"*\")","v":17},null,{"$f":"COUNTIF(M1:M230,\"*\")","v":2},null,null,null,null,{"$f":"COUNTIF(R1:R230,\"*\")","v":25},{"$f":"COUNTIF(S1:S230,\"*\")","v":42}]
[null,null,null,null,null,null,null,"Creek",{"$f":"COUNTIF(I1:I231,\"*\")","v":15},null,null,{"$f":"COUNTIF(L1:L231,\"*\")","v":33}]
[null,null,null,null,null,null,null,"Eastern Shawnee",null,{"$f":"COUNTIF(J1:J232,\"*\")","v":36},null,null,null,null,null,null,{"$f":"COUNTIF(Q1:Q232,\"*\")","v":24}]
[null,null,null,null,null,null,null,"Pleasnat Point Passamaquoddy",null,null,null,null,null,null,null,{"$f":"COUNTIF(P1:P233,\"*\")","v":10}]
[null,null,null,null,null,null,null,"Miami"]
[null,null,null,null,null,null,null,"Modoc"]
[null,null,null,null,null,null,null,"Osage"]
[null,null,null,null,null,null,null,"Ottawa"]
[null,null,null,null,null,null,null,"Peoria"]
[null,null,null,null,null,null,null,"Quapaw"]
[null,null,null,null,null,null,null,"Seminole"]
[null,null,null,null,null,null,null,"Seneca-Cayuga"]
[null,null,null,null,null,null,null,"Thlopthlocco"]
[null,null,null,null,null,null,null,"Wyandotte"]
[]
[null,null,null,null,null,null,null,"EASTERN"]
[null,null,null,null,null,null,null,"Aroostook Band of Micmacs "]
[null,null,null,null,null,null,null,"Catawba Indian Tribe        "]
[null,null,null,null,null,null,null,"Cayuga Nation         "]
[null,null,null,null,null,null,null,"Chickahominy Indian Tribe   "]
[null,null,null,null,null,null,null,"Chickahominy Indians - Eastern Division                        "]
[null,null,null,null,null,null,null,"Chitimacha Tribe of Louisiana "]
[null,null,null,null,null,null,null,"Coushatta Indian Tribe of Louisiana                           "]
[null,null,null,null,null,null,null,"Eastern Band of Cherokee Indians "]
[null,null,null,null,null,null,null,"Houlton Band of Maliseet Indians                                   "]
[null,null,null,null,null,null,null,"Jena Band of Choctaw Indians "]
[null,null,null,null,null,null,null,"Mashantucket Pequot Tribe  "]
[null,null,null,null,null,null,null,"Mashpee Wampanoag Tribe   "]
[null,null,null,null,null,null,null,"Miccosukee Tribe           "]
[null,null,null,null,null,null,null,"Mississippi Band of Choctaw Indians"]
[null,null,null,null,null,null,null,"Mohegan Indian Tribe    "]
[null,null,null,null,null,null,null,"Monacan Indian Nation "]
[null,null,null,null,null,null,null,"Nansemond Indian Tribe "]
[null,null,null,null,null,null,null,"Narragansett Indian Tribe  "]
[null,null,null,null,null,null,null,"Oneida Indian Nation    "]
[null,null,null,null,null,null,null,"Onondaga Indian Nation "]
[null,null,null,null,null,null,null,"Pamunkey Tribe of Virginia "]
[null,null,null,null,null,null,null,"Passamaquoddy Tribe – Indian Township             "]
[null,null,null,null,null,null,null,"Passamaquoddy Tribe – Pleasant Point                               "]
[null,null,null,null,null,null,null,"Penobscot Nation              "]
[null,null,null,null,null,null,null,"Poarch Band of Creek Indians "]
[null,null,null,null,null,null,null,"Rappahannock Tribe, Inc.    "]
[null,null,null,null,null,null,null,"Saint Regis Mohawk Tribe "]
[null,null,null,null,null,null,null,"Seminole Tribe of Florida "]
[null,null,null,null,null,null,null,"Seneca Nation of Indians "]
[null,null,null,null,null,null,null,"Shinnecock Indian Nation "]
[null,null,null,null,null,null,null,"Tonawanda Band of Seneca Indians                        "]
[null,null,null,null,null,null,null,"Tunica/Biloxi Indians of Louisiana                     "]
[null,null,null,null,null,null,null,"Tuscarora Nation    "]
[null,null,null,null,null,null,null,"Upper Mattaponi Tribe "]
[null,null,null,null,null,null,null,"Wampanoag Tribe of Gay Head (Aquinnah)"]
[]
[null,null,null,null,null,null,null,"GREAT PLAINS"]
[null,null,null,null,null,null,null,"Crow Creek"]
[null,null,null,null,null,null,null,"Flandreau"]
[null,null,null,null,null,null,null,"Fort Berthold"]
[null,null,null,null,null,null,null,"Fort Totten"]
[null,null,null,null,null,null,null,"Lower Brule"]
[null,null,null,null,null,null,null,"Oglala Sioux Pr"]
[null,null,null,null,null,null,null,"Omaha"]
[null,null,null,null,null,null,null,"Ponca"]
[null,null,null,null,null,null,null,"Rosebud Sioux"]
[null,null,null,null,null,null,null,"Santee Sioux"]
[null,null,null,null,null,null,null,"Sisseton-Wahpeton"]
[null,null,null,null,null,null,null,"Standing Rock"]
[null,null,null,null,null,null,null,"Trenton"]
[null,null,null,null,null,null,null,"Turtle Mountain"]
[null,null,null,null,null,null,null,"Winnebago"]
[null,null,null,null,null,null,null,"Yankton"]
[]
[null,null,null,null,null,null,null,"MIDWEST"]
[null,null,null,null,null,null,null,"Bay Mills"]
[null,null,null,null,null,null,null,"Bois Forte"]
[null,null,null,null,null,null,null,"Fon Du Lac"]
[null,null,null,null,null,null,null,"Forest County"]
[null,null,null,null,null,null,null,"Grand Portage"]
[null,null,null,null,null,null,null,"Grand Traverse"]
[null,null,null,null,null,null,null,"Hannahville"]
[null,null,null,null,null,null,null,"Ho-Chunk (Wis. Potawatomi)"]
[null,null,null,null,null,null,null,"Huron Band of Potawatomi"]
[null,null,null,null,null,null,null,"Keweenaw Bay"]
[null,null,null,null,null,null,null,"Lac Courte Oreilles"]
[null,null,null,null,null,null,null,"Lac Du Flambeau"]
[null,null,null,null,null,null,null,"Lac Vieux Desert"]
[null,null,null,null,null,null,null,"Leech Lake"]
[null,null,null,null,null,null,null,"Little River Ottawa"]
[null,null,null,null,null,null,null,"Minominee"]
[null,null,null,null,null,null,null,"Mille Lacs Ojibwe"]
[null,null,null,null,null,null,null,"Oneida Tribe "]
[null,null,null,null,null,null,null,"Odawa, Little Traverse"]
[null,null,null,null,null,null,null,"Pokagon Band Potawatomi"]
[null,null,null,null,null,null,null,"Prairie Island"]
[null,null,null,null,null,null,null,"Red Cliff"]
[null,null,null,null,null,null,null,"Red Lake Chippewa"]
[null,null,null,null,null,null,null,"Saginaw Chippewa"]
[null,null,null,null,null,null,null,"Sault Ste. Marie"]
[null,null,null,null,null,null,null,"Shakopee"]
[null,null,null,null,null,null,null,"Sokaogon"]
[null,null,null,null,null,null,null,"St Croix"]
[null,null,null,null,null,null,null,"Stockbridge Munsee"]
[null,null,null,null,null,null,null,"Upper Sioux"]
[null,null,null,null,null,null,null,"White Earth"]
[]
[null,null,null,null,null,null,null,"NAVAJO"]
[null,null,null,null,null,null,null,"Navajo Nation"]
[]
[null,null,null,null,null,null,null,"NORTHWEST"]
[null,null,null,null,null,null,null,"Chehalis"]
[null,null,null,null,null,null,null,"Coeur D'alene"]
[null,null,null,null,null,null,null,"Colville"]
[null,null,null,null,null,null,null,"Coos Bay"]
[null,null,null,null,null,null,null,"Coquille"]
[null,null,null,null,null,null,null,"Cow Creek"]
[null,null,null,null,null,null,null,"Cowlitz"]
[null,null,null,null,null,null,null,"Grand Ronde"]
[null,null,null,null,null,null,null,"Hoh"]
[null,null,null,null,null,null,null,"Sb-Jamestown S'kallum"]
[null,null,null,null,null,null,null,"Kalispel"]
[null,null,null,null,null,null,null,"Klamath"]
[null,null,null,null,null,null,null,"Kootenai"]
[null,null,null,null,null,null,null,"Lower Elwha"]
[null,null,null,null,null,null,null,"Sb-Lummi"]
[null,null,null,null,null,null,null,"Makah"]
[null,null,null,null,null,null,null,"Metlakatla"]
[null,null,null,null,null,null,null,"Muckleshoot"]
[null,null,null,null,null,null,null,"Nez Perce"]
[null,null,null,null,null,null,null,"Nisqually"]
[null,null,null,null,null,null,null,"Nooksack"]
[null,null,null,null,null,null,null,"Nw Band Shoshoni"]
[null,null,null,null,null,null,null,"Port Gamble"]
[null,null,null,null,null,null,null,"Puyallup"]
[null,null,null,null,null,null,null,"Quileute"]
[null,null,null,null,null,null,null,"Sb-Quinault"]
[null,null,null,null,null,null,null,"Salish & Kootenai"]
[null,null,null,null,null,null,null,"Samish"]
[null,null,null,null,null,null,null,"Sauk-Suiattle"]
[null,null,null,null,null,null,null,"Shoalwater Bay"]
[null,null,null,null,null,null,null,"Shoshone-Bannock"]
[null,null,null,null,null,null,null,"Siletz"]
[null,null,null,null,null,null,null,"Skokomish"]
[null,null,null,null,null,null,null,"Snoqualmie"]
[null,null,null,null,null,null,null,"Spokane"]
[null,null,null,null,null,null,null,"Squaxin Island"]
[null,null,null,null,null,null,null,"Stillaguamish"]
[null,null,null,null,null,null,null,"Suquamish"]
[null,null,null,null,null,null,null,"Swinomish"]
[null,null,null,null,null,null,null,"Tulalip"]
[null,null,null,null,null,null,null,"Umatilla"]
[null,null,null,null,null,null,null,"Upper Skagit"]
[null,null,null,null,null,null,null,"Warm Springs"]
[null,null,null,null,null,null,null,"Yakama"]
[]
[null,null,null,null,null,null,null,"PACIFIC"]
[null,null,null,null,null,null,null,"Agua Caliente"]
[null,null,null,null,null,null,null,"Alturas"]
[null,null,null,null,null,null,null,"Auburn"]
[null,null,null,null,null,null,null,"Augustine"]
[null,null,null,null,null,null,null,"Barona"]
[null,null,null,null,null,null,null,"Benton"]
[null,null,null,null,null,null,null,"Berry Creek"]
[null,null,null,null,null,null,null,"Big Lagoon"]
[null,null,null,null,null,null,null,"Big Pine"]
[null,null,null,null,null,null,null,"Big Sandy"]
[null,null,null,null,null,null,null,"Big Valley"]
[null,null,null,null,null,null,null,"Bishop"]
[null,null,null,null,null,null,null,"Blue Lake"]
[null,null,null,null,null,null,null,"Bridgeport"]
[null,null,null,null,null,null,null,"Buena Vista"]
[null,null,null,null,null,null,null,"Cabazon"]
[null,null,null,null,null,null,null,"Cahuilla"]
[null,null,null,null,null,null,null,"Campo"]
[null,null,null,null,null,null,null,"Cedarville"]
[null,null,null,null,null,null,null,"Chicken Ranch"]
[null,null,null,null,null,null,null,"Chico"]
[null,null,null,null,null,null,null,"Cloverdale"]
[null,null,null,null,null,null,null,"Cold Springs"]
[null,null,null,null,null,null,null,"Colusa"]
[null,null,null,null,null,null,null,"Cortina"]
[null,null,null,null,null,null,null,"Coyote Valley"]
[null,null,null,null,null,null,null,"Cuyapaipe"]
[null,null,null,null,null,null,null,"Dry Creek"]
[null,null,null,null,null,null,null,"Elem (Sulphur Bank)"]
[null,null,null,null,null,null,null,"Elk Valley"]
[null,null,null,null,null,null,null,"Enterprise"]
[null,null,null,null,null,null,null,"Fort Bidwell"]
[null,null,null,null,null,null,null,"Fort Independence"]
[null,null,null,null,null,null,null,"Greenville"]
[null,null,null,null,null,null,null,"Grindstone"]
[null,null,null,null,null,null,null,"Guidiville"]
[null,null,null,null,null,null,null,"Sb-Hoopa"]
[null,null,null,null,null,null,null,"Hopland"]
[null,null,null,null,null,null,null,"Inaja-Cosmit"]
[null,null,null,null,null,null,null,"Ione"]
[null,null,null,null,null,null,null,"Jackson"]
[null,null,null,null,null,null,null,"Jamul"]
[null,null,null,null,null,null,null,"Karuk"]
[null,null,null,null,null,null,null,"La Jolla"]
[null,null,null,null,null,null,null,"La Posta"]
[null,null,null,null,null,null,null,"Laytonville"]
[null,null,null,null,null,null,null,"Lone Pine"]
[null,null,null,null,null,null,null,"Los Coyotes"]
[null,null,null,null,null,null,null,"Lytton"]
[null,null,null,null,null,null,null,"Manchester Point"]
[null,null,null,null,null,null,null,"Manzanita"]
[null,null,null,null,null,null,null,"Mesa Grande"]
[null,null,null,null,null,null,null,"Middletown"]
[null,null,null,null,null,null,null,"Mooretown"]
[null,null,null,null,null,null,null,"Morongo"]
[null,null,null,null,null,null,null,"North Fork"]
[null,null,null,null,null,null,null,"Pala"]
[null,null,null,null,null,null,null,"Paskenta"]
[null,null,null,null,null,null,null,"Pauma"]
[null,null,null,null,null,null,null,"Pechanga"]
[null,null,null,null,null,null,null,"Picayune"]
[null,null,null,null,null,null,null,"Pinoleville"]
[null,null,null,null,null,null,null,"Pit River"]
[null,null,null,null,null,null,null,"Potter Valley"]
[null,null,null,null,null,null,null,"Quartz Valley"]
[null,null,null,null,null,null,null,"Ramona"]
[null,null,null,null,null,null,null,"Redding"]
[null,null,null,null,null,null,null,"Redwood Valley"]
[null,null,null,null,null,null,null,"Resighini"]
[null,null,null,null,null,null,null,"Rincon"]
[null,null,null,null,null,null,null,"Robinson"]
[null,null,null,null,null,null,null,"Rohnerville"]
[null,null,null,null,null,null,null,"Round Valley"]
[null,null,null,null,null,null,null,"Rumsey"]
[null,null,null,null,null,null,null,"San Manuel"]
[null,null,null,null,null,null,null,"San Pasqual"]
[null,null,null,null,null,null,null,"San Rosa"]
[null,null,null,null,null,null,null,"Santa Rosa Rancheria"]
[null,null,null,null,null,null,null,"Santa Ynez"]
[null,null,null,null,null,null,null,"Santa Ysabel"]
[null,null,null,null,null,null,null,"Scotts Valley"]
[null,null,null,null,null,null,null,"Sheep Ranch"]
[null,null,null,null,null,null,null,"Sherwood"]
[null,null,null,null,null,null,null,"Shingle Springs"]
[null,null,null,null,null,null,null,"Smith River"]
[null,null,null,null,null,null,null,"Soboba"]
[null,null,null,null,null,null,null,"Stewarts Points"]
[null,null,null,null,null,null,null,"Susanville"]
[null,null,null,null,null,null,null,"Sycuan"]
[null,null,null,null,null,null,null,"Table Bluff"]
[null,null,null,null,null,null,null,"Table Mountain"]
[null,null,null,null,null,null,null,"Tejon Tribe"]
[null,null,null,null,null,null,null,"Timbi-Sha"]
[null,null,null,null,null,null,null,"Torres-Martin"]
[null,null,null,null,null,null,null,"Trinidad"]
[null,null,null,null,null,null,null,"Tule River"]
[null,null,null,null,null,null,null,"Tuolumne"]
[null,null,null,null,null,null,null,"Upper Lake"]
[null,null,null,null,null,null,null,"Viejas"]
[null,null,null,null,null,null,null,"Yurok"]
[null,null,null,null,null,null,null,"Wilton Tribe"]
[]
[null,null,null,null,null,null,null,"ROCKY MOUNTAIN"]
[null,null,null,null,null,null,null,"Crow"]
[null,null,null,null,null,null,null,"Blackfeet"]
[null,null,null,null,null,null,null,"Fort Belknap"]
[null,null,null,null,null,null,null,"Fort Peck"]
[null,null,null,null,null,null,null,"Little Shell"]
[null,null,null,null,null,null,null,"Northern Cheyenne"]
[null,null,null,null,null,null,null,"Rocky Boy's"]
[null,null,null,null,null,null,null,"Northern Arapaho"]
[null,null,null,null,null,null,null,"Shoshone"]
[]
[]
[null,null,null,null,null,null,null,"SOUTHERN PLAINS"]
[null,null,null,null,null,null,null,"Alabama-Coushatta"]
[null,null,null,null,null,null,null,"Apache of Oklahoma"]
[null,null,null,null,null,null,null,"Caddo"]
[null,null,null,null,null,null,null,"Cheyenne & Arapaho"]
[null,null,null,null,null,null,null,"Citizen Potawatomi"]
[null,null,null,null,null,null,null,"Comanche Nation"]
[null,null,null,null,null,null,null,"Delaware"]
[null,null,null,null,null,null,null,"Fort Sill Apache"]
[null,null,null,null,null,null,null,"Iowa of Kansas"]
[null,null,null,null,null,null,null,"Iowa of Oklahoma"]
[null,null,null,null,null,null,null,"Kaw of Oklahoma"]
[null,null,null,null,null,null,null,"Kickapoo Tribe of Kansas"]
[null,null,null,null,null,null,null,"Kickapoo Tribe of Oklahoma"]
[null,null,null,null,null,null,null,"Kiowa of Oklahoma"]
[null,null,null,null,null,null,null,"Otoe-Missouria"]
[null,null,null,null,null,null,null,"Pawnee"]
[null,null,null,null,null,null,null,"Ponca"]
[null,null,null,null,null,null,null,"Prairie Potawatomi"]
[null,null,null,null,null,null,null,"Sac & Fox - Missouri"]
[null,null,null,null,null,null,null,"Sac & Fox Nation - Oklahoma"]
[null,null,null,null,null,null,null,"Wichita"]
[]
[null,null,null,null,null,null,null,"SOUTHWEST"]
[null,null,null,null,null,null,null,"Cochiti"]
[null,null,null,null,null,null,null,"Isleta"]
[null,null,null,null,null,null,null,"Jemez"]
[null,null,null,null,null,null,null,"Jicarilla"]
[null,null,null,null,null,null,null,"Laguna"]
[null,null,null,null,null,null,null,"Mescalero"]
[null,null,null,null,null,null,null,"Nambe"]
[null,null,null,null,null,null,null,"Picuris"]
[null,null,null,null,null,null,null,"Pojoaque"]
[null,null,null,null,null,null,null,"Ramah"]
[null,null,null,null,null,null,null,"San Felipe"]
[null,null,null,null,null,null,null,"San Ildfonso"]
[null,null,null,null,null,null,null,"San Juan"]
[null,null,null,null,null,null,null,"Sandia"]
[null,null,null,null,null,null,null,"Santa Ana"]
[null,null,null,null,null,null,null,"Santa Clara"]
[null,null,null,null,null,null,null,"Santa Domingo"]
[null,null,null,null,null,null,null,"Southern Ute"]
[null,null,null,null,null,null,null,"Taos"]
[null,null,null,null,null,null,null,"Tesuque"]
[null,null,null,null,null,null,null,"Ute Mountain"]
[null,null,null,null,null,null,null,"Ysleta Del Sur"]
[null,null,null,null,null,null,null,"Zia"]
[null,null,null,null,null,null,null,"Zuni"]
[]
[null,null,null,null,null,null,null,"WESTERN"]
[null,null,null,null,null,null,null,"Battle Mountain"]
[null,null,null,null,null,null,null,"Cocopah"]
[null,null,null,null,null,null,null,"Colorado River"]
[null,null,null,null,null,null,null,"Duck Valley"]
[null,null,null,null,null,null,null,"Duckwater"]
[null,null,null,null,null,null,null,"Elko"]
[null,null,null,null,null,null,null,"Ely"]
[null,null,null,null,null,null,null,"Fallon"]
[null,null,null,null,null,null,null,"Fort Mcdermitt"]
[null,null,null,null,null,null,null,"Fort Mcdowell"]
[null,null,null,null,null,null,null,"Gila River"]
[null,null,null,null,null,null,null,"Goshute Business Council"]
[null,null,null,null,null,null,null,"Havasupai"]
[null,null,null,null,null,null,null,"Hopi Tribe"]
[null,null,null,null,null,null,null,"Hopi Tribe (Hpl)"]
[null,null,null,null,null,null,null,"Hualapai"]
[null,null,null,null,null,null,null,"Kabaib Paiute"]
[null,null,null,null,null,null,null,"Lovelock"]
[null,null,null,null,null,null,null,"Moapa"]
[null,null,null,null,null,null,null,"Pascua Yaqui"]
[null,null,null,null,null,null,null,"Pyramid Lake"]
[null,null,null,null,null,null,null,"Quechen"]
[null,null,null,null,null,null,null,"Reno-Sparks"]
[null,null,null,null,null,null,null,"Salt River"]
[null,null,null,null,null,null,null,"San Carlos Apache"]
[null,null,null,null,null,null,null,"San Juan Paiute"]
[null,null,null,null,null,null,null,"Skull Valley"]
[null,null,null,null,null,null,null,"South Fork"]
[null,null,null,null,null,null,null,"Summitt Lake"]
[null,null,null,null,null,null,null,"Tohono O'odham"]
[null,null,null,null,null,null,null,"Tonto Apache"]
[null,null,null,null,null,null,null,"Uintah & Ouray"]
[null,null,null,null,null,null,null,"Walker River Paiute"]
[null,null,null,null,null,null,null,"Washoe"]
[null,null,null,null,null,null,null,"Wells"]
[null,null,null,null,null,null,null,"White Mountain Apache"]
[null,null,null,null,null,null,null,"Yavapai-Apache"]
[null,null,null,null,null,null,null,"Yavapai-Prescott"]
[null,null,null,null,null,null,null,"Yerington Paiute"]
[null,null,null,null,null,null,null,"Yomba"]
[]
[null,null,null,null,null,null,null,{"$f":"COUNTIF(H1:H588,\"*\")","v":575}]

{"sheet":"Form","index":5,"n_rows":637,"n_cols":21,"rows_kept":637,"cut":false,"hidden":false,"merged":[[0,0,2,11],[31,1,31,6],[42,9,42,10],[41,1,41,5],[42,1,42,4],[4,1,4,2],[39,6,39,8],[35,1,35,6],[5,8,5,10],[34,1,34,7],[6,1,6,2],[39,1,39,5],[6,8,6,9],[50,0,53,11],[3,0,3,11],[29,1,29,5],[44,6,44,9],[41,9,41,10],[30,1,30,6],[33,1,33,6],[27,1,27,6],[4,4,4,10],[37,1,37,5],[37,6,37,8]]}
["                                                                                                                                    PRIVACY ACT STATEMENT                                                                                                                                                                                                                                                                   25 CFR 265 and 25 U.S.C. 13 authorize the collection of this information.  This information is covered by the system of record notice “Indian Housing Improvement Program, Interior,    BIA-10.”  The primary use of this information is to determine eligibility for assistance under the Housing Improvement Program.  The records contained therein may only be disclosed in accordance with the routine uses and may not otherwise be disclosed by any means of communication to any person, or to another agency, except pursuant to a written request by, or with prior written consent of the individual to whom the record pertains.  If the BIA uses the information furnished on this form for purposes other than those indicated above, it may provide you with an additional statement reflecting those purposes.  Executive Order 9397 authorizes the collection of your Social Security number.  Furnishing the information is voluntary but failure to do so may result in disapproval of your application.   \n"]
[]
[]
["         Region                                                                                                Tribe of Consortia                                    "]
[1,"WESTERN",null,null,"Quechen"]
[null,"District, Agency, Member Tribe of Consortia",null,null,null,null,"Fiscal Year",null,"Date of Application"]
[3,null,null,null,null,null,2024]
[]
[null,"Last Name of Applicant","First Name",null,"Suffix",null,"Enrollment #",null,"Category:"]
[4]
[null,null,null,null,"Family Size",null,"Income",null,null,null,"Pts"]
[5,"Household Income:",null,null,null,null,null,null,{"$f":"IF(B5=\"Alaska\",'Lookup Alaska'!AL5,Lookup!AL5)","v":{"$error":"#N/A"}},{"$f":"IF(I12=\"\",\"0\",I12)","v":{"$error":"#N/A"}},{"$f":"IF(G12=\"\",\"0\",J12)","v":"0"}]
[]
[6,"Aged Person:",null,null,null,{"$f":"IF(E14=0,0,(INT(YEARFRAC(TODAY(),E14,1))))","v":0},{"$f":"ROUNDDOWN(F14,0)","v":0},{"$f":"IF(F14>55,F14-55,\"0\")","v":"0"},{"$f":"IF(G14>70,\"15\",H14)","v":"0"},null,{"$f":"I14","v":"0"}]
[]
[7,"Disabled Individual:",null,null,null,null,{"$f":"IF(E16=\"Yes\",\"10\",\"0\")","v":"0"},null,{"$f":"IF(E16=\"Yes\",\"10\",\"0\")","v":"0"},{"$f":"I16","v":"0"},{"$f":"J16","v":"0"}]
[]
[8,"Dependent Children:","Under age 18",null,null,null,{"$f":"IF(E18=1,3,0)+IF(E18=2,6,0)+IF(E18=3,9,0)+IF(E18=4,12,0)+IF(E18=5,15,0)+IF(E18>5,15,0)","v":0},null,{"$f":"IF(E18=\"\",\"0\",G18)","v":"0"},{"$f":"I18","v":"0"},{"$f":"J18","v":"0"}]
[]
[9,"Homeless/ Dilapidated",null,null,null,null,{"$f":"IF(OR(E20=\"Homeless\",\"Dilapidated\"),\"Homeless\",\"5\")","v":"5"},{"$f":"IF(E20=\"Homeless\",\"5\",\"0\")","v":"0"},"Homeless",null,{"$f":"H20","v":"0"}]
[]
[10,null,null,null,null,null,{"$f":"IF(OR(E22=\"Overcrowded\",\"Dilapidated\"),\"Dilapidated\",\"5\")","v":"5"},{"$f":"IF(E20=\"Dilapidated\",\"5\",\"0\")","v":"0"},"Dilapidated",null,{"$f":"H22","v":"0"}]
[]
[11,"Overcrowded",null,null,null,null,{"$f":"IF(E24=\"Yes\",\"10\",\"\")","v":""},null,{"$f":"IF(E24=\"Yes\",\"5\",\"0\")","v":"0"},{"$f":"I24","v":"0"},{"$f":"J24","v":"0"}]
[]
[12,"Veteran",null,null,null,null,{"$f":"IF(E26=\"Yes\",\"5\",\"0\")","v":"0"},null,null,{"$f":"I26","v":0},{"$f":"G26","v":"0"}]
[]
[13,"Are you applying for DownPayment Assistance, provide a Certificate of Eligibility letter from Lender. ",null,null,null,null,null,null,null,{"$f":"IF(I28=\"YES\",25,\"0\")","v":"0"},{"$f":"J28","v":"0"}]
[]
[14,"HIP Eligibility requirements 25 CFR Part 256 effective after 12/10/15",null,null,null,null,null,null,"Subtotal",null,{"$f":"IF(K12=\"Not Eligible\",\"Not Eligible\",SUM(K12+K14+K16+K18+K20+K22+K24+K26+K28))","v":0}]
[]
[15,"You are on the waiting list and have obtained a denial letter from the Local Housing Authority.",null,null,null,null,null,null,null,{"$f":"IF(I32=\"YES\",\"Eligible\",IF(I32=\"Pending\",\"Eligible\",IF(I32=\"No\",\"Not Eligible\",\"\")))","v":""},{"$f":"J32","v":""}]
[]
[16,"You have received prior Federal Housing Assistance from the Housing Improvement Program (HIP). ",null,null,null,null,null,null,null,{"$f":"IF(I34=\"No\",\"Eligible\",IF(I34=\"Yes\",\"Not Eligible\",\"\"))","v":""},{"$f":"J34","v":""}]
[]
[17,"You have received Federal Housing Assistance from NAHASDA after 1996.",null,null,null,null,null,null,null,{"$f":"IF(I36=\"No\",\"Eligible\",IF(I36=\"Yes\",\"Not Eligible\",\"\"))","v":""},{"$f":"J36","v":""}]
[]
[18,null,null,null,null,null,"Eligibility Points",null,null,{"$f":"IF(K40=\"Not Eligible\",\"0\",SUM(K12+K14+K16+K18+K20+K22+K24+K26+K28))","v":0},{"$f":"J38","v":0}]
[]
[19,"N/A means \"Not Eligible\" for Housing Assistance under the BIA HIP program.",null,null,null,null,"Eligibility Status ",null,null,{"$f":"IF(K30=\"Not Eligible\",\"Not Eligible\",IF(K32=\"Not Eligible\",\"Not Eligible\",IF(K34=\"Not Eligible\",\"Not Eligible\",IF(K36=\"Not Eligible\",\"Not Eligible\",\"Eligible\"))))","v":"Eligible"},{"$f":"J40","v":"Eligible"}]
[]
[20,"  If known, please provide an estimated start date to renovate or build new!"]
[21,"  If known, please provide an estimated cost to renovate or build new!"]
[]
[22,"Date of Evaluation:",{"$f":"IF(B10=\"\",\"\",NOW())","v":""},null,null,null,"See instructions on printing"]
[]
[23,"Name of Evaluator:",{"$f":"IF(Profile!D10=\"\",\"\",Profile!D10)","v":""}]
[]
[24,"Contact Number:",{"$f":"IF(Profile!D12=\"\",\"\",Profile!D12)","v":""}]
[]
["                                                                                                                   PAPERWORK REDUCTION ACT STATEMENT                                                                                                                                                                                                           This information is being collected to select eligible families or individuals to participate in the Housing Improvement Program.  Response to this request is required to obtain a benefit in accordance with 25 CFR 256.  You are not required to respond to this collection of information unless it displays a currently valid OMB control number.  This information will be used to determine the eligibility and the ranking of the applicant.  Public reporting burden for this form is estimated to average 1 hour per response, including the time for reviewing instructions, gathering and maintaining data, and completing and reviewing the form.  Direct comments regarding the burden estimate or any other aspect of this form to Information Collection Clearance Officer – Indian Affairs, 1849 C Street, NW, MS-4141, Washington, DC 20240. "]
[]
[]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"A","Sr","AVCP","Association of Village Council Presidents","ALASKA"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"B","Jr","ASNA","Arctic Slope Native Association","Native Village Of Akhiok"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"C-1","III","BBNA","Bristol Bay Native Association","Akiachak Native Community"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"C-2","IV","CITC","Cook Inlet Tribal Council","Akiak Native Community"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"D",null,"CCTH","Central Council Tlingit and Haida","Native Village Of Akutan"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"FNA","Fairbanks Native Association","Village Of Alakanuk"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"ICAS","Inupiat Community of the Arctic Slope","Allakaket Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Kawerak","Kawerak","Alatna Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Maniilaq","Maniilaq","Native Village Of Aleknagik"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"TCC","Tanana Chiefs Conference","Native Village Of Ambler"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Village Of Anaktuvuk Pass"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Chinle",null,"Yupiit Of Andreafski"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Yes","Shiprock",null,"Village Of Aniak"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"No","Western",null,"Arctic Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,1,"Homeless","Native Village Of Atka"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,2,"Dilapidated","Village Of Atmautluak"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,3,"Overcrowded","Beaver Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,4,"Veteran","Native Village Of Belkofski"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Orutsararmuit Native Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Village Of Bill Moore's Slough"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Birch Creek Tribe"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Brevig Mission"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Buckland"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Cantwell"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Yes",null,null,"Chalkyitsik Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pending",null,null,"Village Of Chefornak"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"No",null,null,"Chevak Native Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Chickaloon Native Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Chignik"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Chignik Lagoon"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Chignik Lake Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Cheesh-Na Tribe"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Chitna"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Chuloonawick Native Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Circle Native Community"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Village Of Clark's Point"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pribilof Islands Aleut Communities"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Kluti-Kaah"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Council"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Craig Community Association"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Village Of Crooked Creek"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Deering"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Curyung Tribal Council"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Village Of Dot Lake"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Egegik Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Eklutna Native Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Ekuk"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Ekwok Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Elim"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Emmonak Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Nanwalek"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Evansville Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Eyak"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of False Pass"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Fort Yukon"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Gakona"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Gambell"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Georgetown"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Chinik Eskimo Community"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Organized Village Of Grayling"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Gulkana Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Chilkoot Indian Association"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Hamilton"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Holy Cross Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Hoonah Indian Association"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Hooper Bay"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Hughes Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Huslia Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Hydaburg Cooperative Association"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Igiugig Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Village Of Iliamna"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Diomede"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Ivanoff Bay Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Organized Village Of Kake"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Kaktovik Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Village Of Kalskag"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Village Of Kaltag"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Karluk"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Organized Village Of Kasaan"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Kasigluk"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Kenaitze Indian Tribe"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Ketchikan Indian Corporation"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Kiana"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Agdaagux Tribe Of King Cove"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"King Island Native Community"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Kipnuk"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Kivalina"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Klawock Cooperative Association"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Chilkat Indian Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Knik Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Kobuk"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Kokhanok Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"New Koliganek Village Council"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Kongiganak"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Village Of Kotlik"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Kotzebue"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Koyuk"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Koyukuk Native Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Organized Village Of Kwethluk"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Kwigillingok"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Larsen Bay"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Levelock Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Lime Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Galena Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Village Of Lower Kalskag"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Manley Hot Springs Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Manokotak Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Marshall"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Mary's Igloo"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Mcgrath Native Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Mekoryuk"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Mentasta Traditional Council"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Minto"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Asa'carsarmiut Tribe"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pauloff Harbor Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Goodnews Bay"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Naknek"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Napamite"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Napakiak"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Napaskiak"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Nelson Lagoon"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Nenana Native Association"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"New Stuyahok Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Newhalen Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Newtok Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Nightmute"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Nikolai Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Nikolski"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Ninilchik Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Noatak"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Nome Eskimo Community"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Nondalton Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Nuiqsut"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Noorvik Native Community"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Northway Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Nulato Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Nunaptichuk"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Village Of Ohogamiut"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Village Of Old Harbor"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Oscarville Traditional Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Ouzinkie"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Paimut"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pedro Bay Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Perryville"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Petersburg Indian Association"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Pilot Point"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pilot Station Traditional Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Pitka's Point"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Platinum Traditional Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Point Hope"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Point Lay"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Port Graham"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Port Heiden"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Port Lions"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Portage Creek Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Kwinhagak"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rampart Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Village Of Red Devil"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Ruby"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Iqurmuit Traditional Council"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Village Of Salamatoff"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Qagan Tayagungin Tribe Of Sand Point"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Savoonga"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Village Of Saxman"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Scammon Bay"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Selawik"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Seldovia Village Tribe"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Shageluk Native Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Shaktoolik"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Sheldon's Point"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Shismaref"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Shungnak"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sitka Tribe Of Alaska"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Skagway Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Village Of Sleetmute"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Village Of Solomon"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"South Naknek Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pribilof Island Aleut Community Of Saint George"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Algaaciq Native Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Saint Michael"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pribilof Island Aleut Community Of Saint Paul"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Stebbins Community Association"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Stevens"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Village Of Stony River"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Takotna Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Tanacross"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Tanana"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Tatilek"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Tazlina"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Telida Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Teller"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Tetlin"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Traditional Village Of Togiak"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Nunakauyarmiut Tribe"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Tuluksak Native Community"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Tuntutuliak"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Tununak"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Twin Hills Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Tyonek"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Ugashik Village Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Umkumiute Native Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Unalakleet"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Qawalangin Tribe Of Unalaska"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Unga"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Arctic Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Village Of Wainwright"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Wales"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of White Mountain"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Lesnoi Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Wrangell Cooperative Association"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Yakutat Tlingit Tribe"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"King Salmon Tribe"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Shoonaq Tribe Of Kodiak"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Chanega"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Kaguyak Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Kanatak"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Healy Lake Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Central Council Of The Tlingit And Haida Tribes"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Native Village Of Chuathbaluk"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Inupiat Community Of The Arctic Slope"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Village Of Venetie"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Council Of Athabascan Tribal Governments"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Tanana Chiefs Conference"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Fairbanks Native Association"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Cook Inlet Tribal Council"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Association of Village Council Presidents"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Arctic Slope Native Association"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Bristol Bay Native Association"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Cook Inlet Tribal Council"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Central Council Tlingit and Haida"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Fairbanks Native Association"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Inupiat Community of the Arctic Slope"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Kawerak Inc"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Kuskokwim Native Association"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Maniilaq Association"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Tanana Chiefs Conference"]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"EASTERN OKLAHOMA"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Chickasaw",null,"CROW CREEK"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Choctaw",null,"Big Bend"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Creek",null,"Crow Creek"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Eastern Shawnee",null,"Fort Thompson"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pleasnat Point Passamaquoddy"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Miami",null,"OGLALA"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Modoc",null,"Pine Ridge Village"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Osage",null,"Oglala"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Ottawa",null,"Wakpamni"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Peoria",null,"Wounded Knee"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Quapaw",null,"Porcupine"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Seminole",null,"Medicine Root"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Seneca-Cayuga",null,"Eagle Nest"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Thlopthlocco",null,"Pass Creek"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Wyandotte",null,"La Creek"]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"EASTERN"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Catawba",null,"Antelope"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Cherokee",null,"Corn Creek"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Chitimacha",null,"Ideal"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Choctaw",null,"Ring Thunder"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Coushatta",null,"St Francis"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Indian Township",null,"Black Pipe"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Jena Choctaw",null,"Grass Mountain"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Maliseet",null,"Milks Camp"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Miccosukee",null,"Rosebud"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Micmac",null,"Swift Bear"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Narrangansett",null,"Bull Creek"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Penobscot",null,"He Dog"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pleasant Point",null,"Okreek"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Poarch Creek",null,"Soldier Creek"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Seminole",null,"Two Strike"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Seneca Nation",null,"Butte Creek"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Shinnecock Nation",null,"Horse Creek"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"St. Regis Mohawk",null,"Parmealee"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Tunica Biloxi",null,"Spring Creek"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Tuscarora",null,"Upper Cut Meat "]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Wampanoag Aquinnah"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"FORT BERTHOLD"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"GREAT PLAINS",null,"New Town/ Little Shell"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Crow Creek",null,"Four Bears"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Flandreau",null,"Parshall/Lucky Mound"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Fort Berthold",null,"Mandree"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Fort Totten",null,"Twin Buttes"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Lower Brule",null,"White Shield"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Oglala Sioux Pr"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Omaha"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Ponca"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rosebud Sioux"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Santee Sioux"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sisseton-Wahpeton"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Standing Rock"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Trenton"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Turtle Mountain"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Winnebago"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Yankton"]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"MIDWEST"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Bay Mills"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Bois Forte"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Fon Du Lac"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Forest County"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Grand Portage"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Grand Traverse"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Hannahville"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Ho-Chunk (Wis. Potawatomi)"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Huron Band of Potawatomi"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Keweenaw Bay"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Lac Courte Oreilles"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Lac Du Flambeau"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Lac Vieux Desert"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Leech Lake"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Little River Ottawa"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Minominee"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Mille Lacs Ojibwe"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Oneida Tribe "]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Odawa, Little Traverse"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pokagon Band Potawatomi"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Prairie Island"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Red Cliff"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Red Lake Chippewa"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Saginaw Chippewa"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sault Ste. Marie"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Shakopee"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sokaogon"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"St Croix"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Stockbridge Munsee"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Upper Sioux"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"White Earth"]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"NAVAJO"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Chinle"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Eastern"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Ft. Defiance"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Shiprock"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Western"]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"NORTHWEST"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Chehalis"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Coeur D'alene"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Colville"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Coos Bay"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Coquille"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Cow Creek"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Cowlitz"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Grand Ronde"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Hoh"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sb-Jamestown S'kallum"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Kalispel"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Klamath"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Kootenai"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Lower Elwha"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sb-Lummi"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Makah"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Metlakatla"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Muckleshoot"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Nez Perce"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Nisqually"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Nooksack"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Nw Band Shoshoni"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Port Gamble"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Puyallup"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Quileute"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sb-Quinault"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Salish & Kootenai"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Samish"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sauk-Suiattle"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Shoalwater Bay"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Shoshone-Bannock"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Siletz"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Skokomish"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Snoqualmie"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Spokane"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Squaxin Island"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Stillaguamish"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Suquamish"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Swinomish"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Tulalip"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Umatilla"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Upper Skagit"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Warm Springs"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Yakama"]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"PACIFIC"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Agua Caliente"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Alturas"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Auburn"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Augustine"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Barona"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Benton"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Berry Creek"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Big Lagoon"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Big Pine"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Big Sandy"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Big Valley"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Bishop"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Blue Lake"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Bridgeport"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Buena Vista"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Cabazon"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Cahuilla"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Campo"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Cedarville"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Chicken Ranch"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Chico"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Cloverdale"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Cold Springs"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Colusa"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Cortina"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Coyote Valley"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Cuyapaipe"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Dry Creek"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Elem (Sulphur Bank)"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Elk Valley"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Enterprise"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Fort Bidwell"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Fort Independence"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Greenville"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Grindstone"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Guidiville"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sb-Hoopa"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Hopland"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Inaja-Cosmit"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Ione"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Jackson"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Jamul"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Karuk"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"La Jolla"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"La Posta"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Laytonville"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Lone Pine"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Los Coyotes"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Lytton"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Manchester Point"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Manzanita"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Mesa Grande"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Middletown"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Mooretown"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Morongo"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"North Fork"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pala"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Paskenta"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pauma"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pechanga"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Picayune"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pinoleville"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pit River"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Potter Valley"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Quartz Valley"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Ramona"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Redding"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Redwood Valley"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Resighini"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rincon"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Robinson"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rohnerville"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Round Valley"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rumsey"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"San Manuel"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"San Pasqual"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"San Rosa"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Santa Rosa Rancheria"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Santa Ynez"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Santa Ysabel"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Scotts Valley"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sheep Ranch"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sherwood"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Shingle Springs"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Smith River"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Soboba"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Stewarts Points"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Susanville"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sycuan"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Table Bluff"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Table Mountain"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Timbi-Sha"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Torres-Martin"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Trinidad"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Tule River"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Tuolumne"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Upper Lake"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Viejas"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Yurok"]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"ROCKY MOUNTAIN"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Crow"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Blackfeet"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Fort Belknap"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Fort Peck"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Northern Cheyenne"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rocky Boy's"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Northern Arapaho"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Shoshone"]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"SOUTHERN PLAINS"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Alabama-Coushatta"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Apache of Oklahoma"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Caddo"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Cheyenne & Arapaho"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Citizen Potawatomi"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Comanche Nation"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Delaware"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Fort Sill Apache"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Iowa of Kansas"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Iowa of Oklahoma"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Kaw of Oklahoma"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Kickapoo Tribe of Kansas"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Kickapoo Tribe of Oklahoma"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Kiowa of Oklahoma"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Otoe-Missouria"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pawnee"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Ponca"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Prairie Potawatomi"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sac & Fox - Missouri"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sac & Fox Nation - Oklahoma"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Wichita"]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"SOUTHWEST"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Cochiti"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Isleta"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Jemez"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Jicarilla"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Laguna"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Mescalero"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Nambe"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Picuris"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pojoaque"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Ramah"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"San Felipe"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"San Ildfonso"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"San Juan"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sandia"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Santa Ana"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Santa Clara"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Santa Domingo"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Southern Ute"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Taos"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Tesuque"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Ute Mountain"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Ysleta Del Sur"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Zia"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Zuni"]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"WESTERN"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Ak-Chin"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Battle Mountain"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Cocopah"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Colorado River"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Duck Valley"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Duckwater"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Elko"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Ely"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Fallon"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Fort Mcdermitt"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Fort Mcdowell"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Gila River"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Goshute Business Council"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Havasupai"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Hopi Tribe"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Hopi Tribe (Hpl)"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Hualapai"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Kabaib Paiute"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Lovelock"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Moapa"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pascua Yaqui"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pyramid Lake"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Quechen"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Reno-Sparks"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Salt River"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"San Carlos Apache"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"San Juan Paiute"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Skull Valley"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"South Fork"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Summitt Lake"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Tohono O'odham"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Tonto Apache"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Uintah & Ouray"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Walker River Paiute"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Washoe"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Wells"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"White Mountain Apache"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Yavapai-Apache"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Yavapai-Prescott"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Yerington Paiute"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Yomba"]

{"sheet":"PriorityListForm","index":6,"n_rows":2502,"n_cols":23,"rows_kept":2502,"cut":false,"hidden":false,"merged":[[2,14,2,18],[3,1,3,2],[0,11,0,22],[0,0,0,9],[4,0,4,21],[3,9,3,10],[3,15,3,20],[1,1,1,3],[1,6,1,11],[1,14,1,18],[2,1,2,3],[2,6,2,11]]}
["                                                                                                                                                  PRIVACY ACT STATEMENT                                                                                                                                                                                                                                            25 CFR 265 and 25 U.S.C. 13 authorize the collection of this information.  This information is covered by the system of record notice “Indian Housing Improvement Program, Interior, BIA-10.”  The primary use of this information is to determine eligibility for assistance under the Housing Improvement Program.  The records contained therein may only be disclosed in accordance with the routine uses and may not otherwise be disclosed by any means of communication to any person, or to another agency, except pursuant to a written request by, or with prior written consent of the individual to whom the record pertains.  If the BIA uses the information furnished on this form for purposes other than those indicated above, it may provide you with an additional statement reflecting those purposes.  Executive Order 9397 authorizes the collection of your Social Security number.  Furnishing the information is voluntary but failure to do so may result in disapproval of your application.  ",null,null,null,null,null,null,null,null,null,null,"                                                                                                                   PAPERWORK REDUCTION ACT STATEMENT                                                                                                                                                                                                           This information is being collected to select eligible families or individuals to participate in the Housing Improvement Program.  Response to this request is required to obtain a benefit in accordance with 25 CFR 256.  You are not required to respond to this collection of information unless it displays a currently valid OMB control number.  This information will be used to determine the eligibility and the ranking of the applicant.  Public reporting burden for this form is estimated to average 1 hour per response, including the time for reviewing instructions, gathering and maintaining data, and completing and reviewing the form.  Direct comments regarding the burden estimate or any other aspect of this form to Information Collection Clearance Officer – Indian Affairs, 1849 C Street, NW, MS-4141, Washington, DC 20240."]
[null,"Regional Office:",null,null,{"$f":"IF(Profile!D5=\"\",\"\",Profile!D5)","v":"WESTERN"},null,"Number of Tribes Submitting Workplans:",null,null,null,null,null,null,null,"Number of Eligible Applicants:",null,null,null,null,null,{"$f":"IF(U2502=\"\",\"\",U2502)","v":3}]
[null,"Fiscal  Year:",null,null,{"$f":"IF(Profile!D9=\"\",\"\",Profile!D9)","v":2024},null,"Number of Tribes In Region:",null,null,null,null,null,null,null,"Number of Applications Considered:",null,null,null,null,null,{"$f":"IF(V2502=\"\",\"\",V2502)","v":3}]
[]
["        HOUSING IMPROVEMENT PROGRAM PRIORITY RANKING LIST"]
[null,"LAST NAME","FIRST NAME","Suffix","Tribe/ District","Cat","Family size","Income    1040 Form","Income Pts","Aged","Disabled","Dependent Children","Homeless","Dilapidated","Overcrowded","Veteran Points","Down Payment","Denial Letter","Prior HIP","Prior NAHASDA","Eligibility Status","Total Points","Date of Application"]
[1,"Doe","Jane",null,"Yomba","C-2",3,16500,15,0,10,3,5,0,0,0,0,"Pending","No","No","Eligible",33,"2022-12-02"]
[{"$f":"A7+1","v":2},"Tester","James",null,"Goshute Business Council","C-2",2,26000,0,0,0,0,0,5,0,0,0,"Pending","No","No","Eligible",5,"2022-01-02"]
[{"$f":"A8+1","v":3},"Sample","Joe",null,"Quechen","B",1,11280,10,15,10,0,0,5,0,5,0,"Pending","No","No","Eligible",45,"2022-11-28"]
[4]
[5]
[6]
[7]
[8]
[9]
[10]
[11]
[12]
[13]
[14]
[15]
[16]
[17]
[18]
[19]
[20]
[21]
[22]
[23]
[24]
[25]
[26]
[27]
[28]
[29]
[30]
[31]
[32]
[33]
[34]
[35]
[36]
[37]
[38]
[39]
[40]
[41]
[42]
[43]
[44]
[45]
[46]
[47]
[48]
[49]
[50]
[51]
[52]
[53]
[54]
[55]
[56]
[57]
[58]
[59]
[60]
[61]
[62]
[63]
[64]
[65]
[66]
[{"$f":"A72+1","v":67}]
[68]
[69]
[70]
[71]
[72]
[73]
[74]
[75]
[76]
[77]
[78]
[79]
[80]
[81]
[82]
[83]
[84]
[85]
[86]
[87]
[88]
[89]
[90]
[91]
[92]
[93]
[94]
[95]
[96]
[97]
[98]
[99]
[100]
[101]
[102]
[103]
[104]
[105]
[106]
[107]
[108]
[109]
[110]
[111]
[112]
[113]
[114]
[115]
[116]
[117]
[118]
[119]
[120]
[121]
[122]
[123]
[124]
[125]
[126]
[127]
[128]
[129]
[130]
[{"$f":"A136+1","v":131}]
[132]
[133]
[134]
[135]
[136]
[137]
[138]
[139]
[140]
[141]
[142]
[143]
[144]
[145]
[146]
[147]
[148]
[149]
[150]
[151]
[152]
[153]
[154]
[155]
[156]
[157]
[158]
[159]
[160]
[161]
[162]
[163]
[164]
[165]
[166]
[167]
[168]
[169]
[170]
[171]
[172]
[173]
[174]
[175]
[176]
[177]
[178]
[179]
[180]
[181]
[182]
[183]
[184]
[185]
[186]
[187]
[188]
[189]
[190]
[191]
[192]
[193]
[194]
[{"$f":"A200+1","v":195}]
[196]
[197]
[198]
[199]
[200]
[201]
[202]
[203]
[204]
[205]
[206]
[207]
[208]
[209]
[210]
[211]
[212]
[213]
[214]
[215]
[216]
[217]
[218]
[219]
[220]
[221]
[222]
[223]
[224]
[225]
[226]
[227]
[228]
[229]
[230]
[231]
[232]
[233]
[234]
[235]
[236]
[237]
[238]
[239]
[240]
[241]
[242]
[243]
[244]
[245]
[246]
[247]
[248]
[249]
[250]
[251]
[252]
[253]
[254]
[255]
[256]
[257]
[258]
[{"$f":"A264+1","v":259}]
[260]
[261]
[262]
[263]
[264]
[265]
[266]
[267]
[268]
[269]
[270]
[271]
[272]
[273]
[274]
[275]
[276]
[277]
[278]
[279]
[280]
[281]
[282]
[283]
[284]
[285]
[286]
[287]
[288]
[289]
[290]
[291]
[292]
[293]
[294]
[295]
[296]
[297]
[298]
[299]
[300]
[301]
[302]
[303]
[304]
[305]
[306]
[307]
[308]
[309]
[310]
[311]
[312]
[313]
[314]
[315]
[316]
[317]
[318]
[319]
[320]
[321]
[322]
[{"$f":"A328+1","v":323}]
[324]
[325]
[326]
[327]
[328]
[329]
[330]
[331]
[332]
[333]
[334]
[335]
[336]
[337]
[338]
[339]
[340]
[341]
[342]
[343]
[344]
[345]
[346]
[347]
[348]
[349]
[350]
[351]
[352]
[353]
[354]
[355]
[356]
[357]
[358]
[359]
[360]
[361]
[362]
[363]
[364]
[365]
[366]
[367]
[368]
[369]
[370]
[371]
[372]
[373]
[374]
[375]
[376]
[377]
[378]
[379]
[380]
[381]
[382]
[383]
[384]
[385]
[386]
[{"$f":"A392+1","v":387}]
[388]
[389]
[390]
[391]
[392]
[393]
[394]
[395]
[396]
[397]
[398]
[399]
[400]
[401]
[402]
[403]
[404]
[405]
[406]
[407]
[408]
[409]
[410]
[411]
[412]
[413]
[414]
[415]
[416]
[417]
[418]
[419]
[420]
[421]
[422]
[423]
[424]
[425]
[426]
[427]
[428]
[429]
[430]
[431]
[432]
[433]
[434]
[435]
[436]
[437]
[438]
[439]
[440]
[441]
[442]
[443]
[444]
[445]
[446]
[447]
[448]
[449]
[450]
[{"$f":"A456+1","v":451}]
[452]
[453]
[454]
[455]
[456]
[457]
[458]
[459]
[460]
[461]
[462]
[463]
[464]
[465]
[466]
[467]
[468]
[469]
[470]
[471]
[472]
[473]
[474]
[475]
[476]
[477]
[478]
[479]
[480]
[481]
[482]
[483]
[484]
[485]
[486]
[487]
[488]
[489]
[490]
[491]
[492]
[493]
[494]
[495]
[496]
[497]
[498]
[499]
[500]
[501]
[502]
[503]
[504]
[505]
[506]
[507]
[508]
[509]
[510]
[511]
[512]
[513]
[514]
[{"$f":"A520+1","v":515}]
[516]
[517]
[518]
[519]
[520]
[521]
[522]
[523]
[524]
[525]
[526]
[527]
[528]
[529]
[530]
[531]
[532]
[533]
[534]
[535]
[536]
[537]
[538]
[539]
[540]
[541]
[542]
[543]
[544]
[545]
[546]
[547]
[548]
[549]
[550]
[551]
[552]
[553]
[554]
[555]
[556]
[557]
[558]
[559]
[560]
[561]
[562]
[563]
[564]
[565]
[566]
[567]
[568]
[569]
[570]
[571]
[572]
[573]
[574]
[575]
[576]
[577]
[578]
[{"$f":"A584+1","v":579}]
[580]
[581]
[582]
[583]
[584]
[585]
[586]
[587]
[588]
[589]
[590]
[591]
[592]
[593]
[594]
[595]
[596]
[597]
[598]
[599]
[600]
[601]
[602]
[603]
[604]
[605]
[606]
[607]
[608]
[609]
[610]
[611]
[612]
[613]
[614]
[615]
[616]
[617]
[618]
[619]
[620]
[621]
[622]
[623]
[624]
[625]
[626]
[627]
[628]
[629]
[630]
[631]
[632]
[633]
[634]
[635]
[636]
[637]
[638]
[639]
[640]
[641]
[642]
[{"$f":"A648+1","v":643}]
[644]
[645]
[646]
[647]
[648]
[649]
[650]
[651]
[652]
[653]
[654]
[655]
[656]
[657]
[658]
[659]
[660]
[661]
[662]
[663]
[664]
[665]
[666]
[667]
[668]
[669]
[670]
[671]
[672]
[673]
[674]
[675]
[676]
[677]
[678]
[679]
[680]
[681]
[682]
[683]
[684]
[685]
[686]
[687]
[688]
[689]
[690]
[691]
[692]
[693]
[694]
[695]
[696]
[697]
[698]
[699]
[700]
[701]
[702]
[703]
[704]
[705]
[706]
[{"$f":"A712+1","v":707}]
[708]
[709]
[710]
[711]
[712]
[713]
[714]
[715]
[716]
[717]
[718]
[719]
[720]
[721]
[722]
[723]
[724]
[725]
[726]
[727]
[728]
[729]
[730]
[731]
[732]
[733]
[734]
[735]
[736]
[737]
[738]
[739]
[740]
[741]
[742]
[743]
[744]
[745]
[746]
[747]
[748]
[749]
[750]
[751]
[752]
[753]
[754]
[755]
[756]
[757]
[758]
[759]
[760]
[761]
[762]
[763]
[764]
[765]
[766]
[767]
[768]
[769]
[770]
[{"$f":"A776+1","v":771}]
[772]
[773]
[774]
[775]
[776]
[777]
[778]
[779]
[780]
[781]
[782]
[783]
[784]
[785]
[786]
[787]
[788]
[789]
[790]
[791]
[792]
[793]
[794]
[795]
[796]
[797]
[798]
[799]
[800]
[801]
[802]
[803]
[804]
[805]
[806]
[807]
[808]
[809]
[810]
[811]
[812]
[813]
[814]
[815]
[816]
[817]
[818]
[819]
[820]
[821]
[822]
[823]
[824]
[825]
[826]
[827]
[828]
[829]
[830]
[831]
[832]
[833]
[834]
[{"$f":"A840+1","v":835}]
[836]
[837]
[838]
[839]
[840]
[841]
[842]
[843]
[844]
[845]
[846]
[847]
[848]
[849]
[850]
[851]
[852]
[853]
[854]
[855]
[856]
[857]
[858]
[859]
[860]
[861]
[862]
[863]
[864]
[865]
[866]
[867]
[868]
[869]
[870]
[871]
[872]
[873]
[874]
[875]
[876]
[877]
[878]
[879]
[880]
[881]
[882]
[883]
[884]
[885]
[886]
[887]
[888]
[889]
[890]
[891]
[892]
[893]
[894]
[895]
[896]
[897]
[898]
[{"$f":"A904+1","v":899}]
[900]
[901]
[902]
[903]
[904]
[905]
[906]
[907]
[908]
[909]
[910]
[911]
[912]
[913]
[914]
[915]
[916]
[917]
[918]
[919]
[920]
[921]
[922]
[923]
[924]
[925]
[926]
[927]
[928]
[929]
[930]
[931]
[932]
[933]
[934]
[935]
[936]
[937]
[938]
[939]
[940]
[941]
[942]
[943]
[944]
[945]
[946]
[947]
[948]
[949]
[950]
[951]
[952]
[953]
[954]
[955]
[956]
[957]
[958]
[959]
[960]
[961]
[962]
[963]
[964]
[965]
[966]
[967]
[968]
[969]
[970]
[971]
[972]
[973]
[974]
[975]
[976]
[977]
[978]
[979]
[980]
[981]
[982]
[983]
[984]
[985]
[986]
[987]
[988]
[989]
[990]
[991]
[992]
[993]
[994]
[995]
[996]
[997]
[998]
[999]
[1000]
[1001]
[1002]
[1003]
[1004]
[1005]
[1006]
[1007]
[1008]
[1009]
[1010]
[1011]
[1012]
[1013]
[1014]
[1015]
[1016]
[1017]
[1018]
[1019]
[1020]
[1021]
[1022]
[1023]
[1024]
[1025]
[1026]
[1027]
[1028]
[1029]
[1030]
[1031]
[1032]
[1033]
[1034]
[1035]
[1036]
[1037]
[1038]
[1039]
[1040]
[1041]
[1042]
[1043]
[1044]
[1045]
[1046]
[1047]
[1048]
[1049]
[1050]
[1051]
[1052]
[1053]
[1054]
[1055]
[1056]
[1057]
[1058]
[1059]
[1060]
[1061]
[1062]
[1063]
[1064]
[1065]
[1066]
[1067]
[1068]
[1069]
[1070]
[1071]
[1072]
[1073]
[1074]
[1075]
[1076]
[1077]
[1078]
[1079]
[1080]
[1081]
[1082]
[1083]
[1084]
[1085]
[1086]
[1087]
[1088]
[1089]
[1090]
[1091]
[1092]
[1093]
[1094]
[1095]
[1096]
[1097]
[1098]
[1099]
[1100]
[1101]
[1102]
[1103]
[1104]
[1105]
[1106]
[1107]
[1108]
[1109]
[1110]
[1111]
[1112]
[1113]
[1114]
[1115]
[1116]
[1117]
[1118]
[1119]
[1120]
[1121]
[1122]
[1123]
[1124]
[1125]
[1126]
[1127]
[1128]
[1129]
[1130]
[1131]
[1132]
[{"$f":"A1138+1","v":1133}]
[{"$f":"A1139+1","v":1134}]
[{"$f":"A1140+1","v":1135}]
[1136]
[1137]
[1138]
[1139]
[1140]
[1141]
[1142]
[1143]
[1144]
[1145]
[1146]
[1147]
[1148]
[1149]
[1150]
[1151]
[1152]
[1153]
[1154]
[1155]
[1156]
[1157]
[1158]
[1159]
[1160]
[1161]
[1162]
[1163]
[1164]
[1165]
[1166]
[1167]
[1168]
[1169]
[1170]
[1171]
[1172]
[1173]
[1174]
[1175]
[1176]
[1177]
[1178]
[1179]
[1180]
[1181]
[1182]
[1183]
[1184]
[1185]
[1186]
[1187]
[1188]
[1189]
[1190]
[1191]
[1192]
[1193]
[1194]
[1195]
[1196]
[{"$f":"A1202+1","v":1197}]
[1198]
[1199]
[1200]
[1201]
[1202]
[1203]
[1204]
[1205]
[1206]
[1207]
[1208]
[1209]
[1210]
[1211]
[1212]
[1213]
[1214]
[{"$f":"A1220+1","v":1215}]
[1216]
[1217]
[1218]
[1219]
[1220]
[1221]
[1222]
[1223]
[1224]
[1225]
[1226]
[1227]
[1228]
[1229]
[1230]
[1231]
[1232]
[1233]
[1234]
[1235]
[1236]
[1237]
[1238]
[1239]
[1240]
[1241]
[1242]
[1243]
[1244]
[1245]
[1246]
[1247]
[1248]
[1249]
[1250]
[1251]
[1252]
[1253]
[1254]
[1255]
[1256]
[1257]
[1258]
[1259]
[1260]
[1261]
[1262]
[1263]
[1264]
[1265]
[1266]
[1267]
[1268]
[1269]
[1270]
[1271]
[1272]
[1273]
[1274]
[1275]
[1276]
[1277]
[1278]
[{"$f":"A1284+1","v":1279}]
[1280]
[1281]
[1282]
[1283]
[1284]
[1285]
[1286]
[1287]
[1288]
[1289]
[1290]
[1291]
[1292]
[1293]
[1294]
[1295]
[1296]
[1297]
[1298]
[1299]
[1300]
[1301]
[1302]
[1303]
[1304]
[1305]
[1306]
[1307]
[1308]
[1309]
[1310]
[1311]
[1312]
[1313]
[1314]
[1315]
[1316]
[1317]
[1318]
[1319]
[1320]
[1321]
[1322]
[1323]
[1324]
[1325]
[1326]
[1327]
[1328]
[1329]
[1330]
[1331]
[1332]
[1333]
[1334]
[1335]
[1336]
[1337]
[1338]
[1339]
[1340]
[1341]
[1342]
[{"$f":"A1348+1","v":1343}]
[1344]
[1345]
[1346]
[1347]
[1348]
[1349]
[1350]
[1351]
[1352]
[1353]
[1354]
[1355]
[1356]
[1357]
[1358]
[1359]
[1360]
[1361]
[1362]
[1363]
[1364]
[1365]
[1366]
[1367]
[1368]
[1369]
[1370]
[1371]
[1372]
[1373]
[1374]
[1375]
[1376]
[1377]
[1378]
[1379]
[1380]
[1381]
[1382]
[1383]
[1384]
[1385]
[1386]
[1387]
[1388]
[1389]
[1390]
[1391]
[1392]
[1393]
[1394]
[1395]
[1396]
[1397]
[1398]
[1399]
[1400]
[1401]
[1402]
[1403]
[1404]
[1405]
[1406]
[{"$f":"A1412+1","v":1407}]
[1408]
[1409]
[1410]
[1411]
[1412]
[1413]
[1414]
[1415]
[1416]
[1417]
[1418]
[1419]
[1420]
[1421]
[1422]
[1423]
[1424]
[1425]
[1426]
[1427]
[1428]
[1429]
[1430]
[1431]
[1432]
[1433]
[1434]
[1435]
[1436]
[1437]
[1438]
[1439]
[1440]
[1441]
[1442]
[1443]
[1444]
[1445]
[1446]
[1447]
[1448]
[1449]
[1450]
[1451]
[1452]
[1453]
[1454]
[1455]
[1456]
[1457]
[1458]
[1459]
[1460]
[1461]
[1462]
[1463]
[1464]
[1465]
[1466]
[1467]
[1468]
[1469]
[1470]
[{"$f":"A1476+1","v":1471}]
[1472]
[1473]
[1474]
[1475]
[1476]
[1477]
[1478]
[1479]
[1480]
[1481]
[1482]
[1483]
[1484]
[1485]
[1486]
[1487]
[1488]
[1489]
[1490]
[1491]
[1492]
[1493]
[1494]
[1495]
[1496]
[1497]
[1498]
[1499]
[1500]
[1501]
[1502]
[1503]
[1504]
[1505]
[1506]
[1507]
[1508]
[1509]
[1510]
[1511]
[1512]
[1513]
[1514]
[1515]
[1516]
[1517]
[1518]
[1519]
[1520]
[1521]
[1522]
[1523]
[1524]
[1525]
[1526]
[1527]
[1528]
[1529]
[1530]
[1531]
[1532]
[1533]
[1534]
[{"$f":"A1540+1","v":1535}]
[1536]
[1537]
[1538]
[1539]
[1540]
[1541]
[1542]
[1543]
[1544]
[1545]
[1546]
[1547]
[1548]
[1549]
[1550]
[1551]
[1552]
[1553]
[1554]
[1555]
[1556]
[1557]
[1558]
[1559]
[1560]
[1561]
[1562]
[1563]
[1564]
[1565]
[1566]
[1567]
[1568]
[1569]
[1570]
[1571]
[1572]
[1573]
[1574]
[1575]
[1576]
[1577]
[1578]
[1579]
[1580]
[1581]
[1582]
[1583]
[1584]
[1585]
[1586]
[1587]
[1588]
[1589]
[1590]
[1591]
[1592]
[1593]
[1594]
[1595]
[1596]
[1597]
[1598]
[{"$f":"A1604+1","v":1599}]
[1600]
[1601]
[1602]
[1603]
[1604]
[1605]
[1606]
[1607]
[1608]
[1609]
[1610]
[1611]
[1612]
[1613]
[1614]
[1615]
[1616]
[1617]
[1618]
[1619]
[1620]
[1621]
[1622]
[1623]
[1624]
[1625]
[1626]
[1627]
[1628]
[1629]
[1630]
[1631]
[1632]
[1633]
[1634]
[1635]
[1636]
[1637]
[1638]
[1639]
[1640]
[1641]
[1642]
[1643]
[1644]
[1645]
[1646]
[1647]
[1648]
[1649]
[1650]
[1651]
[1652]
[1653]
[1654]
[1655]
[1656]
[1657]
[1658]
[1659]
[1660]
[1661]
[1662]
[{"$f":"A1668+1","v":1663}]
[1664]
[1665]
[1666]
[1667]
[1668]
[1669]
[1670]
[1671]
[1672]
[1673]
[1674]
[1675]
[1676]
[1677]
[1678]
[1679]
[1680]
[1681]
[1682]
[1683]
[1684]
[1685]
[1686]
[1687]
[1688]
[1689]
[1690]
[1691]
[1692]
[1693]
[1694]
[1695]
[1696]
[1697]
[1698]
[1699]
[1700]
[1701]
[1702]
[1703]
[1704]
[1705]
[1706]
[1707]
[1708]
[1709]
[1710]
[1711]
[1712]
[1713]
[1714]
[1715]
[1716]
[1717]
[1718]
[1719]
[1720]
[1721]
[1722]
[1723]
[1724]
[1725]
[1726]
[{"$f":"A1732+1","v":1727}]
[1728]
[1729]
[1730]
[1731]
[1732]
[1733]
[1734]
[1735]
[1736]
[1737]
[1738]
[1739]
[1740]
[1741]
[1742]
[1743]
[1744]
[1745]
[1746]
[1747]
[1748]
[1749]
[1750]
[1751]
[1752]
[1753]
[1754]
[1755]
[1756]
[1757]
[1758]
[1759]
[1760]
[1761]
[1762]
[1763]
[1764]
[1765]
[1766]
[1767]
[1768]
[1769]
[1770]
[1771]
[1772]
[1773]
[1774]
[1775]
[1776]
[1777]
[1778]
[1779]
[1780]
[1781]
[1782]
[1783]
[1784]
[1785]
[1786]
[1787]
[1788]
[1789]
[1790]
[{"$f":"A1796+1","v":1791}]
[1792]
[1793]
[1794]
[1795]
[1796]
[1797]
[1798]
[1799]
[1800]
[1801]
[1802]
[1803]
[1804]
[1805]
[1806]
[1807]
[1808]
[1809]
[1810]
[1811]
[1812]
[1813]
[1814]
[1815]
[1816]
[1817]
[1818]
[1819]
[1820]
[1821]
[1822]
[1823]
[1824]
[1825]
[1826]
[1827]
[1828]
[1829]
[1830]
[1831]
[1832]
[1833]
[1834]
[1835]
[1836]
[1837]
[1838]
[1839]
[1840]
[1841]
[1842]
[1843]
[1844]
[1845]
[1846]
[1847]
[1848]
[1849]
[1850]
[1851]
[1852]
[1853]
[1854]
[{"$f":"A1860+1","v":1855}]
[1856]
[1857]
[1858]
[1859]
[1860]
[1861]
[1862]
[1863]
[1864]
[1865]
[1866]
[1867]
[1868]
[1869]
[1870]
[1871]
[1872]
[1873]
[1874]
[1875]
[1876]
[1877]
[1878]
[1879]
[1880]
[1881]
[1882]
[1883]
[1884]
[1885]
[1886]
[1887]
[1888]
[1889]
[1890]
[1891]
[1892]
[1893]
[1894]
[1895]
[1896]
[1897]
[1898]
[1899]
[1900]
[1901]
[1902]
[1903]
[1904]
[1905]
[1906]
[1907]
[1908]
[1909]
[1910]
[1911]
[1912]
[1913]
[1914]
[1915]
[1916]
[1917]
[1918]
[{"$f":"A1924+1","v":1919}]
[1920]
[1921]
[1922]
[1923]
[1924]
[1925]
[1926]
[1927]
[1928]
[1929]
[1930]
[1931]
[1932]
[1933]
[1934]
[1935]
[1936]
[1937]
[1938]
[1939]
[1940]
[1941]
[1942]
[1943]
[1944]
[1945]
[1946]
[1947]
[1948]
[1949]
[1950]
[1951]
[1952]
[1953]
[1954]
[1955]
[1956]
[1957]
[1958]
[1959]
[1960]
[1961]
[1962]
[1963]
[1964]
[1965]
[1966]
[1967]
[1968]
[1969]
[1970]
[1971]
[1972]
[1973]
[1974]
[1975]
[1976]
[1977]
[1978]
[1979]
[1980]
[1981]
[1982]
[{"$f":"A1988+1","v":1983}]
[1984]
[1985]
[1986]
[1987]
[1988]
[1989]
[1990]
[1991]
[1992]
[1993]
[1994]
[1995]
[1996]
[1997]
[1998]
[1999]
[2000]
[2001]
[2002]
[2003]
[2004]
[2005]
[2006]
[2007]
[2008]
[2009]
[2010]
[2011]
[2012]
[2013]
[2014]
[2015]
[2016]
[2017]
[2018]
[2019]
[2020]
[2021]
[2022]
[2023]
[2024]
[2025]
[2026]
[2027]
[2028]
[2029]
[2030]
[2031]
[2032]
[2033]
[2034]
[2035]
[2036]
[2037]
[2038]
[2039]
[2040]
[2041]
[2042]
[2043]
[2044]
[2045]
[2046]
[{"$f":"A2052+1","v":2047}]
[2048]
[2049]
[2050]
[2051]
[2052]
[2053]
[2054]
[2055]
[2056]
[2057]
[2058]
[2059]
[2060]
[2061]
[2062]
[2063]
[2064]
[2065]
[2066]
[2067]
[2068]
[2069]
[2070]
[2071]
[2072]
[2073]
[2074]
[2075]
[2076]
[2077]
[2078]
[2079]
[2080]
[2081]
[2082]
[2083]
[2084]
[2085]
[2086]
[2087]
[2088]
[2089]
[2090]
[2091]
[2092]
[2093]
[2094]
[2095]
[2096]
[2097]
[2098]
[2099]
[2100]
[2101]
[2102]
[2103]
[2104]
[2105]
[2106]
[2107]
[2108]
[2109]
[2110]
[{"$f":"A2116+1","v":2111}]
[2112]
[2113]
[2114]
[2115]
[2116]
[2117]
[2118]
[2119]
[2120]
[2121]
[2122]
[2123]
[2124]
[2125]
[2126]
[2127]
[2128]
[2129]
[2130]
[2131]
[2132]
[2133]
[2134]
[2135]
[2136]
[2137]
[2138]
[2139]
[2140]
[2141]
[2142]
[2143]
[2144]
[2145]
[2146]
[2147]
[2148]
[2149]
[2150]
[2151]
[2152]
[2153]
[2154]
[2155]
[2156]
[2157]
[2158]
[2159]
[2160]
[2161]
[2162]
[2163]
[2164]
[2165]
[2166]
[2167]
[2168]
[2169]
[2170]
[2171]
[2172]
[2173]
[2174]
[{"$f":"A2180+1","v":2175}]
[2176]
[2177]
[2178]
[2179]
[2180]
[2181]
[2182]
[2183]
[2184]
[2185]
[2186]
[2187]
[2188]
[2189]
[2190]
[2191]
[2192]
[2193]
[2194]
[2195]
[2196]
[2197]
[2198]
[2199]
[2200]
[2201]
[2202]
[2203]
[2204]
[2205]
[2206]
[2207]
[2208]
[2209]
[2210]
[2211]
[2212]
[2213]
[2214]
[2215]
[2216]
[2217]
[2218]
[2219]
[2220]
[2221]
[2222]
[2223]
[2224]
[2225]
[2226]
[2227]
[2228]
[2229]
[2230]
[2231]
[2232]
[2233]
[2234]
[2235]
[2236]
[2237]
[2238]
[{"$f":"A2244+1","v":2239}]
[2240]
[2241]
[2242]
[2243]
[2244]
[2245]
[2246]
[2247]
[2248]
[2249]
[2250]
[2251]
[2252]
[2253]
[2254]
[2255]
[2256]
[2257]
[2258]
[2259]
[2260]
[2261]
[2262]
[2263]
[2264]
[2265]
[2266]
[2267]
[2268]
[2269]
[2270]
[2271]
[2272]
[2273]
[2274]
[2275]
[2276]
[2277]
[2278]
[2279]
[2280]
[2281]
[2282]
[2283]
[2284]
[2285]
[2286]
[2287]
[2288]
[2289]
[2290]
[2291]
[2292]
[2293]
[2294]
[2295]
[2296]
[2297]
[2298]
[2299]
[2300]
[2301]
[2302]
[{"$f":"A2308+1","v":2303}]
[2304]
[2305]
[2306]
[2307]
[2308]
[2309]
[2310]
[2311]
[2312]
[2313]
[2314]
[2315]
[2316]
[2317]
[2318]
[2319]
[2320]
[2321]
[2322]
[2323]
[2324]
[2325]
[2326]
[2327]
[2328]
[2329]
[2330]
[2331]
[2332]
[2333]
[2334]
[2335]
[2336]
[2337]
[2338]
[2339]
[2340]
[2341]
[2342]
[2343]
[2344]
[2345]
[2346]
[2347]
[2348]
[2349]
[2350]
[2351]
[2352]
[2353]
[2354]
[2355]
[2356]
[2357]
[2358]
[2359]
[2360]
[2361]
[2362]
[2363]
[2364]
[2365]
[2366]
[{"$f":"A2372+1","v":2367}]
[2368]
[2369]
[2370]
[2371]
[2372]
[2373]
[2374]
[2375]
[2376]
[2377]
[2378]
[2379]
[2380]
[2381]
[2382]
[2383]
[2384]
[2385]
[2386]
[2387]
[2388]
[2389]
[2390]
[2391]
[2392]
[2393]
[2394]
[2395]
[2396]
[2397]
[2398]
[2399]
[2400]
[2401]
[2402]
[2403]
[2404]
[2405]
[2406]
[2407]
[2408]
[2409]
[2410]
[2411]
[2412]
[2413]
[2414]
[2415]
[2416]
[2417]
[2418]
[2419]
[2420]
[2421]
[2422]
[2423]
[2424]
[2425]
[2426]
[2427]
[2428]
[2429]
[2430]
[{"$f":"A2436+1","v":2431}]
[2432]
[2433]
[2434]
[2435]
[2436]
[2437]
[2438]
[2439]
[2440]
[2441]
[2442]
[2443]
[2444]
[2445]
[2446]
[2447]
[2448]
[2449]
[2450]
[2451]
[2452]
[2453]
[2454]
[2455]
[2456]
[2457]
[2458]
[2459]
[2460]
[2461]
[2462]
[2463]
[2464]
[2465]
[2466]
[2467]
[2468]
[2469]
[2470]
[2471]
[2472]
[2473]
[2474]
[2475]
[2476]
[2477]
[2478]
[2479]
[2480]
[2481]
[2482]
[2483]
[2484]
[2485]
[2486]
[2487]
[2488]
[2489]
[2490]
[2491]
[2492]
[2493]
[2494]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"COUNTIF(U7:U2500,\"Eligible\")","v":3},{"$f":"COUNTIF(V7:V2500,\">=1\")-COUNTIF(V7:V2500,\">100\")","v":3}]

{"sheet":"TribePartI","index":7,"n_rows":2522,"n_cols":14,"rows_kept":2522,"cut":false,"hidden":false,"merged":[[0,0,3,13],[4,0,7,13],[8,0,8,10],[10,11,10,13],[9,1,9,3],[10,1,10,3],[9,11,9,13],[9,4,9,9],[10,4,10,9],[11,1,11,3],[11,11,11,13],[14,5,15,9],[14,11,16,11],[13,1,13,10],[11,4,11,9],[12,4,12,9],[14,4,16,4],[14,0,15,3],[12,1,12,3],[12,11,12,13],[14,10,16,10],[14,12,16,12],[14,13,16,13]]}
["                                                                                            PRIVACY ACT STATEMENT                                                                                                                                                                                                                                                                         25 CFR 265 and 25 U.S.C. 13 authorize the collection of this information.  This information is covered by the system of record notice “Indian Housing Improvement Program, Interior, BIA-10.”  The primary use of this information is to determine eligibility for assistance under the Housing Improvement Program.  The records contained therein may only be disclosed in accordance with the routine uses and may not otherwise be disclosed by any means of communication to any person, or to another agency, except pursuant to a written request by, or with prior written consent of the individual to whom the record pertains.  If the BIA uses the information furnished on this form for purposes other than those indicated above, it may provide you with an additional statement reflecting those purposes.  Executive Order 9397 authorizes the collection of your Social Security number.  Furnishing the information is voluntary but failure to do so may result in disapproval of your application.  "]
[]
[]
[]
["                                                                                                               PAPERWORK REDUCTION ACT STATEMENT                                                                                                                                                                                                           This information is being collected to select eligible families or individuals to participate in the Housing Improvement Program.  Response to this request is required to obtain a benefit in accordance with 25 CFR 256.  You are not required to respond to this collection of information unless it displays a currently valid OMB control number.  This information will be used to determine the eligibility and the ranking of the applicant.  Public reporting burden for this form is estimated to average 1 hour per response, including the time for reviewing instructions, gathering and maintaining data, and completing and reviewing the form.  Direct comments regarding the burden estimate or any other aspect of this form to Information Collection Clearance Officer – Indian Affairs, 1849 C Street, NW, MS-4141, Washington, DC 20240. "]
[]
[]
[]
["                   PART I - TRIBAL WORK PLAN ",null,null,null,null,null,null,null,null,null,null,"Date:",null,{"$f":"IF(Profile!D17=0,\"\",Profile!D17)","v":""}]
[1,"Work Plan for Fiscal Year: ",null,null,{"$f":"IF(Profile!D9=\"\",\"\",Profile!D9)","v":2024},null,null,null,null,null,"Name:",{"$f":"IF(Profile!D10=0,\"\",Profile!D10)","v":""}]
[2,"Name of Tribe / Consortium:",null,null,{"$f":"IF(Profile!D6=\"\",\"\",Profile!D6)","v":"Quechen"},null,null,null,null,null,"Title:",{"$f":"IF(Profile!D11=0,\"\",Profile!D11)","v":""}]
[3,"Number of Eligible Applicants:",null,null,{"$f":"IF(M2521=0,\"\",M2521)","v":3},null,null,null,null,null,"Phone:",{"$f":"IF(Profile!D12=0,\"\",Profile!D12)","v":""}]
[4,"Number of Applications Received:",null,null,{"$f":"IF(N2521=0,\"\",N2521)","v":3},null,null,null,null,null,"Fax:",{"$f":"IF(Profile!D13=0,\"\",Profile!D13)","v":""}]
[null,"See instructions for printing form            "]
["5. Name of Eligible Applicant              (ranked in order of need)",null,null,null,"6. Applicant's Servicing Tribe    ","7. Program Category            (Enter One As Applicable)",null,null,null,null,"8a. Estimated Start Date","8b. Estimated Project Costs                                         \n 25 CFR 256.17(b))**        ","Eligibility Status","8c. Priority Ranking Points                        (ranked in order from           highest to lowest)"]
[]
[null,"Last ","First","Suffix",null,"(A)","(B)","(C-1)","(C-2)","(D)"]
[1,"Doe","Jane",null,null,null,null,null,"C-2",null,null,null,"Eligible",33]
[{"$f":"A18+1","v":2},"Tester","James",null,null,null,null,null,"C-2",null,null,null,"Eligible",5]
[{"$f":"A19+1","v":3},"Sample","Joe",null,null,null,"B",null,null,null,null,null,"Eligible",45]
[4]
[5]
[6]
[7]
[8]
[9]
[10]
[11]
[12]
[13]
[14]
[15]
[16]
[17]
[18]
[19]
[20]
[21]
[22]
[23]
[24]
[25]
[26]
[27]
[28]
[29]
[30]
[31]
[32]
[33]
[34]
[35]
[36]
[37]
[38]
[39]
[40]
[41]
[42]
[43]
[44]
[45]
[46]
[47]
[48]
[49]
[50]
[51]
[52]
[53]
[54]
[55]
[56]
[57]
[58]
[59]
[60]
[61]
[62]
[63]
[64]
[65]
[66]
[{"$f":"A83+1","v":67}]
[68]
[69]
[70]
[71]
[72]
[73]
[74]
[75]
[76]
[77]
[78]
[79]
[80]
[81]
[82]
[83]
[84]
[85]
[86]
[87]
[88]
[89]
[90]
[91]
[92]
[93]
[94]
[95]
[96]
[97]
[98]
[99]
[100]
[101]
[102]
[103]
[104]
[105]
[106]
[107]
[108]
[109]
[110]
[111]
[112]
[113]
[114]
[115]
[116]
[117]
[118]
[119]
[120]
[121]
[122]
[123]
[124]
[125]
[126]
[127]
[128]
[129]
[130]
[{"$f":"A147+1","v":131}]
[132]
[133]
[134]
[135]
[136]
[137]
[138]
[139]
[140]
[141]
[142]
[143]
[144]
[145]
[146]
[147]
[148]
[149]
[150]
[151]
[152]
[153]
[154]
[155]
[156]
[157]
[158]
[159]
[160]
[161]
[162]
[163]
[164]
[165]
[166]
[167]
[168]
[169]
[170]
[171]
[172]
[173]
[174]
[175]
[176]
[177]
[178]
[179]
[180]
[181]
[182]
[183]
[184]
[185]
[186]
[187]
[188]
[189]
[190]
[191]
[192]
[193]
[194]
[{"$f":"A211+1","v":195}]
[196]
[197]
[198]
[199]
[200]
[201]
[202]
[203]
[204]
[205]
[206]
[207]
[208]
[209]
[210]
[211]
[212]
[213]
[214]
[215]
[216]
[217]
[218]
[219]
[220]
[221]
[222]
[223]
[224]
[225]
[226]
[227]
[228]
[229]
[230]
[231]
[232]
[233]
[234]
[235]
[236]
[237]
[238]
[239]
[240]
[241]
[242]
[243]
[244]
[245]
[246]
[247]
[248]
[249]
[250]
[251]
[252]
[253]
[254]
[255]
[256]
[257]
[258]
[{"$f":"A275+1","v":259}]
[260]
[261]
[262]
[263]
[264]
[265]
[266]
[267]
[268]
[269]
[270]
[271]
[272]
[273]
[274]
[275]
[276]
[277]
[278]
[279]
[280]
[281]
[282]
[283]
[284]
[285]
[286]
[287]
[288]
[289]
[290]
[291]
[292]
[293]
[294]
[295]
[296]
[297]
[298]
[299]
[300]
[301]
[302]
[303]
[304]
[305]
[306]
[307]
[308]
[309]
[310]
[311]
[312]
[313]
[314]
[315]
[316]
[317]
[318]
[319]
[320]
[321]
[322]
[{"$f":"A339+1","v":323}]
[324]
[325]
[326]
[327]
[328]
[329]
[330]
[331]
[332]
[333]
[334]
[335]
[336]
[337]
[338]
[339]
[340]
[341]
[342]
[343]
[344]
[345]
[346]
[347]
[348]
[349]
[350]
[351]
[352]
[353]
[354]
[355]
[356]
[357]
[358]
[359]
[360]
[361]
[362]
[363]
[364]
[365]
[366]
[367]
[368]
[369]
[370]
[371]
[372]
[373]
[374]
[375]
[376]
[377]
[378]
[379]
[380]
[381]
[382]
[383]
[384]
[385]
[386]
[{"$f":"A403+1","v":387}]
[388]
[389]
[390]
[391]
[392]
[393]
[394]
[395]
[396]
[397]
[398]
[399]
[400]
[401]
[402]
[403]
[404]
[405]
[406]
[407]
[408]
[409]
[410]
[411]
[412]
[413]
[414]
[415]
[416]
[417]
[418]
[419]
[420]
[421]
[422]
[423]
[424]
[425]
[426]
[427]
[428]
[429]
[430]
[431]
[432]
[433]
[434]
[435]
[436]
[437]
[438]
[439]
[440]
[441]
[442]
[443]
[444]
[445]
[446]
[447]
[448]
[449]
[450]
[{"$f":"A467+1","v":451}]
[452]
[453]
[454]
[455]
[456]
[457]
[458]
[459]
[460]
[461]
[462]
[463]
[464]
[465]
[466]
[467]
[468]
[469]
[470]
[471]
[472]
[473]
[474]
[475]
[476]
[477]
[478]
[479]
[480]
[481]
[482]
[483]
[484]
[485]
[486]
[487]
[488]
[489]
[490]
[491]
[492]
[493]
[494]
[495]
[496]
[497]
[498]
[499]
[500]
[501]
[502]
[503]
[504]
[505]
[506]
[507]
[508]
[509]
[510]
[511]
[512]
[513]
[514]
[{"$f":"A531+1","v":515}]
[516]
[517]
[518]
[519]
[520]
[521]
[522]
[523]
[524]
[525]
[526]
[527]
[528]
[529]
[530]
[531]
[532]
[533]
[534]
[535]
[536]
[537]
[538]
[539]
[540]
[541]
[542]
[543]
[544]
[545]
[546]
[547]
[548]
[549]
[550]
[551]
[552]
[553]
[554]
[555]
[556]
[557]
[558]
[559]
[560]
[561]
[562]
[563]
[564]
[565]
[566]
[567]
[568]
[569]
[570]
[571]
[572]
[573]
[574]
[575]
[576]
[577]
[578]
[{"$f":"A595+1","v":579}]
[580]
[581]
[582]
[583]
[584]
[585]
[586]
[587]
[588]
[589]
[590]
[591]
[592]
[593]
[594]
[595]
[596]
[597]
[598]
[599]
[600]
[601]
[602]
[603]
[604]
[605]
[606]
[607]
[608]
[609]
[610]
[611]
[612]
[613]
[614]
[615]
[616]
[617]
[618]
[619]
[620]
[621]
[622]
[623]
[624]
[625]
[626]
[627]
[628]
[629]
[630]
[631]
[632]
[633]
[634]
[635]
[636]
[637]
[638]
[639]
[640]
[641]
[642]
[{"$f":"A659+1","v":643}]
[644]
[645]
[646]
[647]
[648]
[649]
[650]
[651]
[652]
[653]
[654]
[655]
[656]
[657]
[658]
[659]
[660]
[661]
[662]
[663]
[664]
[665]
[666]
[667]
[668]
[669]
[670]
[671]
[672]
[673]
[674]
[675]
[676]
[677]
[678]
[679]
[680]
[681]
[682]
[683]
[684]
[685]
[686]
[687]
[688]
[689]
[690]
[691]
[692]
[693]
[694]
[695]
[696]
[697]
[698]
[699]
[700]
[701]
[702]
[703]
[704]
[705]
[706]
[{"$f":"A723+1","v":707}]
[708]
[709]
[710]
[711]
[712]
[713]
[714]
[715]
[716]
[717]
[718]
[719]
[720]
[721]
[722]
[723]
[724]
[725]
[726]
[727]
[728]
[729]
[730]
[731]
[732]
[733]
[734]
[735]
[736]
[737]
[738]
[739]
[740]
[741]
[742]
[743]
[744]
[745]
[746]
[747]
[748]
[749]
[750]
[751]
[752]
[753]
[754]
[755]
[756]
[757]
[758]
[759]
[760]
[761]
[762]
[763]
[764]
[765]
[766]
[767]
[768]
[769]
[770]
[{"$f":"A787+1","v":771}]
[772]
[773]
[774]
[775]
[776]
[777]
[778]
[779]
[780]
[781]
[782]
[783]
[784]
[785]
[786]
[787]
[788]
[789]
[790]
[791]
[792]
[793]
[794]
[795]
[796]
[797]
[798]
[799]
[800]
[801]
[802]
[803]
[804]
[805]
[806]
[807]
[808]
[809]
[810]
[811]
[812]
[813]
[814]
[815]
[816]
[817]
[818]
[819]
[820]
[821]
[822]
[823]
[824]
[825]
[826]
[827]
[828]
[829]
[830]
[831]
[832]
[833]
[834]
[{"$f":"A851+1","v":835}]
[836]
[837]
[838]
[839]
[840]
[841]
[842]
[843]
[844]
[845]
[846]
[847]
[848]
[849]
[850]
[851]
[852]
[853]
[854]
[855]
[856]
[{"$f":"A873+1","v":857}]
[858]
[859]
[860]
[861]
[862]
[863]
[864]
[865]
[866]
[867]
[868]
[869]
[870]
[871]
[872]
[873]
[874]
[875]
[876]
[877]
[878]
[879]
[880]
[881]
[882]
[883]
[884]
[885]
[886]
[887]
[888]
[889]
[890]
[891]
[892]
[893]
[894]
[895]
[896]
[897]
[898]
[899]
[900]
[901]
[902]
[903]
[904]
[905]
[{"$f":"A922+1","v":906}]
[907]
[908]
[909]
[910]
[911]
[912]
[913]
[914]
[915]
[916]
[917]
[918]
[919]
[920]
[921]
[922]
[923]
[924]
[925]
[926]
[927]
[928]
[929]
[930]
[931]
[932]
[933]
[934]
[935]
[936]
[937]
[938]
[939]
[940]
[941]
[942]
[943]
[944]
[945]
[946]
[947]
[948]
[949]
[950]
[951]
[952]
[953]
[954]
[955]
[956]
[957]
[958]
[959]
[960]
[961]
[962]
[963]
[964]
[965]
[966]
[967]
[968]
[969]
[{"$f":"A986+1","v":970}]
[971]
[972]
[973]
[974]
[975]
[976]
[977]
[978]
[979]
[980]
[981]
[982]
[983]
[984]
[985]
[986]
[987]
[988]
[989]
[990]
[991]
[992]
[993]
[994]
[995]
[996]
[997]
[998]
[999]
[1000]
[1001]
[1002]
[1003]
[1004]
[1005]
[1006]
[1007]
[1008]
[1009]
[1010]
[1011]
[1012]
[1013]
[1014]
[1015]
[1016]
[1017]
[1018]
[1019]
[1020]
[1021]
[1022]
[1023]
[1024]
[1025]
[1026]
[1027]
[1028]
[1029]
[1030]
[1031]
[1032]
[1033]
[{"$f":"A1050+1","v":1034}]
[1035]
[1036]
[1037]
[1038]
[1039]
[1040]
[1041]
[1042]
[1043]
[1044]
[1045]
[1046]
[1047]
[1048]
[1049]
[1050]
[1051]
[1052]
[1053]
[1054]
[1055]
[1056]
[1057]
[1058]
[1059]
[1060]
[1061]
[1062]
[1063]
[1064]
[1065]
[1066]
[1067]
[1068]
[1069]
[1070]
[1071]
[1072]
[1073]
[1074]
[1075]
[1076]
[1077]
[1078]
[1079]
[1080]
[1081]
[1082]
[1083]
[1084]
[1085]
[1086]
[1087]
[1088]
[1089]
[1090]
[1091]
[1092]
[1093]
[1094]
[1095]
[1096]
[1097]
[{"$f":"A1114+1","v":1098}]
[1099]
[1100]
[1101]
[1102]
[1103]
[1104]
[1105]
[1106]
[1107]
[1108]
[1109]
[1110]
[1111]
[1112]
[1113]
[1114]
[1115]
[1116]
[1117]
[1118]
[1119]
[1120]
[1121]
[1122]
[1123]
[1124]
[1125]
[1126]
[1127]
[1128]
[1129]
[1130]
[1131]
[1132]
[1133]
[1134]
[1135]
[1136]
[1137]
[1138]
[1139]
[1140]
[1141]
[1142]
[1143]
[1144]
[1145]
[1146]
[1147]
[1148]
[1149]
[1150]
[1151]
[1152]
[1153]
[1154]
[1155]
[1156]
[1157]
[1158]
[1159]
[1160]
[1161]
[{"$f":"A1178+1","v":1162}]
[1163]
[1164]
[1165]
[1166]
[1167]
[1168]
[1169]
[1170]
[1171]
[1172]
[1173]
[1174]
[1175]
[1176]
[1177]
[1178]
[1179]
[1180]
[1181]
[1182]
[1183]
[1184]
[1185]
[1186]
[1187]
[1188]
[1189]
[1190]
[1191]
[1192]
[1193]
[1194]
[1195]
[1196]
[1197]
[1198]
[1199]
[1200]
[1201]
[1202]
[1203]
[1204]
[1205]
[1206]
[1207]
[1208]
[1209]
[1210]
[1211]
[1212]
[1213]
[1214]
[1215]
[1216]
[1217]
[1218]
[1219]
[1220]
[1221]
[1222]
[1223]
[1224]
[1225]
[{"$f":"A1242+1","v":1226}]
[1227]
[1228]
[1229]
[1230]
[1231]
[1232]
[1233]
[1234]
[1235]
[1236]
[1237]
[1238]
[1239]
[1240]
[1241]
[1242]
[1243]
[1244]
[1245]
[1246]
[1247]
[1248]
[1249]
[1250]
[1251]
[1252]
[1253]
[1254]
[1255]
[1256]
[1257]
[1258]
[1259]
[1260]
[1261]
[1262]
[1263]
[1264]
[1265]
[1266]
[1267]
[1268]
[1269]
[1270]
[1271]
[1272]
[1273]
[1274]
[1275]
[1276]
[1277]
[1278]
[1279]
[1280]
[1281]
[1282]
[1283]
[1284]
[1285]
[1286]
[1287]
[1288]
[1289]
[{"$f":"A1306+1","v":1290}]
[1291]
[1292]
[1293]
[1294]
[1295]
[1296]
[1297]
[1298]
[1299]
[1300]
[1301]
[1302]
[1303]
[1304]
[1305]
[1306]
[1307]
[1308]
[1309]
[1310]
[1311]
[1312]
[1313]
[1314]
[1315]
[1316]
[1317]
[1318]
[1319]
[1320]
[1321]
[1322]
[1323]
[1324]
[1325]
[1326]
[1327]
[1328]
[1329]
[1330]
[1331]
[1332]
[1333]
[1334]
[1335]
[1336]
[1337]
[1338]
[1339]
[1340]
[1341]
[1342]
[1343]
[1344]
[1345]
[1346]
[1347]
[1348]
[1349]
[1350]
[1351]
[1352]
[1353]
[{"$f":"A1370+1","v":1354}]
[1355]
[1356]
[1357]
[1358]
[1359]
[1360]
[1361]
[1362]
[1363]
[1364]
[1365]
[1366]
[1367]
[1368]
[1369]
[1370]
[1371]
[1372]
[1373]
[1374]
[1375]
[1376]
[1377]
[1378]
[1379]
[1380]
[1381]
[1382]
[1383]
[1384]
[1385]
[1386]
[1387]
[1388]
[1389]
[1390]
[1391]
[1392]
[1393]
[1394]
[1395]
[1396]
[1397]
[1398]
[1399]
[1400]
[1401]
[1402]
[1403]
[1404]
[1405]
[1406]
[1407]
[1408]
[1409]
[1410]
[1411]
[1412]
[1413]
[1414]
[1415]
[1416]
[1417]
[{"$f":"A1434+1","v":1418}]
[1419]
[1420]
[1421]
[1422]
[1423]
[1424]
[1425]
[{"$f":"A1442+1","v":1426}]
[1427]
[1428]
[1429]
[1430]
[1431]
[1432]
[1433]
[1434]
[1435]
[1436]
[1437]
[1438]
[1439]
[1440]
[1441]
[1442]
[1443]
[1444]
[1445]
[1446]
[1447]
[1448]
[1449]
[1450]
[1451]
[1452]
[1453]
[1454]
[1455]
[1456]
[1457]
[1458]
[1459]
[1460]
[1461]
[1462]
[1463]
[1464]
[1465]
[1466]
[1467]
[1468]
[1469]
[1470]
[1471]
[1472]
[1473]
[1474]
[1475]
[1476]
[1477]
[1478]
[1479]
[1480]
[1481]
[{"$f":"A1498+1","v":1482}]
[1483]
[1484]
[1485]
[1486]
[1487]
[1488]
[1489]
[1490]
[1491]
[1492]
[1493]
[1494]
[1495]
[1496]
[1497]
[1498]
[1499]
[1500]
[1501]
[1502]
[1503]
[1504]
[1505]
[1506]
[1507]
[1508]
[1509]
[1510]
[1511]
[1512]
[1513]
[1514]
[1515]
[1516]
[1517]
[1518]
[1519]
[1520]
[1521]
[1522]
[1523]
[1524]
[1525]
[1526]
[1527]
[1528]
[1529]
[1530]
[1531]
[1532]
[1533]
[1534]
[1535]
[1536]
[1537]
[1538]
[1539]
[1540]
[1541]
[1542]
[1543]
[1544]
[1545]
[{"$f":"A1562+1","v":1546}]
[1547]
[1548]
[1549]
[1550]
[1551]
[1552]
[1553]
[1554]
[1555]
[1556]
[1557]
[1558]
[1559]
[1560]
[1561]
[1562]
[1563]
[1564]
[1565]
[1566]
[1567]
[1568]
[1569]
[1570]
[1571]
[1572]
[1573]
[1574]
[1575]
[1576]
[1577]
[1578]
[1579]
[1580]
[1581]
[1582]
[1583]
[1584]
[1585]
[1586]
[1587]
[1588]
[1589]
[1590]
[1591]
[1592]
[1593]
[1594]
[1595]
[1596]
[1597]
[1598]
[1599]
[1600]
[1601]
[1602]
[1603]
[1604]
[1605]
[1606]
[1607]
[1608]
[1609]
[{"$f":"A1626+1","v":1610}]
[1611]
[1612]
[1613]
[1614]
[1615]
[1616]
[1617]
[1618]
[1619]
[1620]
[1621]
[1622]
[1623]
[1624]
[1625]
[1626]
[1627]
[1628]
[1629]
[1630]
[1631]
[1632]
[1633]
[1634]
[1635]
[1636]
[1637]
[1638]
[1639]
[1640]
[1641]
[1642]
[1643]
[1644]
[1645]
[1646]
[1647]
[1648]
[1649]
[1650]
[1651]
[1652]
[1653]
[1654]
[1655]
[1656]
[1657]
[1658]
[1659]
[1660]
[1661]
[1662]
[1663]
[1664]
[1665]
[1666]
[1667]
[1668]
[1669]
[1670]
[1671]
[1672]
[1673]
[{"$f":"A1690+1","v":1674}]
[1675]
[1676]
[1677]
[1678]
[1679]
[1680]
[1681]
[1682]
[1683]
[1684]
[1685]
[1686]
[1687]
[1688]
[1689]
[1690]
[1691]
[1692]
[1693]
[1694]
[1695]
[1696]
[1697]
[1698]
[1699]
[1700]
[1701]
[1702]
[1703]
[1704]
[1705]
[1706]
[1707]
[1708]
[1709]
[1710]
[1711]
[1712]
[1713]
[1714]
[1715]
[1716]
[1717]
[1718]
[1719]
[1720]
[1721]
[1722]
[1723]
[1724]
[1725]
[1726]
[1727]
[1728]
[1729]
[1730]
[1731]
[1732]
[1733]
[1734]
[1735]
[1736]
[1737]
[{"$f":"A1754+1","v":1738}]
[1739]
[1740]
[1741]
[1742]
[1743]
[1744]
[1745]
[1746]
[1747]
[1748]
[1749]
[1750]
[1751]
[1752]
[1753]
[1754]
[1755]
[1756]
[1757]
[1758]
[1759]
[1760]
[1761]
[1762]
[1763]
[1764]
[1765]
[1766]
[1767]
[1768]
[1769]
[1770]
[1771]
[1772]
[1773]
[1774]
[1775]
[1776]
[1777]
[1778]
[1779]
[1780]
[1781]
[1782]
[1783]
[1784]
[1785]
[1786]
[1787]
[1788]
[1789]
[1790]
[1791]
[1792]
[1793]
[1794]
[1795]
[1796]
[1797]
[1798]
[1799]
[1800]
[1801]
[{"$f":"A1818+1","v":1802}]
[1803]
[1804]
[1805]
[1806]
[1807]
[1808]
[1809]
[1810]
[1811]
[1812]
[1813]
[1814]
[1815]
[1816]
[1817]
[1818]
[1819]
[1820]
[1821]
[1822]
[1823]
[1824]
[1825]
[1826]
[1827]
[1828]
[1829]
[1830]
[1831]
[1832]
[1833]
[{"$f":"A1850+1","v":1834}]
[1835]
[1836]
[1837]
[1838]
[1839]
[1840]
[1841]
[1842]
[1843]
[1844]
[1845]
[1846]
[1847]
[1848]
[1849]
[1850]
[1851]
[1852]
[1853]
[1854]
[1855]
[1856]
[1857]
[1858]
[1859]
[1860]
[1861]
[1862]
[1863]
[1864]
[1865]
[{"$f":"A1882+1","v":1866}]
[1867]
[1868]
[1869]
[1870]
[1871]
[1872]
[1873]
[1874]
[1875]
[1876]
[1877]
[1878]
[1879]
[1880]
[1881]
[1882]
[1883]
[1884]
[1885]
[1886]
[1887]
[1888]
[1889]
[1890]
[1891]
[1892]
[1893]
[1894]
[1895]
[1896]
[1897]
[{"$f":"A1914+1","v":1898}]
[1899]
[1900]
[1901]
[1902]
[1903]
[1904]
[1905]
[1906]
[1907]
[1908]
[1909]
[1910]
[1911]
[1912]
[1913]
[1914]
[1915]
[1916]
[1917]
[1918]
[1919]
[1920]
[1921]
[1922]
[1923]
[1924]
[1925]
[1926]
[1927]
[1928]
[1929]
[{"$f":"A1946+1","v":1930}]
[1931]
[1932]
[1933]
[1934]
[1935]
[1936]
[1937]
[1938]
[1939]
[1940]
[1941]
[{"$f":"A1958+1","v":1942}]
[1943]
[1944]
[1945]
[1946]
[1947]
[1948]
[1949]
[1950]
[1951]
[1952]
[1953]
[1954]
[1955]
[1956]
[1957]
[1958]
[1959]
[1960]
[1961]
[1962]
[1963]
[1964]
[1965]
[1966]
[1967]
[1968]
[1969]
[1970]
[1971]
[1972]
[1973]
[1974]
[1975]
[1976]
[1977]
[1978]
[1979]
[1980]
[1981]
[1982]
[1983]
[1984]
[1985]
[1986]
[1987]
[1988]
[1989]
[1990]
[1991]
[1992]
[1993]
[1994]
[1995]
[1996]
[1997]
[1998]
[1999]
[2000]
[2001]
[2002]
[2003]
[2004]
[2005]
[{"$f":"A2022+1","v":2006}]
[2007]
[2008]
[2009]
[2010]
[2011]
[2012]
[2013]
[2014]
[2015]
[2016]
[2017]
[2018]
[2019]
[2020]
[2021]
[2022]
[2023]
[2024]
[2025]
[2026]
[2027]
[2028]
[2029]
[2030]
[2031]
[2032]
[2033]
[2034]
[2035]
[2036]
[2037]
[2038]
[2039]
[2040]
[2041]
[2042]
[2043]
[2044]
[2045]
[2046]
[2047]
[2048]
[2049]
[2050]
[2051]
[2052]
[2053]
[2054]
[2055]
[2056]
[2057]
[2058]
[2059]
[2060]
[2061]
[2062]
[2063]
[2064]
[2065]
[2066]
[2067]
[2068]
[2069]
[{"$f":"A2086+1","v":2070}]
[2071]
[2072]
[2073]
[2074]
[2075]
[2076]
[2077]
[2078]
[2079]
[2080]
[2081]
[2082]
[2083]
[2084]
[2085]
[2086]
[2087]
[2088]
[2089]
[2090]
[2091]
[2092]
[2093]
[2094]
[2095]
[2096]
[2097]
[2098]
[2099]
[2100]
[2101]
[2102]
[2103]
[2104]
[2105]
[2106]
[2107]
[2108]
[2109]
[2110]
[2111]
[2112]
[2113]
[2114]
[2115]
[2116]
[2117]
[2118]
[2119]
[2120]
[2121]
[2122]
[2123]
[2124]
[2125]
[2126]
[2127]
[2128]
[2129]
[2130]
[2131]
[2132]
[2133]
[{"$f":"A2150+1","v":2134}]
[2135]
[2136]
[2137]
[2138]
[2139]
[2140]
[2141]
[2142]
[2143]
[2144]
[2145]
[2146]
[2147]
[2148]
[2149]
[2150]
[2151]
[2152]
[2153]
[2154]
[2155]
[2156]
[2157]
[2158]
[2159]
[2160]
[2161]
[2162]
[2163]
[2164]
[2165]
[2166]
[2167]
[2168]
[2169]
[2170]
[2171]
[2172]
[2173]
[2174]
[2175]
[2176]
[2177]
[2178]
[2179]
[2180]
[2181]
[2182]
[2183]
[2184]
[2185]
[2186]
[2187]
[2188]
[2189]
[2190]
[2191]
[2192]
[2193]
[2194]
[2195]
[2196]
[2197]
[{"$f":"A2214+1","v":2198}]
[2199]
[2200]
[2201]
[2202]
[2203]
[2204]
[2205]
[2206]
[2207]
[2208]
[2209]
[2210]
[2211]
[2212]
[2213]
[2214]
[2215]
[2216]
[2217]
[2218]
[2219]
[2220]
[2221]
[2222]
[2223]
[2224]
[2225]
[2226]
[2227]
[2228]
[2229]
[2230]
[2231]
[2232]
[2233]
[2234]
[2235]
[2236]
[2237]
[2238]
[2239]
[2240]
[2241]
[2242]
[2243]
[2244]
[2245]
[2246]
[2247]
[2248]
[2249]
[2250]
[2251]
[2252]
[2253]
[2254]
[2255]
[2256]
[2257]
[2258]
[2259]
[2260]
[2261]
[{"$f":"A2278+1","v":2262}]
[2263]
[2264]
[2265]
[2266]
[2267]
[2268]
[2269]
[2270]
[2271]
[2272]
[2273]
[2274]
[2275]
[2276]
[2277]
[2278]
[2279]
[2280]
[2281]
[2282]
[2283]
[2284]
[2285]
[2286]
[2287]
[2288]
[2289]
[2290]
[2291]
[2292]
[2293]
[2294]
[2295]
[2296]
[2297]
[2298]
[2299]
[2300]
[2301]
[2302]
[2303]
[2304]
[2305]
[2306]
[2307]
[2308]
[2309]
[2310]
[2311]
[2312]
[2313]
[2314]
[2315]
[2316]
[2317]
[2318]
[2319]
[2320]
[2321]
[2322]
[2323]
[2324]
[2325]
[{"$f":"A2342+1","v":2326}]
[2327]
[2328]
[2329]
[2330]
[2331]
[2332]
[2333]
[2334]
[2335]
[2336]
[2337]
[2338]
[2339]
[2340]
[2341]
[2342]
[2343]
[2344]
[2345]
[2346]
[2347]
[2348]
[2349]
[2350]
[2351]
[2352]
[2353]
[2354]
[2355]
[2356]
[2357]
[2358]
[2359]
[2360]
[2361]
[2362]
[2363]
[2364]
[2365]
[2366]
[2367]
[2368]
[2369]
[2370]
[2371]
[2372]
[2373]
[2374]
[2375]
[2376]
[2377]
[2378]
[2379]
[2380]
[2381]
[2382]
[2383]
[2384]
[2385]
[2386]
[2387]
[2388]
[2389]
[{"$f":"A2406+1","v":2390}]
[2391]
[2392]
[2393]
[2394]
[2395]
[2396]
[2397]
[2398]
[2399]
[2400]
[2401]
[2402]
[2403]
[2404]
[2405]
[2406]
[2407]
[2408]
[2409]
[2410]
[2411]
[2412]
[2413]
[2414]
[2415]
[2416]
[2417]
[2418]
[2419]
[2420]
[2421]
[2422]
[2423]
[2424]
[2425]
[2426]
[2427]
[2428]
[2429]
[2430]
[2431]
[2432]
[2433]
[2434]
[2435]
[2436]
[2437]
[2438]
[2439]
[2440]
[2441]
[2442]
[2443]
[2444]
[2445]
[2446]
[2447]
[2448]
[2449]
[2450]
[2451]
[2452]
[2453]
[{"$f":"A2470+1","v":2454}]
[2455]
[2456]
[2457]
[2458]
[2459]
[2460]
[2461]
[2462]
[2463]
[2464]
[2465]
[2466]
[2467]
[2468]
[2469]
[2470]
[2471]
[2472]
[2473]
[2474]
[2475]
[2476]
[2477]
[2478]
[2479]
[2480]
[2481]
[2482]
[2483]
[2484]
[2485]
[2486]
[2487]
[2488]
[2489]
[2490]
[2491]
[2492]
[2493]
[2494]
[2495]
[2496]
[2497]
[2498]
[2499]
[2500]
[2501]
[2502]
[2503]
[null,{"$f":"COUNTA(B18:B2520)","v":3},null,null,{"$f":"SUM(IF(FREQUENCY(IF(LEN(E17:E2520)>0,MATCH(E17:E2520,E17:E2520,0),\"\"), IF(LEN(E17:E2520)>0,MATCH(E17:E2520,E17:E2520,0),\"\"))>0,1))","v":0},{"$f":"COUNTA(F18:F2520)","v":0},{"$f":"COUNTA(G18:G2520)","v":1},{"$f":"COUNTA(H18:H2520)","v":0},{"$f":"COUNTA(I18:I2520)","v":2},{"$f":"COUNTA(J18:J2520)","v":0},null,null,{"$f":"COUNTIF(M18:M2520,\"Eligible\")","v":3},{"$f":"COUNT(N18:N2520)","v":3}]
[null,"aada",null,null,null,null,null,"C-1",null,null,null,null,"Eligible",10]

{"sheet":"Tribe Part II ","index":8,"n_rows":62,"n_cols":14,"rows_kept":62,"cut":false,"hidden":false,"merged":[[61,0,66,13],[55,0,59,13],[0,0,0,13],[1,0,2,0],[3,12,3,13],[1,10,1,13],[2,10,2,13],[1,5,1,8],[2,5,2,8],[3,1,3,4],[2,1,2,4],[7,5,7,8],[4,12,4,13],[3,10,3,11],[4,10,4,11],[1,1,1,3],[8,0,10,0],[3,0,5,0],[8,3,10,3],[3,5,3,8],[4,5,4,8],[5,1,5,4],[5,5,5,8],[6,5,6,8],[8,4,9,8],[4,1,4,4],[7,1,7,2],[6,1,6,2],[8,1,9,2],[8,9,9,10],[5,12,5,13],[6,12,6,13],[8,11,9,13],[6,10,6,11],[5,10,5,11]]}
["PART II - REPORT OF ACCOMPLISHMENTS"]
[1,"a. Number of Applicants Provided Service:",null,null,null,{"$f":"IF(B54=0,\"\",B54)","v":""},null,null,null,null,"   Name of Tribe / Consortium"]
[null,"b. Number of Projects Completed within Fiscal Year:",null,null,null,{"$f":"IF(K54=0,\"\",K54)","v":""},null,null,null,null,{"$f":"IF(Profile!D6=0,\"\",Profile!D6)","v":"Quechen"}]
[2,"a. Amount of Total  Administration Funds to Report:",null,null,null,{"$f":"IF(L54=0,\"\",L54)","v":""},null,null,null,null," REGION",null,{"$f":"IF(Profile!D5=0,\"\",Profile!D5)","v":"WESTERN"}]
[null,"b. Amount of Total  Constuction Funds to Report:",null,null,null,{"$f":"IF(M54=0,\"\",M54)","v":""},null,null,null,null,"AGENCY",null,{"$f":"IF(Profile!D8=\"\",\"\",Profile!D8)","v":""}]
[null,"c. Amount of Total HIP Funds to Report:",null,null,null,{"$f":"IF(N54=0,\"\",N54)","v":""},null,null,null,null," FISCAL YEAR",null,{"$f":"IF(Profile!D9=0,\"\",Profile!D9)","v":2024}]
[null,"Type or Printed Name ",null,{"$f":"IF(Profile!D10=0,\"\",Profile!D10)","v":""},"Title",{"$f":"IF(Profile!D11=0,\"\",Profile!D11)","v":""}]
[null,"Telephone",null,{"$f":"IF(Profile!D12=0,\"\",Profile!D12)","v":""},"Fax",{"$f":"IF(Profile!D13=0,\"\",Profile!D13)","v":""}]
[3,"Name of Applicant Provided Program Services     ",null,"4. Applicant's Servicing Tribe","5. Program Category    (Enter one, as applicable)",null,null,null,null,"6.  Construction Schedules",null,"7. Construction Funds"]
[]
[null,"Last ","First",null,"(A)","(B)","(C-1)","(C-2)","(D)","a.Date of Construction Start","b.Date of Construction Completion","a. Admin cost","b. Project cost","c.Sum of 7(a) & 7(b)"]
[1,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(SUM(L12:M12)=0,\"\",SUM(L12:M12))","v":""}]
[{"$f":"A12+1","v":2},null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(SUM(L13:M13)=0,\"\",SUM(L13:M13))","v":""}]
[3,null,null,null," ",null,null,null,null," ",null,null,null,""]
[4,null,null,null," ",null,null,null,null,null,null,null,null,""]
[5,null,null,null,null,null,null,null,null,null,null,null,null,""]
[6,null,null,null,null,null,null,null,null," ",null,null,null,""]
[7,null,null,null,null,null,null,null,null,null,null,null,null,""]
[8,null,null,null,null,null,null,null,null,null,null,null,null,""]
[9,null,null,null,null,null,null,null,null,null,null,null,null,""]
[10,null,null,null,null,null,null,null,null,null,null,null,null,""]
[11,null,null,null,null,null,null,null,null,null,null,null,null,""]
[12,null,null,null,null,null,null,null,null,null,null,null,null,""]
[13,null,null,null,null,null,null,null,null,null,null,null,null,""]
[14,null,null,null,null,null,null,null,null,null,null,null,null,""]
[15,null,null,null,null,null,null,null,null,null,null,null,null,""]
[16,null,null,null,null,null,null,null,null,null,null,null,null,""]
[17,null,null,null,null,null,null,null,null,null,null,null,null,""]
[18,null,null,null,null,null,null,null,null,null,null,null,null,""]
[19,null,null,null,null,null,null,null,null,null,null,null,null,""]
[20,null,null,null,null,null,null,null,null,null,null,null,null,""]
[21]
[22]
[23]
[24]
[25]
[26]
[27]
[28]
[29]
[30]
[31]
[32]
[33]
[34]
[35]
[36]
[37]
[38]
[39,null,null,null,null,null,null,null,null,null,null,null,null,""]
[40,null,null,null,null,null,null,null,null,null,null,null,null,""]
[41,null,null,null,null,null,null,null,null,null,null,null,null,""]
[42,null,null,null,null,null,null,null,null,null,null,null,null,""]
[null,{"$f":"COUNTA(B12:B53)","v":0},null,null,{"$f":"SUM(E12:E53)","v":0},{"$f":"SUM(F12:F53)","v":0},{"$f":"SUM(G12:G53)","v":0},{"$f":"SUM(H12:H53)","v":0},null,null,{"$f":"COUNTA(K12:K53)","v":0},{"$f":"SUM(L12:L53)","v":0},{"$f":"SUM(M12:M53)","v":0},{"$f":"SUM(N12:N53)","v":0}]
[null,null,null,null,null,null,null,{"$f":"SUM(E54:H54)","v":0}]
["                                                                                                                                 PRIVACY ACT STATEMENT                                                                                                                                                                                                                                                                                                                                                                                                                 25 CFR 265 and 25 U.S.C. 13 authorize the collection of this information.  This information is covered by the system of record notice “Indian Housing Improvement Program, Interior, BIA-10.”  The primary use of this information is to determine eligibility for assistance under the Housing Improvement Program.  The records contained therein may only be disclosed in accordance with the routine uses and may not otherwise be disclosed by any means of communication to any person, or to another agency, except pursuant to a written request by, or with prior written consent of the individual to whom the record pertains.  If the BIA uses the information furnished on this form for purposes other than those indicated above, it may provide you with an additional statement reflecting those purposes.  Executive Order 9397 authorizes the collection of your Social Security number.  Furnishing the information is voluntary but failure to do so may result in disapproval of your application.   "]
[]
[]
[]
[]
[]
["                                                                                                                    PAPERWORK REDUCTION ACT STATEMENT                                                                                                                                                                                                                                                                                                                                                                       This information is being collected to select eligible families or individuals to participate in the Housing Improvement Program.  Response to this request is required to obtain a benefit in accordance with 25 CFR 256.  You are not required to respond to this collection of information unless it displays a currently valid OMB control number.  This information will be used to determine the eligibility and the ranking of the applicant.  Public reporting burden for this form is estimated to average 1 hour per response, including the time for reviewing instructions, gathering and maintaining data, and completing and reviewing the form.  Direct comments regarding the burden estimate or any other aspect of this form to Information Collection Clearance Officer – Indian Affairs, 1849 C Street, NW, MS-4141, Washington, DC 20240. "]

{"sheet":"150 Per Cent","index":9,"n_rows":43,"n_cols":21,"rows_kept":43,"cut":false,"hidden":false,"merged":[[0,0,0,21],[1,0,1,21],[2,1,2,3],[2,4,2,6],[2,7,2,9],[2,10,2,12],[2,13,2,15],[2,16,2,18],[2,19,2,21],[15,20,15,21],[4,20,4,21],[5,20,5,21],[6,20,6,21],[7,20,7,21],[8,20,8,21],[9,20,9,21],[10,20,10,21],[11,20,11,21],[14,20,14,21],[12,20,12,21],[13,20,13,21],[23,0,23,21],[24,0,24,21],[25,1,25,3],[25,4,25,6],[25,7,25,9],[25,10,25,12],[25,13,25,15],[25,16,25,18],[25,19,25,21],[16,20,16,21],[18,1,18,2],[18,4,18,5],[18,7,18,8],[18,10,18,11],[18,13,18,14],[18,16,18,17],[38,20,38,21],[27,20,27,21],[28,20,28,21],[29,20,29,21],[30,20,30,21],[31,20,31,21],[32,20,32,21],[33,20,33,21],[34,20,34,21],[35,20,35,21],[36,20,36,21],[37,20,37,21],[39,20,39,21],[41,1,41,2],[41,4,41,5],[41,7,41,8],[41,10,41,11],[41,13,41,14],[41,16,41,17]]}
["FACTOR NO. 1 - HIP ELIGIBILITY/SELECTION CRITERIA @ 150%"]
["INCOME GUIDELINE POINT SCHEDULE FOR ALL STATES EXCEPT ALASKA & HAWAII"]
["FAMILY SIZE","0% to 25% of PG\n25 POINTS",null,null,"26% to 50% of PG\n20 POINTS",null,null,"51% to 75% of PG\n15 POINTS",null,null,"76% to 100 of PG\n10 POINTS",null,null,"101% to 125% of PG \n5 POINTS",null,null,"125% to 150% of PG\n0 POINTS",null,null,"OVER 150% of FPIG\nINELIGIBLE"]
[]
[1,0,"TO",3397.5,{"$f":"D5+1","v":3398.5},"TO",{"$f":"G18","v":7290},{"$f":"G5+1","v":7291},"TO",{"$f":"J18","v":10935},{"$f":"J5+1","v":10936},"TO",{"$f":"M18","v":14580},{"$f":"M5+1","v":14581},"TO",{"$f":"P18","v":18225},{"$f":"P5+1","v":18226},"TO",{"$f":"S18","v":21870},{"$f":"S5+1","v":21871},"& HIGHER"]
[2,0,"TO",4532.5,4533.5,"TO",{"$f":"G5+G$17","v":9860},9861,"TO",{"$f":"J5+J$17","v":14790},14791,"TO",{"$f":"M5+M$17","v":19720},19721,"TO",{"$f":"P5+P$17","v":24650},24651,"TO",{"$f":"S5+S$17","v":29580},29581,"& HIGHER"]
[3,0,"TO",{"$f":"D6+D$17","v":5817.5},5818.5,"TO",{"$f":"G6+G$17","v":12430},12431,"TO",18645,18646,"TO",{"$f":"M6+M$17","v":24860},24861,"TO",31075,31076,"TO",37290,37291,"& HIGHER"]
[4,0,"TO",7102.5,7103.5,"TO",15000,15001,"TO",22500,22501,"TO",{"$f":"M7+M$17","v":30000},30001,"TO",37500,37501,"TO",45000,45001,"& HIGHER"]
[5,0,"TO",8387.5,8388.5,"TO",17570,17571,"TO",26355,26356,"TO",{"$f":"M8+M$17","v":35140},35141,"TO",43925,43926,"TO",52710,52711,"& HIGHER"]
[6,0,"TO",9672.5,9673.5,"TO",20140,20141,"TO",30210,30211,"TO",{"$f":"M9+M17","v":40280},40281,"TO",50350,50351,"TO",60420,60421,"& HIGHER"]
[7,0,"TO",10957.5,10958.5,"TO",22710,22711,"TO",34065,34066,"TO",{"$f":"M10+M$17","v":45420},45421,"TO",56775,56776,"TO",68130,68131,"& HIGHER"]
[8,0,"TO",12242.5,12243.5,"TO",25280,25281,"TO",37920,37921,"TO",{"$f":"M11+M$17","v":50560},50561,"TO",63200,63201,"TO",75840,75841,"& HIGHER"]
[9,0,"TO",13527.5,13528.5,"TO",27850,27851,"TO",41775,41776,"TO",{"$f":"M12+M$17","v":55700},55701,"TO",69625,69626,"TO",83550,83551,"& HIGHER"]
[10,0,"TO",14812.5,14813.5,"TO",30420,30421,"TO",45630,45631,"TO",{"$f":"M13+M$17","v":60840},60841,"TO",76050,76051,"TO",91260,91261,"& HIGHER"]
[11,0,"TO",16097.5,16098.5,"TO",32990,32991,"TO",49485,49486,"TO",{"$f":"M14+M$17","v":65980},65981,"TO",82475,82476,"TO",98970,98971,"& HIGHER"]
[12,0,"TO",17382.5,17383.5,"TO",35560,{"$f":"G16+1","v":35561},"TO",53340,53341,"TO",{"$f":"M15+M17","v":71120},71121,"TO",88900,88901,"TO",106680,106681,"& HIGHER"]
["EACH PERSON OVER 12 ADD",null,null,{"$f":"$M19*0.25","v":1285},null,null,{"$f":"$M$19*0.5","v":2570},null,null,{"$f":"$M$19*0.75","v":3855},null,null,{"$f":"$M$19*1","v":5140},null,null,{"$f":"$M$19*1.25","v":6425},null,null,{"$f":"$M$19*1.5","v":7710},{"$f":"S17+1","v":7711},"& HIGHER"]
[null,"25%=",null,{"$f":"$M$18*0.25","v":3645},"50%=",null,{"$f":"$M$18*0.5","v":7290},"'75%=",null,{"$f":"$M$18*0.75","v":10935},"100%=",null,14580,"125%=",null,{"$f":"$M$18*1.25","v":18225},"150% =",null,{"$f":"$M18*1.5","v":21870},null,{"$f":"R18*1.25","v":0}]
[null,"@ Add'l:",null,{"$f":"J19*0.25","v":963.75},"@ Add'l:",null,{"$f":"M19*0.5","v":2570},"@ Add'l:",null,{"$f":"M19*0.75","v":3855},"@ Add'l:",null,5140,"@ Add'l:",null,{"$f":"$M19*1.25","v":6425},"@ Add'l:",null,{"$f":"M19*1.5","v":7710},null,{"$f":"R19*1.25","v":0}]
["PG =","HHS Poverty Guidelines"]
[]
[]
[]
["FACTOR NO. 1 - HIP ELIGIBILITY/SELECTION CRITERIA @ 150%"]
["INCOME GUIDELINE POINT SCHEDULE FOR ALASKA"]
["FAMILY SIZE","0% to 25% of PG\n25 POINTS",null,null,"26% to 50% of PG\n20 POINTS",null,null,"51% to 75% of PG\n15 POINTS",null,null,"76% to 100 of PG\n10 POINTS",null,null,"101% to 125% of PG\n5 POINTS",null,null,"126% to 150% of PG\n0 POINTS",null,null,"OVER 150% of FPIG\nINELIGIBLE"]
[]
[1,0,"TO",{"$f":"D41","v":4552.5},{"$f":"D28+1","v":4553.5},"TO",{"$f":"G41","v":9105},{"$f":"G28+1","v":9106},"TO",{"$f":"J41","v":13657.5},{"$f":"J28+1","v":13658.5},"TO",{"$f":"M41","v":18210},{"$f":"M28+1","v":18211},"TO",{"$f":"P41","v":22762.5},{"$f":"P28+1","v":22763.5},"TO",{"$f":"S41","v":27315},{"$f":"S28+1","v":27316},"& HIGHER"]
[2,0,"TO",{"$f":"D28+D$40","v":6160},6161,"TO",{"$f":"G28+G$40","v":12320},12321,"TO",{"$f":"J28+J$40","v":18480},18481,"TO",{"$f":"M28+M$40","v":24640},24641,"TO",{"$f":"P28+P$40","v":30800},30801,"TO",{"$f":"S28+S$40","v":36960},36961,"& HIGHER"]
[3,0,"TO",7767.5,7768.5,"TO",15535,15536,"TO",23302.5,23303.5,"TO",31070,31071,"TO",38837.5,38838.5,"TO",46605,46606,"& HIGHER"]
[4,0,"TO",9375,9376,"TO",18750,18751,"TO",28125,28126,"TO",37500,37501,"TO",46875,46876,"TO",56250,56251,"& HIGHER"]
[5,0,"TO",10982.5,10983.5,"TO",21965,21966,"TO",32947.5,32948.5,"TO",43930,43931,"TO",54912.5,54913.5,"TO",65895,65896,"& HIGHER"]
[6,0,"TO",12590,12591,"TO",25180,25181,"TO",37770,37771,"TO",50360,50361,"TO",62950,62951,"TO",75540,75541,"& HIGHER"]
[7,0,"TO",14197.5,14198.5,"TO",28395,28396,"TO",42592.5,42593.5,"TO",56790,56791,"TO",70987.5,70988.5,"TO",85185,85186,"& HIGHER"]
[8,0,"TO",15805,15806,"TO",31610,31611,"TO",47415,47416,"TO",63220,63221,"TO",79025,79026,"TO",94830,94831,"& HIGHER"]
[9,0,"TO",17412.5,17413.5,"TO",34825,34826,"TO",52237.5,52238.5,"TO",69650,69651,"TO",87062.5,87063.5,"TO",104475,104476,"& HIGHER"]
[10,0,"TO",19020,19021,"TO",38040,38041,"TO",57060,57061,"TO",76080,76081,"TO",95100,95101,"TO",114120,114121,"& HIGHER"]
[11,0,"TO",20627.5,20628.5,"TO",41255,41256,"TO",61882.5,61883.5,"TO",82510,82511,"TO",103137.5,103138.5,"TO",123765,123766,"& HIGHER"]
[12,0,"TO",22235,22236,"TO",44470,44471,"TO",66705,66706,"TO",88940,88941,"TO",111175,111176,"TO",133410,133411,"& HIGHER"]
["EACH PERSON OVER 12 ADD",null,null,{"$f":"D42","v":1607.5},null,null,{"$f":"G42","v":3215},null,null,{"$f":"J42","v":4822.5},null,null,{"$f":"M42","v":6430},null,null,{"$f":"P42","v":8037.5},null,null,{"$f":"S42","v":9645},9646,"& HIGHER"]
[null,"25%=",null,{"$f":"$M$41*0.25","v":4552.5},"50%=",null,{"$f":"$M$41*0.5","v":9105},"'75%=",null,{"$f":"$M$41*0.75","v":13657.5},"100%=",null,18210,"125%=",null,{"$f":"$M$41*1.25","v":22762.5},"150% =",null,{"$f":"$M41*1.5","v":27315},null,{"$f":"R41*1.25","v":0}]
[null,"@ Add'l:",null,{"$f":"M42*0.25","v":1607.5},"@ Add'l:",null,{"$f":"M42*0.5","v":3215},"@ Add'l:",null,{"$f":"M42*0.75","v":4822.5},"@ Add'l:",null,6430,"@ Add'l:",null,{"$f":"$M42*1.25","v":8037.5},"@ Add'l:",null,{"$f":"M42*1.5","v":9645},null,{"$f":"R42*1.25","v":0}]
["PG =","HHS Poverty Guidelines"]

{"sheet":"FPIG13","index":10,"n_rows":42,"n_cols":18,"rows_kept":42,"cut":false,"hidden":true,"merged":[[30,17,30,18],[31,17,31,18],[36,17,36,18],[32,17,32,18],[33,17,33,18],[34,17,34,18],[35,17,35,18],[22,13,22,15],[22,16,22,18],[28,17,28,18],[29,17,29,18],[25,17,25,18],[27,17,27,18],[26,17,26,18],[24,17,24,18],[22,1,22,3],[22,4,22,6],[22,7,22,9],[22,10,22,12],[8,17,8,18],[9,17,9,18],[10,17,10,18],[11,17,11,18],[12,17,12,18],[13,17,13,18],[20,0,20,18],[21,0,21,18],[18,13,18,14],[18,1,18,2],[15,17,15,18],[18,10,18,11],[4,17,4,18],[5,17,5,18],[6,17,6,18],[7,17,7,18],[16,13,16,15],[14,17,14,18],[16,17,16,18],[0,0,0,18],[1,0,1,18],[2,1,2,3],[2,4,2,6],[2,7,2,9],[2,10,2,12],[2,16,2,18],[2,13,2,15],[16,1,16,3],[16,4,16,6],[16,7,16,9],[16,10,16,12],[18,7,18,8],[18,4,18,5],[38,13,38,14],[38,1,38,2],[38,4,38,5],[38,7,38,8],[38,10,38,11]]}
["FACTOR NO. 1 - HIP ELIGIBILITY/SELECTION CRITERIA @ 150%"]
["INCOME GUIDELINE POINT SCHEDULE FOR ALASKA "]
["FAMILY SIZE","0% to 25% of PG\n40 POINTS",null,null,"26% to 50% of PG\n30 POINTS",null,null,"51% to 75% of PG\n20 POINTS",null,null,"76% to 100% of PG\n10 POINTS",null,null,"101% to 125% of PG\n0 POINTS",null,null,"OVER 125% of FPIG\nINELIGIBLE"]
[]
[1,0,"TO",{"$f":"$D$18","v":3587.5},{"$f":"D5+1","v":3588.5},"TO",{"$f":"G18","v":6985},{"$f":"G5+1","v":6986},"TO",{"$f":"J18","v":10478},{"$f":"J5+1","v":10479},"TO",{"$f":"M18","v":14350},{"$f":"M5+1","v":14351},"TO",{"$f":"P18","v":17463},{"$f":"P5+1","v":17464},"& HIGHER"]
[2,0,"TO",{"$f":"D5+B$17","v":4845},4846,"TO",{"$f":"G5+E$17","v":9500},9501,"TO",14191,14192,"TO",{"$f":"M5+K$17","v":19380},19381,"TO",23651,23652,"& HIGHER"]
[3,0,"TO",{"$f":"D6+B$17","v":6102.5},6103.5,"TO",12015,12016,"TO",{"$f":"J6+H$17","v":17963.5},17964.5,"TO",24410,24411,"TO",29839,{"$f":"P7+1","v":29840},"& HIGHER"]
[4,0,"TO",{"$f":"D7+B$17","v":7360},7361,"TO",14530,14531,"TO",21617,21618,"TO",29440,29441,"TO",{"$f":"P7+N$17","v":36126.5},{"$f":"P8+1","v":36127.5},"& HIGHER"]
[5,0,"TO",8617.5,8618.5,"TO",17045,17046,"TO",25389.5,25390.5,"TO",34470,34471,"TO",42215,42216,"& HIGHER"]
[6,0,"TO",{"$f":"D9+B$17","v":9875},9876,"TO",19560,19561,"TO",29043,29044,"TO",39500,39501,"TO",48403,48404,"& HIGHER"]
[7,0,"TO",11132.5,11133.5,"TO",22075,22076,"TO",32815.5,32816.5,"TO",44530,44531,"TO",54591,54592,"& HIGHER"]
[8,0,"TO",{"$f":"D11+B$17","v":12390},12391,"TO",24590,24591,"TO",36469,36470,"TO",49560,49561,"TO",60779,60780,"& HIGHER"]
[9,0,"TO",13647.5,13648.5,"TO",27105,27106,"TO",40241.5,40242.5,"TO",54590,54591,"TO",66967,66968,"& HIGHER"]
[10,0,"TO",{"$f":"D13+B$17","v":14905},14906,"TO",29620,29621,"TO",43895,43896,"TO",59620,59621,"TO",73155,73156,"& HIGHER"]
[11,0,"TO",16162.5,16163.5,"TO",32135,32136,"TO",47667.5,47668.5,"TO",64650,64651,"TO",{"$f":"P14+N$17","v":79442.5},79443.5,"& HIGHER"]
[12,0,"TO",{"$f":"D15+B$17","v":17420},13251,"TO",34650,34651,"TO",51321,51322,"TO",69680,69681,"TO",85531,85532,"& HIGHER"]
["EACH PERSON OVER 12 ADD",{"$f":"D19","v":1257.5},null,null,{"$f":"G19","v":2515},null,null,{"$f":"J19","v":3772.5},null,null,{"$f":"M19","v":5030},null,null,{"$f":"P19","v":6287.5},null,null,{"$f":"N17+1","v":6288.5},"& HIGHER"]
["2013 PG:","25%=",null,{"$f":"$M$18*0.25","v":3587.5},"50%=",null,6985,"75%=",null,10478,"100%=",null,14350,"125% =",null,17463]
[null,"@ Add'l:",null,{"$f":"M19*0.25","v":1257.5},"@ Add'l:",null,{"$f":"M19*0.5","v":2515},"@ Add'l:",null,{"$f":"M19*0.75","v":3772.5},"@ Add'l:",null,5030,null,null,{"$f":"M19*1.25","v":6287.5}]
["PG =","HHS Poverty Guidelines"]
["FACTOR NO. 1 - HIP ELIGIBILITY/SELECTION CRITERIA @ 150%"]
["INCOME GUIDELINE POINT SCHEDULE FOR ALL STATES EXCEPT ALASKA "]
["FAMILY SIZE","0% to 25% of FPIG\n40 POINTS",null,null,"26% to 50% of FPIG\n30 POINTS",null,null,"51% to 75% of FPIG\n20 POINTS",null,null,"76% to 100% of FPIG\n10 POINTS",null,null,"101% to 125% of FPIG\n0 POINTS",null,null,"OVER 125% of FPIG\nINELIGIBLE"]
[]
[1,0,"TO",{"$f":"D38","v":2793},{"$f":"D25+1","v":2794},"TO",{"$f":"G38","v":5585},{"$f":"G25+1","v":5586},"TO",{"$f":"J38","v":8378},{"$f":"J25+1","v":8379},"TO",{"$f":"M38","v":11490},{"$f":"M25+1","v":11491},"TO",{"$f":"P38","v":13963},{"$f":"P25+1","v":13964},"& HIGHER"]
[2,0,"TO",{"$f":"D25+D$37","v":3798},3799,"TO",{"$f":"G25+G$37","v":7595},7596,"TO",{"$f":"J25+J$37","v":11393},11394,"TO",{"$f":"M25+M$37","v":15510},15511,"TO",{"$f":"P25+P$37","v":18988},18989,"& HIGHER"]
[3,0,"TO",4803,4804,"TO",9605,9606,"TO",14408,14409,"TO",19530,19531,"TO",24013,24014,"& HIGHER"]
[4,0,"TO",5808,5809,"TO",11615,11616,"TO",17423,17424,"TO",23550,23551,"TO",29038,29039,"& HIGHER"]
[5,0,"TO",6813,6814,"TO",13625,13626,"TO",20438,20439,"TO",27570,27571,"TO",34063,34064,"& HIGHER"]
[6,0,"TO",7818,7819,"TO",15635,15636,"TO",23453,23454,"TO",31590,31591,"TO",39088,39089,"& HIGHER"]
[7,0,"TO",8823,8824,"TO",17645,17646,"TO",26468,26469,"TO",35610,35611,"TO",44113,44114,"& HIGHER"]
[8,0,"TO",9828,9829,"TO",19655,19656,"TO",29483,29484,"TO",39630,39631,"TO",49138,49139,"& HIGHER"]
[9,0,"TO",10833,10834,"TO",21665,21666,"TO",32498,32499,"TO",43650,43651,"TO",54163,54164,"& HIGHER"]
[10,0,"TO",11838,11839,"TO",23675,23676,"TO",35513,35514,"TO",47670,47671,"TO",59188,59189,"& HIGHER"]
[11,0,"TO",12843,12844,"TO",25685,25686,"TO",38528,38529,"TO",51690,51691,"TO",64213,64214,"& HIGHER"]
[12,0,"TO",13848,13849,"TO",27695,27696,"TO",41543,41544,"TO",55710,55711,"TO",69238,69239,"& HIGHER"]
["EACH PERSON OVER 12 ADD",null,null,{"$f":"D39","v":1005},null,null,{"$f":"G39","v":2010},null,null,{"$f":"J39","v":3015},null,null,{"$f":"M39","v":4020},null,null,{"$f":"P39","v":5025},5026,"& HIGHER"]
["2013 PG:","@ 25% =",null,2793,"@ 50% =",null,5585,"@ 75% =",null,8378,"@ 100% =",null,11490,"@ 125% =",null,13963]
[null,"@ Add'l:",null,{"$f":"M39*0.25","v":1005},"@ Add'l:",null,{"$f":"M39*0.5","v":2010},"@ Add'l:",null,{"$f":"M39*0.75","v":3015},"@ Add'l:",null,4020,"@ Add'l:",null,{"$f":"M39*1.25","v":5025}]
["PG =","HHS Poverty Guidelines"]
[]
["To view the  2013 Department of Health and Human Services Poverty Income Guideline, go to: ",null,null,null,null,null,null,null,null,null,null,null,"http://aspe.hhs.gov/poverty/13poverty.cfm"]

{"sheet":"FPIG 125%","index":11,"n_rows":40,"n_cols":18,"rows_kept":40,"cut":false,"hidden":true,"merged":[[0,0,0,18],[1,0,1,18],[2,1,2,3],[2,4,2,6],[2,7,2,9],[2,10,2,12],[2,13,2,15],[2,16,2,18],[15,17,15,18],[4,17,4,18],[5,17,5,18],[6,17,6,18],[7,17,7,18],[8,17,8,18],[11,17,11,18],[12,17,12,18],[13,17,13,18],[14,17,14,18],[9,17,9,18],[10,17,10,18],[20,0,20,18],[16,1,16,3],[16,4,16,6],[16,7,16,9],[16,10,16,12],[16,13,16,15],[16,17,16,18],[18,1,18,2],[18,4,18,5],[18,7,18,8],[18,10,18,11],[18,13,18,14],[21,0,21,18],[22,1,22,3],[22,4,22,6],[22,7,22,9],[22,10,22,12],[22,13,22,15],[22,16,22,18],[35,17,35,18],[24,17,24,18],[25,17,25,18],[26,17,26,18],[27,17,27,18],[28,17,28,18],[29,17,29,18],[30,17,30,18],[31,17,31,18],[32,17,32,18],[33,17,33,18],[34,17,34,18],[36,17,36,18],[38,1,38,2],[38,4,38,5],[38,7,38,8],[38,10,38,11],[38,13,38,14]]}
["FACTOR NO. 1 - HIP ELIGIBILITY/SELECTION CRITERIA @ 125%"]
["INCOME GUIDELINE POINT SCHEDULE FOR ALL STATES EXCEPT ALASKA "]
["FAMILY SIZE","0% to 25% of PG\n40 POINTS",null,null,"26% to 50% of PG\n30 POINTS",null,null,"51% to 75% of PG\n20 POINTS",null,null,"76% to 100% of PG\n10 POINTS",null,null,"101% to 125% of PG\n0 POINTS",null,null,"OVER 125% of FPIG\nINELIGIBLE"]
[]
[1,0,"TO",{"$f":"D18","v":2872.5},{"$f":"D5+1","v":2873.5},"TO",{"$f":"G18","v":5745},{"$f":"G5+1","v":5746},"TO",{"$f":"J18","v":8617.5},{"$f":"J5+1","v":8618.5},"TO",{"$f":"M18","v":11490},{"$f":"M5+1","v":11491},"TO",{"$f":"P18","v":14362.5},{"$f":"P5+1","v":14363.5},"& HIGHER"]
[2,0,"TO",{"$f":"D5+B$17","v":3877.5},3878.5,"TO",{"$f":"G5+E$17","v":7755},7756,"TO",{"$f":"J5+H$17","v":11632.5},11633.5,"TO",{"$f":"M5+K$17","v":15510},15511,"TO",{"$f":"P5+N$17","v":19387.5},19388.5,"& HIGHER"]
[3,0,"TO",4882.5,4883.5,"TO",9765,9766,"TO",14647.5,14648.5,"TO",19530,19531,"TO",24412.5,24413.5,"& HIGHER"]
[4,0,"TO",5887.5,5888.5,"TO",11775,11776,"TO",17662.5,17663.5,"TO",23550,23551,"TO",29437.5,29438.5,"& HIGHER"]
[5,0,"TO",6892.5,6893.5,"TO",13785,13786,"TO",20677.5,20678.5,"TO",27570,27571,"TO",34462.5,34463.5,"& HIGHER"]
[6,0,"TO",7897.5,7898.5,"TO",15795,15796,"TO",23692.5,23693.5,"TO",31590,31591,"TO",39487.5,39488.5,"& HIGHER"]
[7,0,"TO",8902.5,8903.5,"TO",17805,17806,"TO",26707.5,26708.5,"TO",35610,35611,"TO",44512.5,44513.5,"& HIGHER"]
[8,0,"TO",9907.5,9908.5,"TO",19815,19816,"TO",29722.5,29723.5,"TO",39630,39631,"TO",49537.5,49538.5,"& HIGHER"]
[9,0,"TO",10912.5,10913.5,"TO",21825,21826,"TO",32737.5,32738.5,"TO",43650,43651,"TO",54562.5,54563.5,"& HIGHER"]
[10,0,"TO",11917.5,11918.5,"TO",23835,23836,"TO",35752.5,35753.5,"TO",47670,47671,"TO",59587.5,59588.5,"& HIGHER"]
[11,0,"TO",12922.5,12923.5,"TO",25845,25846,"TO",38767.5,38768.5,"TO",51690,51691,"TO",64612.5,64613.5,"& HIGHER"]
[12,0,"TO",13927.5,13928.5,"TO",27855,27856,"TO",41782.5,41783.5,"TO",55710,55711,"TO",69637.5,69638.5,"& HIGHER"]
["EACH PERSON OVER 12 ADD",{"$f":"D19","v":1005},null,null,{"$f":"G19","v":2010},null,null,{"$f":"J19","v":3015},null,null,{"$f":"$M$19","v":4020},null,null,{"$f":"P19","v":5025},null,null,{"$f":"N17+1","v":5026},"& HIGHER"]
["2012 PG:","25%=",null,{"$f":"$M$18*0.25","v":2872.5},"50%=",null,{"$f":"$M$18*0.5","v":5745},"75%=",null,{"$f":"$M$18*0.75","v":8617.5},"100%=",null,11490,"125% =",null,{"$f":"M18*1.25","v":14362.5}]
[null,"@ Add'l:",null,{"$f":"M19*0.25","v":1005},"@ Add'l:",null,{"$f":"M19*0.5","v":2010},"@ Add'l:",null,{"$f":"M19*0.75","v":3015},"@ Add'l:",null,4020,"@ Add'l:",null,{"$f":"M19*1.25","v":5025}]
["PG =","HHS Poverty Guidelines"]
["FACTOR NO. 1 - HIP ELIGIBILITY/SELECTION CRITERIA @ 125%"]
["INCOME GUIDELINE POINT SCHEDULE FOR ALASKA"]
["FAMILY SIZE","0% to 25% of FPIG\n40 POINTS",null,null,"26% to 50% of FPIG\n30 POINTS",null,null,"51% to 75% of FPIG\n20 POINTS",null,null,"76% to 100% of FPIG\n10 POINTS",null,null,"101% to 125% of FPIG\n0 POINTS",null,null,"OVER 125% of FPIG\nINELIGIBLE"]
[]
[1,0,"TO",{"$f":"D38","v":3587.5},{"$f":"D25+1","v":3588.5},"TO",{"$f":"G38","v":7175},{"$f":"G25+1","v":7176},"TO",{"$f":"J38","v":10762.5},{"$f":"J25+1","v":10763.5},"TO",{"$f":"M38","v":14350},{"$f":"M25+1","v":14351},"TO",{"$f":"P38","v":17937.5},{"$f":"P25+1","v":17938.5},"& HIGHER"]
[2,0,"TO",{"$f":"D25+D$37","v":4845},4846,"TO",{"$f":"G25+G$37","v":9690},9691,"TO",{"$f":"J25+J$37","v":14535},14536,"TO",{"$f":"M25+M$37","v":19380},19381,"TO",{"$f":"P25+P$37","v":24225},24226,"& HIGHER"]
[3,0,"TO",6102.5,6103.5,"TO",12205,12206,"TO",18307.5,18308.5,"TO",24410,24411,"TO",30512.5,30513.5,"& HIGHER"]
[4,0,"TO",7360,7361,"TO",14720,14721,"TO",22080,22081,"TO",29440,29441,"TO",36800,36801,"& HIGHER"]
[5,0,"TO",8617.5,8618.5,"TO",17235,17236,"TO",25852.5,25853.5,"TO",34470,34471,"TO",43087.5,43088.5,"& HIGHER"]
[6,0,"TO",9875,9876,"TO",19750,19751,"TO",29625,29626,"TO",39500,39501,"TO",49375,49376,"& HIGHER"]
[7,0,"TO",11132.5,11133.5,"TO",22265,22266,"TO",33397.5,33398.5,"TO",44530,44531,"TO",55662.5,55663.5,"& HIGHER"]
[8,0,"TO",12390,12391,"TO",24780,24781,"TO",37170,37171,"TO",49560,49561,"TO",61950,61951,"& HIGHER"]
[9,0,"TO",13647.5,13648.5,"TO",27295,27296,"TO",40942.5,40943.5,"TO",54590,54591,"TO",68237.5,68238.5,"& HIGHER"]
[10,0,"TO",14905,14906,"TO",29810,29811,"TO",44715,44716,"TO",59620,59621,"TO",74525,74526,"& HIGHER"]
[11,0,"TO",16162.5,16163.5,"TO",32325,32326,"TO",48487.5,48488.5,"TO",64650,64651,"TO",80812.5,80813.5,"& HIGHER"]
[12,0,"TO",17420,17421,"TO",34840,34841,"TO",52260,52261,"TO",69680,69681,"TO",87100,87101,"& HIGHER"]
["EACH PERSON OVER 12 ADD",null,null,{"$f":"D39","v":1257.5},null,null,{"$f":"G39","v":2515},null,null,{"$f":"J39","v":3772.5},null,null,{"$f":"M39","v":5030},null,null,{"$f":"P39","v":6287.5},6288.5,"& HIGHER"]
["2014 PG:","@ 25% =",null,{"$f":"$M$38*0.25","v":3587.5},"@ 50% =",null,{"$f":"$M$38*0.5","v":7175},"@ 75% =",null,{"$f":"$M$38*0.75","v":10762.5},"@ 100% =",null,14350,"@ 125% =",null,{"$f":"M38*1.25","v":17937.5}]
[null,"@ Add'l:",null,{"$f":"M39*0.25","v":1257.5},"@ Add'l:",null,{"$f":"M39*0.5","v":2515},"@ Add'l:",null,{"$f":"M39*0.75","v":3772.5},"@ Add'l:",null,5030,"@ Add'l:",null,{"$f":"M39*1.25","v":6287.5}]
["PG =","HHS Poverty Guidelines"]

{"sheet":"Sheet1","index":12,"n_rows":7,"n_cols":4,"rows_kept":7,"cut":false,"hidden":true,"merged":[]}
[]
[]
[null," formula shows total if all three cell are populated or than zero, other wise blank or zero"]
[]
[null,{"$f":"IF(OR(ISBLANK(B7),ISBLANK(C7),ISBLANK(D7)), \"no data\", IF(OR(B7=0, C7=0, D7=0),\"ZERO\", B7+C7+D7))","v":7}]
[]
[null,1,2,4]

{"sheet":"HIP Home ","index":13,"n_rows":0,"n_cols":0,"rows_kept":0,"cut":false,"hidden":false,"merged":[]}